{"id":115212,"date":"2019-09-02T05:13:26","date_gmt":"2019-09-02T03:13:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/grave-incidente-nella-notte-sulla-statale-18-tre-feriti-gravi\/"},"modified":"2023-01-16T18:33:29","modified_gmt":"2023-01-16T17:33:29","slug":"310219-grave-incidente-nella-notte-sulla-statale-18-tre-feriti-gravi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/310219-grave-incidente-nella-notte-sulla-statale-18-tre-feriti-gravi\/","title":{"rendered":"Grave incidente nella notte sulla Statale 18, tre feriti gravi"},"content":{"rendered":"<h4>Un terribile incidente stradale si \u00e8 verificato nella notte ed ha coinvolto tre auto. Tra le persone ferite anche una donna incinta<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>NOCERA TERINESE (CZ) &#8211; L&#8217;impatto si \u00e8 verificato nella notte nei pressi del Villaggio del Golfo sulla Statale 18 a Nocera Terinese ed ha provocato il ferimento grave di tre persone. Tre le auto che si sono scontrate: una Smart, una Panda ed una Ford Focus. Altre due persone sono rimaste ferite in modo lieve tra cui una ragazza in gravidanza. Sul posto carabinieri, vigili del fuoco e sanitari del 118.<\/p>\n<p>Le persone rimaste ferite in modo grave sarebbero il conducente della Smart ed una coppia a bordo della Panda il cui conducente \u00e8 rimasto incastrato tra le lamiere, ed \u00e8 stato estratto dal personale dei vigili fuoco. L&#8217;incidente ha provocato disagi e rallentamenti sulla Statale che \u00e8 stata chiusa al transito in ambedue sensi di marcia sino al termine delle operazioni di soccorso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un terribile incidente stradale si \u00e8 verificato nella notte ed ha coinvolto tre auto. Tra le persone ferite anche una donna incinta<\/p>\n","protected":false},"author":42,"featured_media":115213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-115212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115212"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115213"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}