{"id":115259,"date":"2019-09-02T16:40:23","date_gmt":"2019-09-02T14:40:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/allontanato-dalla-processione-membro-di-una-famiglia-di-ndrangheta\/"},"modified":"2023-01-16T18:33:32","modified_gmt":"2023-01-16T17:33:32","slug":"310336-allontanato-dalla-processione-membro-di-una-famiglia-di-ndrangheta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/310336-allontanato-dalla-processione-membro-di-una-famiglia-di-ndrangheta\/","title":{"rendered":"Allontanato dalla processione membro di una famiglia di &#8216;ndrangheta"},"content":{"rendered":"<h4>L&#8217;uomo voleva portare in spalla la Madonna<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>SAN LUCA (RC) &#8211; Approfittando della confusione dovuta al gran numero di fedeli accorsi questa mattina al Santuario della Madonna di Polsi, un soggetto, appartenente per vincoli di sangue ad una nota famiglia di &#8216;Ndrangheta di Bagnara Calabra, <strong>ha tentato di intrufolarsi tra i portatori della statua della Madonna<\/strong>, violando le prescrizioni degli organizzatori e della diocesi finalizzate ad evitare indebite intromissioni nel regolare e genuino svolgimento delle funzioni religiose. L\u2019uomo, una volta identificato dai carabinieri impiegati nell\u2019ambito dei servizi di ordine pubblico presenti per i festeggiamenti, \u00e8 stato accompagnato presso il presidio dell\u2019Arma di Polsi per un controllo di rito e successivi adempimenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo voleva portare in spalla la Madonna<\/p>\n","protected":false},"author":43,"featured_media":115260,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-115259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115259"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115260"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}