{"id":115265,"date":"2019-09-03T04:53:18","date_gmt":"2019-09-03T02:53:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/comune-di-cassano-jonio-sciolto-per-mafia-si-vota-il-10-novembre\/"},"modified":"2023-01-16T18:33:32","modified_gmt":"2023-01-16T17:33:32","slug":"310344-comune-di-cassano-jonio-sciolto-per-mafia-si-vota-il-10-novembre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/310344-comune-di-cassano-jonio-sciolto-per-mafia-si-vota-il-10-novembre\/","title":{"rendered":"Comune di Cassano Jonio sciolto per mafia, si vota il 10 novembre"},"content":{"rendered":"<h4>Dopo due anni di gestione commissariale il prefetto convoca i comizi e fissa le elezioni per il rinnovo del Consiglio comunale<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASSANO ALLO JONIO (CS) &#8211; Sono state fissate per il<strong> 10 novembre prossimo<\/strong> le elezioni per il rinnovo del Consiglio comunale di Cassano allo Jonio, sciolto nel 2017 per presunti condizionamenti della criminalit\u00e0 organizzata. In caso di <strong>ballottaggio<\/strong>, gli elettori si recheranno nuovamente alle urne <strong>il 24 novembre.<\/strong><\/p>\n<p>A fissare la data delle elezioni amministrative \u00e9 stato, con uno specifico decreto, il prefetto di Cosenza, Paola Galeone. Le candidature a sindaco e le liste dei consiglieri a loro collegate dovranno essere presentate entro le ore 12 del 12 ottobre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo due anni di gestione commissariale il prefetto convoca i comizi e fissa le elezioni per il rinnovo del Consiglio comunale<\/p>\n","protected":false},"author":42,"featured_media":115266,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-115265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}