{"id":115305,"date":"2019-09-03T14:39:46","date_gmt":"2019-09-03T12:39:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/laino-borgo-scoperta-unantica-citta-nascosta-nella-valle-del-mercure\/"},"modified":"2023-01-16T18:33:35","modified_gmt":"2023-01-16T17:33:35","slug":"310437-laino-borgo-scoperta-unantica-citta-nascosta-nella-valle-del-mercure","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/310437-laino-borgo-scoperta-unantica-citta-nascosta-nella-valle-del-mercure\/","title":{"rendered":"Laino Borgo, scoperta un&#8217;antica citt\u00e0 nascosta nella Valle del Mercure"},"content":{"rendered":"<h4>Ci sarebbe un&#8217;antica citt\u00e0 nascosta nel ventre della montagna in localit\u00e0 San Gada, nel territorio comunale di Laino Borgo. I resti dell&#8217;insediamento sono venuti alla luce grazie ad una campagna di scavi condotta dall&#8217;Universit\u00e0 di Messina<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>LAINO BORGO (CS) &#8211; <strong>In localit\u00e0 San Gada, nel territorio comunale di Laino Borgo<\/strong>, sono venuti alla luce i resti di un&#8217;insediamento. <strong>Nella pancia della montagna un&#8217;antica citt\u00e0<\/strong> nascosta, scoperta grazie ad una <strong>importante campagna di scavi condotta dall&#8217;Universit\u00e0 di Messina<\/strong> ed in particolare dal gruppo di ricerca e scavi diretta da Fabrizio Mollo, docente del <strong>Dipartimento di Civilt\u00e0 Antiche e Moderne dell\u2019Universit\u00e0 degli Studi di Messina<\/strong>. I risultati ufficiali saranno presentati alla stampa nel corso di una conferenza stampa in programma venerd\u00ec 6 settembre alle ore 18.30 in piazza Navarro a Laino Borgo. <strong>Gli scavi iniziati e protrattisi per tutto il mese di luglio,<\/strong> hanno visto protagonisti gli studenti di archeologia dell&#8217;ateneo messinese accompagnati e guidati dai docenti Mollo e Sfacteria. Questo progetto si inserisce nel quadro delle attivit\u00e0 a supporto della valorizzazione delle zone archeologiche della Valle del Mercure che nell&#8217;ottobre 2018 avevano gi\u00e0 visto la pubblicazione di una carta archeologica.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Un progetto di scavo &#8211; rende noto l&#8217;amministrazione comunale &#8211; iniziato dopo l&#8217;incontro tra il docente messinese ed il compianto Sindaco di Laino Borgo,<strong> Francesco Armentano, che fu il primo a credere nelle potenzialit\u00e0 di questa attivit\u00e0 archeologica<\/strong> ed inserirla in un <strong>quadro di valorizzazione del turismo culturale di Laino Borgo e dell&#8217;intera Valle del Mercure<\/strong>. Il Sindaco Mariangelina Russo ha continuato nel solco di quella esperienza positiva finanziata per la prima volta proprio dall&#8217;amministrazione guidata dal primo cittadino Armentano e che ha dato esito positivo chiedendo all&#8217;Ente Parco del Pollino di supportare la continuazione degli scavi che ha portato ad u<strong>n progetto pi\u00f9 compiuto<\/strong> &#8211; redatto dall&#8217;Universit\u00e0 di Messina &#8211; <strong>per avviare una campagna archeologica in localit\u00e0 San Gada<\/strong> che ha portato ad importanti rinvenimenti che saranno illustrati nel corso della conferenza stampa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Sar\u00e0 l&#8217;occasione &#8211; ha dichiarato il Sindaco Mariangelina Russo &#8211; per<strong> raccontare alla citt\u00e0 ed al territorio l&#8217;entit\u00e0 di questi ritrovamenti che rappresentano un punto di svolta per Laino Borgo e tutta la Valle del Mercure<\/strong>, ma anche l&#8217;occasione per tributare il giusto ringraziamento al Presidente del Parco, Domenico Pappaterra, per aver creduto nel nostro progetto ed esserci stato al fianco per la v<strong>alorizzazione della nostra Comunit\u00e0<\/strong>, cos\u00ec come sar\u00e0 giusto ringraziare tutti i cittadini che, entusiasti di questa ricerca archeologica, hanno collaborato con l&#8217;amministrazione comunale. Tra questi in particolare Terenzio Calvosa, Agostino Calvosa, Armando Avena, Domenico Cersosimo ed il figlio Federico, studente di archeologia presso l&#8217;universit\u00e0 di Messina, sempre attenti a dare indicazioni per la buona riuscita degli sforzi collettivi&#8221;. All&#8217;appuntamento di venerd\u00ec parteciperanno il Sindaco di Laino Borgo, Mariangelina Russo, il vice sindaco, Innocenzo Donato, Luigi Bloise, responsabile dell&#8217;Ufficio Geoparco del Parco Nazionale del Pollino, Domenico Pappaterra, presidente del Parco Nazionale del Pollino e Maria Francesca Corigliano, assessore ai Beni Culturali della Regione Calabria. Relazioneranno sull&#8217;attivit\u00e0 di scavo Mariangela Barbato, dell&#8217;Ufficio della soprintendenza archeologica belle arti e paesaggio della provincia di Cosenza, e Fabrizio Mollo, del dipartimento di civilt\u00e0 antiche e moderne dell&#8217;Universit\u00e0 di Messina<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sarebbe un&#8217;antica citt\u00e0 nascosta nel ventre della montagna in localit\u00e0 San Gada, nel territorio comunale di Laino Borgo. I resti dell&#8217;insediamento sono venuti alla luce grazie ad una campagna di scavi condotta dall&#8217;Universit\u00e0 di Messina<\/p>\n","protected":false},"author":46,"featured_media":115306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-115305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115305"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115306"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}