{"id":115327,"date":"2019-09-04T08:58:53","date_gmt":"2019-09-04T06:58:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fondi-per-i-teatri-e-presunte-clientele-chiesto-il-processo-per-la-compagna-di-oliverio\/"},"modified":"2023-01-16T18:33:37","modified_gmt":"2023-01-16T17:33:37","slug":"310616-fondi-per-i-teatri-e-presunte-clientele-chiesto-il-processo-per-la-compagna-di-oliverio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/310616-fondi-per-i-teatri-e-presunte-clientele-chiesto-il-processo-per-la-compagna-di-oliverio\/","title":{"rendered":"Fondi per i teatri e presunte clientele, chiesto il processo per la compagna di Oliverio"},"content":{"rendered":"<h4>L&#8217;inchiesta riguarda il presunto sistema clientelare legato all&#8217;assegnazione dei contributi regionali per i teatri e le iniziative culturali<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Sono state rinviate a giudizio le nove persone indagate nell\u2019ambito di un&#8217;inchiesta avviata per far luce sull&#8217;assegnazione di contributi regionali destinati alla realizzazione di iniziative culturali, e da finanziare nel 2016 nell\u2019ambito della selezione indetta dal dipartimento Turismo e beni culturali, istruzione e cultura dell\u2019ente; fondi per oltre <strong>600mila euro<\/strong>. A maggio era stata la <strong>Guardia di Finanza di Catanzaro<\/strong> a notificare gli avvisi di garanzia e le accuse sono di turbata libert\u00e0 del procedimento di scelta del contraente in relazione all\u2019affidamento nel 2017 e da parte dello stesso dipartimento regionale, dei contributi gravanti sul fondo unico cultura.<\/p>\n<p>L&#8217;11 novembre prossimo si terr\u00e0 l&#8217;udienza preliminare e davanti al Gup Battaglia comparir\u00e0 la <strong>61enne <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7989\" target=\"_blank\" rel=\"noopener noreferrer\">Adriana Toman<\/a><\/span>,<\/strong> compagna del governatore della Calabria, Mario Oliverio (che non \u00e8 indagato), autrice e regista alla quale si contesta di aver sfruttato la posizione goduta in seno all\u2019ente proprio per la sua \u201cvicinanza\u201d al governatore.<\/p>\n<p>Gli altri indagati sono:<\/p>\n<p>&#8211; <strong>Sonia Tallarico<\/strong>, 61enne dirigente generale del Dipartimento regionale \u201cTurismo e beni culturali, istruzione e cultura\u201d;<br \/>\n&#8211; <strong>Antonio Sicoli<\/strong>, 71enne critico d\u2019arte e direttore del Maon, il Museo d\u2019arte dell\u2019Otto e Novecento di Rende;<br \/>\n&#8211; <strong>Marco Silani<\/strong>, 51enne direttore artistico della Compagnia teatrale Porta Cenere di Cosenza;<br \/>\n&#8211; <strong>Gianclaudio Festa<\/strong>, 50enne reggino coordinatore dell\u2019Avvocatura regionale;<br \/>\n&#8211; <strong>Dario Borruto<\/strong>, 67enne di Reggio Calabria, avvocato presso l&#8217;Avvocatura Regionale;<br \/>\n&#8211; <strong>Pasquale Giorgio Piraino<\/strong>, 62 anni di San Costantino Calabro;<br \/>\n&#8211; <strong>Angela Rotella<\/strong>, 67 anni di Gimigliano;<br \/>\n&#8211; <strong>Giacinto Gaetano<\/strong>, 64 anni, di Lamezia Terme.<\/p>\n<h4>LEGGI per approfondire<\/h4>\n<p>https:\/\/quicosenza.it\/news\/7989<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;inchiesta riguarda il presunto sistema clientelare legato all&#8217;assegnazione dei contributi regionali per i teatri e le iniziative culturali<\/p>\n","protected":false},"author":42,"featured_media":115328,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-115327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115327"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115328"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}