{"id":115341,"date":"2019-09-04T11:04:07","date_gmt":"2019-09-04T09:04:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arrestati-dopo-aver-rubato-la-barca-a-vela-dei-migranti-sbarcati-ieri-a-le-castella\/"},"modified":"2023-01-16T18:33:37","modified_gmt":"2023-01-16T17:33:37","slug":"310642-arrestati-dopo-aver-rubato-la-barca-a-vela-dei-migranti-sbarcati-ieri-a-le-castella","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/310642-arrestati-dopo-aver-rubato-la-barca-a-vela-dei-migranti-sbarcati-ieri-a-le-castella\/","title":{"rendered":"Arrestati dopo aver rubato la barca a vela usata dai migranti sbarcati a Le Castella"},"content":{"rendered":"<h4>Avevano messo le mani sulla barca a vela dalla <strong>quale poche ore prima erano sbarcati 53 migranti e rimasta incagliata, prendendo il largo. Arrestati dai carabinieri due uomini\u00a0<\/strong><\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>ISOLA CAPO RIZZUTO (KR) &#8211;\u00a0I carabinieri di Isola Capo Rizzuto hanno <strong>arrestato due uomini, <\/strong>accusati entrambi di <strong>furto aggravato in concorso<\/strong>: si tratta di un <strong>39enne disoccupato e pregiudicato<\/strong>, attualmente affidato in prova al servizio sociale, e di un <strong>37enne agricoltore, con precedenti penali<\/strong>, entrambi residenti nel comune del crotonese. Poco prima i due avevano sottratto la barca a vela, risultata di propriet\u00e0 di una ditta di noleggio con sede a Malta, dalla quale erano <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7992\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>sbarcati ieri 53 migranti clandestini<\/strong><\/a><\/span>. La barca era <strong>r<\/strong><b>imasta incagliata tra gli scogli nella nota localit\u00e0 turistica di Le Castella<\/b>, e i due hanno tentato il furto approfittando del fatto che fosse rimasta temporaneamente incustodita per le operazioni di soccorso.<\/p>\n<p><strong>Saliti a bordo i due hanno preso il largo nelle acque antistanti il Castello Aragonese<\/strong>, <strong>ma sono stati in breve raggiunti da personale della Guardia Costiera<\/strong>, che li ha fermati ed accompagnati presso il porto commerciale. Qui sono stati tratti in arresto.\u00a0 Il natante, posto sotto sequestro, sar\u00e0 restituito al proprietario. Gli arrestati, dopo le formalit\u00e0 di rito, sono stati tradotti presso le rispettive abitazioni in <strong>regime di arresti domiciliar<\/strong>i, in attesa dell\u2019udienza di convalida.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avevano messo le mani sulla barca a vela dalla quale poche ore prima erano sbarcati 53 migranti e rimasta incagliata, prendendo il largo. Arrestati dai carabinieri due uomini\u00a0<\/p>\n","protected":false},"author":46,"featured_media":115342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-115341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115341"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115342"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}