{"id":115498,"date":"2019-09-07T15:47:57","date_gmt":"2019-09-07T13:47:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-frecciargento-finanziato-dalla-calabria-non-piace-al-codacons-esposto-alla-corte-dei-conti\/"},"modified":"2023-01-16T18:33:48","modified_gmt":"2023-01-16T17:33:48","slug":"311172-il-frecciargento-finanziato-dalla-calabria-non-piace-al-codacons-esposto-alla-corte-dei-conti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/311172-il-frecciargento-finanziato-dalla-calabria-non-piace-al-codacons-esposto-alla-corte-dei-conti\/","title":{"rendered":"Il frecciargento finanziato dalla Calabria non piace al Codacons &#8220;esposto alla Corte dei Conti&#8221;"},"content":{"rendered":"<h4>L&#8217;associazione dei consumatori non usa troppi giri di parole &#8220;1,7 milioni di euro per un esperimento destinato a naufragare. Non possiamo permetterci questi lussi. \u00c8 immorale usare soldi pubblici per campagna elettorale&#8221;. Il Codacons presenter\u00e0 un esposto a Corte dei Conti<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA (CS) &#8211; Il notevole finanziamento messo in campo dalla Regione Calabria \u00e8 stato fondamentale nell&#8217;attivare il <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/8006\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Frecciargento Sibari-Bolazano.<\/strong><\/a><\/span> Il collegamento ad alta velocit\u00e0 di Trenitalia rappresenta senza ombra di dubbio una tappa storica per tutta la Sibaritide e, per la prima volta, permetter\u00e0 di arrivare a Roma con un treno freccia prima delle 11:00 di mattina. Il collegamento ha trovato il <strong>plauso di istituzioni, sindaci, imprenditori e associazioni del territorio<\/strong> ma anche <strong>la durissima reazione del Codacons<\/strong> a cui non \u00e8 andato gi\u00f9 il <strong>finanziamento pubblico definito stratosferico<\/strong> per <strong>un servizio &#8220;sperimentale&#8221; utile solo a una piccolissima parte del territorio calabrese<\/strong>, mentre <strong>il finanziamento della linea jonica si limiterebbe a mere opere di manutenzione<\/strong> e non ad un potenziamento della linea.<\/p>\n<p>Un attacco durissimo che arriva dal <strong>vicepresidente del Codacons Francesco Di Lieto<\/strong> &#8220;come sempre Trenitalia prevede delle tariffe agevolate in occasione delle tornate elettorali. E per le prossime elezioni ha ottenuto dalla Regione Calabria solamente 1,7 milioni di euro &#8211; scrive Di Lieto &#8211;\u00a0Cifra che il Governatore Oliverio ha immediatamente corrisposto per poter veder partire da Sibari un nuovissimo Frecciargento. <strong>Un esperimento forse utile ad una piccolissima parte del territorio calabrese, sicuramente molto costoso per tutti<\/strong>. Forse Oliverio non \u00e8 stato informato, ma la Calabria non finisce a Paola ma non \u00e8 una questione di becero campanilismo. Perch\u00e9 <strong>questa costosa inaugurazione \u00e8 gi\u00e0 destinata a naufragare<\/strong><em>&#8220;<\/em>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/8007\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-311006\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/09\/freccia-606x400.png\" alt=\"\" width=\"617\" height=\"407\" title=\"\"><\/a><\/p>\n<p>&#8220;Proviamo a rifletterci &#8211; sostiene Francesco Di Lieto &#8211; Il Frecciargento lascer\u00e0 da Sibari alle 6,15 per giungere a Roma Termini alle 10,30, quindi ripartir\u00e0 da Roma alle 18,14 per rientrare a Sibari alle 22,45. I passeggeri, <strong>una volta a Sibari troverebbero una stazione pressoch\u00e9 deserta, senza la possibilit\u00e0 di utilizzare treni regionali<\/strong>. Ma niente paura. La Regione provveder\u00e0 a g<strong>arantire un servizio Autobus sostitutivo<\/strong>. Probabilmente serviranno tanti autobus, visto che un Frecciargento ospita circa 500 passeggeri e se giungesse a Sibari con solo la met\u00e0 dei passeggeri, per riportarli a casa servirebbero almeno 10 mezzi. Stando cos\u00ec le cose <strong>da luned\u00ec prossimo chi vorr\u00e0 utilizzar il Frecciargento dovr\u00e0 utilizzare mezzi di fortuna<\/strong>. Per cui possono dormire sonni tranquilli le compagnie che offrono collegamenti autobus per Roma <strong>mentre i Calabresi si apprestano a buttare 1,7 milioni di euro<\/strong>. Ma tanto non abbiamo problemi economici e possiamo permetterci questi esperimenti. <strong>Gi\u00e0 immaginiamo le fermate intermedie che verranno promesse da qui al prossimo novembre<\/strong> &#8211; ironizza Di Lieto. Nulla di nuovo sotto il sole,<strong> del resto siamo la stessa Regione che ha impiegato risorse pubbliche, poco meno di 1 milione di euro<\/strong>\u00a0per sostenere RFI nell&#8217;eseguire q<strong>uelle che appaiono delle semplici opere di manutenzione<\/strong>. Opere che n<strong>on comportano un serio potenziamento della linea jonica<\/strong> (quella a binario unico) e che <strong>non prevedono il fondamentale recupero delle stazioni<\/strong>. Il tutto senza contare che le<strong> opere eseguite da RFI sono balzate agli onori delle cronache sia per preoccupanti cedimenti, come il collasso del ponte a Cropani<\/strong> avvenuto solo la scorsa settimana, e sia per le ancor pi\u00f9 allarmanti infiltrazioni criminali&#8221;.<\/p>\n<h4>Esposto alla Corte dei Conti<\/h4>\n<p>&#8220;<strong>Per questo motivo il Codacons ha deciso di presentare un esposto alla Corte dei Conti<\/strong> affinch\u00e9 sia a<strong>ccuratamente verificato quello che a noi appare un vero e proprio spreco<\/strong> &#8211; conclude Di Lieto &#8211; ovvero <strong>l\u2019utilizzo di una somma stratosferica destinata a sostenere un \u201cesperimento\u201d<\/strong>. Una \u201cprova\u201d utile, probabilmente, ad una minima parte del territorio Calabrese e <strong>destinata a naufragare nel breve volgere di un anno<\/strong>. Riteniamo sia i<strong>mmorale utilizzare risorse pubbliche per finanziare una campagna elettorale<\/strong>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;associazione dei consumatori non usa troppi giri di parole &#8220;1,7 milioni di euro per un esperimento destinato a naufragare. Non possiamo permetterci questi lussi. \u00c8 immorale usare soldi pubblici per campagna elettorale&#8221;. Il Codacons presenter\u00e0 un esposto a Corte dei Conti<\/p>\n","protected":false},"author":46,"featured_media":115499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-115498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115498"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115499"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}