{"id":115756,"date":"2019-09-12T16:08:23","date_gmt":"2019-09-12T14:08:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/metro-cosenza-rende-unical-ferrara-m5s-ritardi-che-mettono-a-rischio-il-finanziamento\/"},"modified":"2023-01-16T18:34:07","modified_gmt":"2023-01-16T17:34:07","slug":"312082-metro-cosenza-rende-unical-ferrara-m5s-ritardi-che-mettono-a-rischio-il-finanziamento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/312082-metro-cosenza-rende-unical-ferrara-m5s-ritardi-che-mettono-a-rischio-il-finanziamento\/","title":{"rendered":"Metro Cosenza-Rende-Unical, Ferrara (M5S): &#8220;Ritardi che mettono a rischio il finanziamento&#8221;"},"content":{"rendered":"<h4><strong>Secondo l&#8217;europarlamentare del Movimento Cinque Stelle, che ha presentato un&#8217;interrogazione alla Commissione europea, &#8220;la mancata approvazione del progetto esecutivo ed altre criticit\u00e0 potrebbero determinare una riprogrammazione delle risorse: a rischio 156,8 milioni di euro stanziati per la realizzazione del progetto&#8221;<\/strong><!--more--><\/h4>\n<h4><\/h4>\n<p>COSENZA &#8211; L\u2019eurodeputata Laura Ferrara, membro della Commissione per i trasporti ed il turismo del Parlamento europeo, riaccende i riflettori sul &#8220;Sistema di <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7459\" target=\"_blank\" rel=\"noopener noreferrer\">c<strong>ollegamento metropolitano tra Cosenza, Rende e Universit\u00e0 della Calabria<\/strong><\/a><\/span>&#8221; e su una possibile riprogrammazione delle risorse. &#8220;Come ampiamente previsto la progettazione e realizzazione della metro leggera che dovr\u00e0 collegare Cosenza, Rende e Universit\u00e0 della Calabria <strong>procede con notevole ritardo e ci\u00f2 mette a rischio il finanziamento ma si potrebbero comunque riprogrammare le risorse<\/strong>&#8220;. Queste le parole della pentastellata che nella giornata di oggi ha presentato un&#8217;<strong>interrogazione alla Commissione europea la parlamentare a Bruxelles sull&#8217;argomento<\/strong> mettendo in risalto le criticit\u00e0 e i rallentamenti del progetto contestato da un\u2019ampia fetta della cittadinanza dei centri coinvolti, Cosenza e Rende, da comitati ed anche dal Movimento 5 stelle. Nella nota si evidenzia ancora come il progetto della metro leggera ha gi\u00e0 cagionato numerosi disagi ai cittadini cosentini che si vedono costretti a subire lunghe code in auto a causa dell&#8217;enorme cantiere che chiude di fatto un\u2019arteria stradale fondamentale per la circolazione del traffico cittadino e non solo.<\/p>\n<p>La cifra iniziale stanziata, pari a<strong> 156,8 milioni di euro<\/strong>, di cui attualmente <strong>certificati 2,8 milioni dei 10 milioni che si stimava di raggiungere al 31.12.2018<\/strong>, rischiano, dunque, di <strong>tornare indietro a causa della mancata approvazione del progetto esecutivo<\/strong>, la questione del tracciato e i tempi di realizzazione, costituisce un futuro rischio finanziario per il programma e potrebbe determinare una riprogrammazione delle risorse.<\/p>\n<p>La Ferrara mette ancora in evidenza come gi\u00e0 nella fase di avvio dell\u2019attuazione dell\u2019iter autorizzativo per l\u2019esercizio del materiale rotabile e per la redazione della progettazione esecutiva si presentava il primo rallentamento. Un secondo intoppo lo si registrava, altres\u00ec, in fase di avvio dei lavori per la risoluzione di alcune interferenze con il tracciato di progetto. &#8220;<strong>I dubbi sulla reale utilit\u00e0 di questa mega opera<\/strong> &#8211; conclude &#8211; <strong>che sventrer\u00e0 due citt\u00e0 rimangono tutti<\/strong>, a maggior ragione se si pensa all\u2019<strong>ingente somma di denaro che si investirebbe per un intervento sproporzionato rispetto alla potenziale utenza di riferimento<\/strong>. Considerato che il progetto \u00e8 diviso in due fasi, tra le programmazioni 2007-2013 e 2014-2020, ho chiesto alla Commissione a quanto ammontano i pagamenti effettuati a valere sulla programmazione 2014\/2020 e se vi siano potenziali rischi di futura perdita del finanziamento e, conseguentemente, <strong>se la Commissione ritiene sia preferibile la riprogrammazione delle risorse verso altre azioni conformemente a<\/strong> quanto dispone l\u2019art.30 Reg.(UE) n.1303\/2013 sulla modifica dei programmi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo l&#8217;europarlamentare del Movimento Cinque Stelle, che ha presentato un&#8217;interrogazione alla Commissione europea, &#8220;la mancata approvazione del progetto esecutivo ed altre criticit\u00e0 potrebbero determinare una riprogrammazione delle risorse: a rischio 156,8 milioni di euro stanziati per la realizzazione del progetto&#8221;<\/p>\n","protected":false},"author":52,"featured_media":115757,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-115756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115756"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115757"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}