{"id":115809,"date":"2019-09-13T13:16:50","date_gmt":"2019-09-13T11:16:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cambio-ai-vertici-dei-guardiani-della-costa-jonica-cosentina\/"},"modified":"2023-01-16T18:34:10","modified_gmt":"2023-01-16T17:34:10","slug":"312270-cambio-ai-vertici-dei-guardiani-della-costa-jonica-cosentina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/312270-cambio-ai-vertici-dei-guardiani-della-costa-jonica-cosentina\/","title":{"rendered":"Cambio ai vertici dei &#8216;guardiani&#8217; della costa jonica cosentina"},"content":{"rendered":"<h4>Si \u00e8 insediato oggi il nuovo comandante della Capitaneria di Porto di Corigliano<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Oggi, Venerd\u00ec 13 Settembre, presso la Capitaneria di Porto di Corigliano Calabro si \u00e8 tenuta la cerimonia del <strong>cambio di Comando tra il Capitano di Fregata Pietro Di Giovanni ed il Capitano di Fregata Alberto Mandrillo.<\/strong> All&#8217;evento hanno partecipato, oltre agli operatori della Stazione, il Direttore Marittimo della Calabria e della Basilicata Tirrenica Contrammiraglio Giancarlo Russo e le massime autorit\u00e0 militari, civili e religiose locali e della provincia di Cosenza. Il Comandante Pietro Di Giovanni per un anno ha coordinato le attivit\u00e0 della Capitaneria di Porto di Corigliano fronteggiando con professionalit\u00e0 tutte le situazioni di emergenza in mare e portando a termine diverse operazioni con una proficua collaborazione della Procura di Castrovillari conseguendo illustri risultati a tutela dell&#8217;ambiente e del demanio pubblico. Destinato ad un nuovo e prestigioso\u00a0incarico presso il Comando Generale del Corpo delle Capitanerie di Porto di Roma affida la guida della Capitaneria di Porto di Corigliano al Comandante Alberto Mandrillo 48enne originario di Taranto laureato in Giurisprudenza presso l\u2019Universit\u00e0 degli Studi di Bologna ed abilitato all\u2019esercizio della professione di Avvocato presso la Corte di Appello di Catanzaro. Il Comandante Mandrillo proviene dalla Capitaneria di porto di Salerno dove ha ricoperto gli incarichi di Capo servizio Sicurezza della Navigazione e Portuale e Capo servizio Personale Marittimo, Attivit\u00e0 Marittime e Contenzioso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 insediato oggi il nuovo comandante della Capitaneria di Porto di Corigliano<\/p>\n","protected":false},"author":43,"featured_media":115810,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-115809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115809"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115810"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}