{"id":115967,"date":"2019-09-17T05:30:35","date_gmt":"2019-09-17T03:30:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/piste-ciclabili-pericolose-per-pedoni-ciclisti-ed-automobilisti\/"},"modified":"2023-01-16T18:34:20","modified_gmt":"2023-01-16T17:34:20","slug":"312837-piste-ciclabili-pericolose-per-pedoni-ciclisti-ed-automobilisti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/312837-piste-ciclabili-pericolose-per-pedoni-ciclisti-ed-automobilisti\/","title":{"rendered":"Piste ciclabili pericolose per pedoni, ciclisti ed automobilisti"},"content":{"rendered":"<h4>Anomalie a Cosenza nei percorsi ciclabili<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00abDurante l\u2019ultima commissione consiliare Sport, svoltasi alla presenza dell\u2019assessore al Benessere del Comune di Cosenza Carmine Vizza e del dirigente dei settori Sport e Lavori Pubblici Francesco Converso, ho sollevato &#8211; sottolinea sulla sua pagina facebook Bianca Rende consigliere comunale in quota PD &#8211; la questione della sicurezza della nuova pista ciclabile. Un <strong>cordolo di 50 x 40 centimetri. lungo il viale Parco<\/strong> non sembra affatto compatibile con le ragioni della sicurezza dei cicloamatori e degli automobilisti, che vedono restringersi la carreggiata, senza possibilit\u00e0 di scavalco in emergenza\u00bb.<\/p>\n<p>\u00abConsiderato, altres\u00ec, che lungo via Bendicenti ci sono tratti a fruibilit\u00e0 mista da parte di pedoni e ciclisti, che mettono a repentaglio la sicurezza di entrambi, dal momento che ai sensi del codice delle strada il ciclista \u00e8 obbligato ad usare la ciclabile, se esistente, anche quando \u00e8 occupata. Personalmente, sono a favore delle piste ciclabili, anzi mi auguro passino presto anche dentro la citt\u00e0, consentendo cos\u00ec una circolazione alternativa da parte di molti, ma come al solito in questa citt\u00e0 le cose si fanno pensando all\u2019opera e non ai cittadini. Sicurezza, sicurezza, sicurezza. Questo \u00e8 l\u2019imperativo che dovrebbe guidare ogni intervento. Ad oggi non \u00e8 cos\u00ec e chiediamo che si cambi subito il progetto\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anomalie a Cosenza nei percorsi ciclabili<\/p>\n","protected":false},"author":43,"featured_media":115968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-115967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=115967"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/115967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/115968"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=115967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=115967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=115967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}