{"id":116337,"date":"2019-09-23T05:16:56","date_gmt":"2019-09-23T03:16:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spruzzano-spray-al-peperoncino-in-piazza-interviene-la-polizia\/"},"modified":"2023-01-16T18:34:45","modified_gmt":"2023-01-16T17:34:45","slug":"314129-spruzzano-spray-al-peperoncino-in-piazza-interviene-la-polizia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/314129-spruzzano-spray-al-peperoncino-in-piazza-interviene-la-polizia\/","title":{"rendered":"Spruzzano spray al peperoncino in piazza, interviene la Polizia"},"content":{"rendered":"<h4>Avrebbero spruzzato lo spray in una delle strade della movida per poi fuggire. Ed \u00e8 caccia agli autori del gesto<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; Due persone hanno contattato la Polizia per segnalare il fatto accaduto nella notte tra sabato e domenica quando alcuni soggetti, non identificati, hanno spruzzato dello spray urticante tra la folla in una delle piazze della &#8216;movida&#8217; di Lamezia e poi si sono dati alla fuga. Quando i poliziotti sono arrivati sul posto hanno trovato uno dei ragazzi con forte lacrimazione e con gli occhi rossi ma nessuno sarebbe stato in grado di fornire altri dettagli. Le forze dell\u2019ordine hanno avviato le indagini e hanno sequestrato le immagini dei sistemi di videosorveglianza presenti sul posto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avrebbero spruzzato lo spray in una delle strade della movida per poi fuggire. Ed \u00e8 caccia agli autori del gesto<\/p>\n","protected":false},"author":42,"featured_media":116338,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-116337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=116337"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/116338"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=116337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=116337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=116337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}