{"id":116353,"date":"2019-09-23T09:41:10","date_gmt":"2019-09-23T07:41:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mai-piu-cani-in-canile-liniziativa-e-lincentivo-di-120-e-del-comune-di-bisignano\/"},"modified":"2023-01-16T18:34:47","modified_gmt":"2023-01-16T17:34:47","slug":"314164-mai-piu-cani-in-canile-liniziativa-e-lincentivo-di-120-e-del-comune-di-bisignano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/314164-mai-piu-cani-in-canile-liniziativa-e-lincentivo-di-120-e-del-comune-di-bisignano\/","title":{"rendered":"&#8220;Mai pi\u00f9 cani in canile&#8221;, l&#8217;iniziativa e l&#8217;incentivo di 120 \u20ac del Comune di Bisignano"},"content":{"rendered":"<h4>Una splendida oltre che utile iniziativa quella messa in campo dal Comune di Bisignano presentata dall&#8217;assessore Alessia Prezioso, per fare uscire i cani dai canili e risparmiare sui costi per il loro mantenimento<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>BISIGNANO (CS) &#8211; Tre obiettivi in una sola iniziativa: favorire il benessere animale, diminuire i costi e le spese per il mantenimento dei cani in canile e ridurre il fenomeno del randagismo. Il tutto con un incentivo a chi decider\u00e0 di aprire il suo cuore e la sua casa ad un peloso, di propriet\u00e0 del comune di Bisignano: <strong>120 euro l&#8217;anno<\/strong>. &#8220;Il progetto &#8216;<strong>mai pi\u00f9 cani in canile&#8217; <\/strong>\u00e8 utile non solo per svuotare i canili e favorire il benessere dei pelosi, ma anche per abbattere i costi e le spese per il mantenimento dei cani di propriet\u00e0 del Comune di Bisignano ospitati nei canili convenzionati. E questo consente di conseguenza consente, liberando a rotazione i cani dal canile sanitario, di programmare pi\u00f9 catture sul territorio, garantendo maggiore sicurezza, igiene pubblica e meno randagi in giro&#8221;.<\/p>\n<p>L&#8217;idea dell&#8217;assessorato Tutela degli Animali \u00e8 stata illustrata dall&#8217;assessore <strong>Alessia Prezioso<\/strong> ai microfoni di <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/7776\" target=\"_blank\" rel=\"noopener noreferrer\">RLB<\/a><\/span><\/strong><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/685406020&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p>Il cuore di questo progetto per\u00f2, \u00e8 soprattutto l&#8217;incentivo alle adozioni. L&#8217;iniziativa infatti, \u00e8 riservata agli &#8216;adottanti&#8217; della provincia di Cosenza che vorranno portare a casa un cane di propriet\u00e0 del Comune di Bisignano, ospitato nei canili convenzionati con l&#8217;ente (Lattarico, Bisignano e Mendicino). Chi adotter\u00e0 non solo si porter\u00e0 a casa un cane <strong>vaccinato, microchippato e sterilizzato<\/strong>, ma l&#8217;ente si impegna a dare un contributo di <strong>120 euro<\/strong> l&#8217;anno per le spese, il mantenimento e cure. Questo ovviamente <strong>sotto controllo dall&#8217;inizio alla fine.<\/strong> Questi 120 euro rappresentano certamente una spesa per il Comune, ma in maniera ridotta se si pensa al costo giornaliero per mantenere un cane in canile&#8221;.<\/p>\n<p><iframe loading=\"lazy\" title=\"Bisignano mai pi\u00f9 cani in canile - &quot; Io aspetto te adottami&quot;\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/fEwnFbN-IGY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Infine, oltre al contributo del Comune sar\u00e0 offerto un <strong>percorso gratuito educativo cinofilo di 5 incontri per inserire il cane nella nuova famiglia. L&#8217;assessore Prezioso invita a visitare la pagina Facebook &#8220;<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/8166\" target=\"_blank\" rel=\"noopener noreferrer\">Io aspetto te adottami<\/a><\/span><\/strong>&#8221; o a contattare per informazioni il numero <strong>349 7196626<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-314186 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/09\/71532199_557999011607425_304668255375589376_n.jpg\" alt=\"\" width=\"480\" height=\"678\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una splendida oltre che utile iniziativa quella messa in campo dal Comune di Bisignano presentata dall&#8217;assessore Alessia Prezioso, per fare uscire i cani dai canili e risparmiare sui costi per il loro mantenimento<\/p>\n","protected":false},"author":42,"featured_media":116354,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,47],"tags":[],"class_list":["post-116353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-qui-la-zampa"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=116353"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/116354"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=116353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=116353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=116353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}