{"id":116357,"date":"2019-09-23T10:08:54","date_gmt":"2019-09-23T08:08:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/anche-il-sindaco-di-aprigliano-lascia-il-pd-e-aderisce-a-italia-viva\/"},"modified":"2023-01-16T18:34:47","modified_gmt":"2023-01-16T17:34:47","slug":"314175-anche-il-sindaco-di-aprigliano-lascia-il-pd-e-aderisce-a-italia-viva","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/314175-anche-il-sindaco-di-aprigliano-lascia-il-pd-e-aderisce-a-italia-viva\/","title":{"rendered":"Anche il sindaco di Aprigliano lascia il Pd e aderisce a Italia Viva"},"content":{"rendered":"<h4>Si susseguono le adesioni al nuovo soggetto politico di Matteo Renzi. Nei giorni scorsi anche Bianca Rende ha annunciato il suo passaggio Italia Viva. Oggi \u00e8 la volta del sindaco di Aprigliano<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>APRIGLIANO (CS) &#8211; Alessandro Porco, primo cittadino di Aprigliano aderisce a Italia Viva e motiva il suo passaggio: \u00abIn un momento politico di grande fibrillazione, di incertezze, quando sarebbe molto pi\u00f9 facile guardare dalla finestra e fare scelte di opportunismo, sento il dovere di esprimere la mia opinione e dichiarare apertamente da quale parte sto, non senza aver consumato un legittimo conflitto interiore\u00bb.<\/p>\n<p>\u00abScelgo di aderire alla nuova formazione politica lanciata da Matteo Renzi in quanto perfettamente aderente al mio percorso formativo, ideale e politico, avendo condiviso &#8211; spiega Porco &#8211; sempre e consapevolmente, tutte le iniziative che l\u2019ex Segretario del PD ed ex Presidente del Consiglio dei Ministri, ora senatore della Repubblica, ha intrapreso: dalle primarie, all\u2019azione di governo del Paese; dalla Leopolda al referendum per la riforma costituzionale, sino alla odierna formazione di \u201cItalia Viva\u201d. Bisogna considerare che il tentativo di costruire la casa comune dei Democratici, non si \u00e8 mai, purtroppo, realmente concretizzata, lasciando il posto piuttosto ad una conflittualit\u00e0 interna per la supremazia delle individualit\u00e0 che ha lacerato il Partito allontanandolo dal Paese reale\u00bb.<\/p>\n<p>\u00abCon \u201cItalia Viva\u201d inizio un percorso nuovo, sicuramente impegnativo, ricominciando da zero, con la visione di un futuro possibile, in un\u2019area ampia, dove abbiano cittadinanza le persone che affrontano il quotidiano con fatica, dove \u00e8 necessario infondere coraggio e dare certezze piuttosto che lasciar soffiare i venti sovranisti e le barbarie disumane\u00bb.<\/p>\n<p>\u00abSono consapevole di lasciare una comunit\u00e0 con la quale ho condiviso molto delle mie battaglie e che mi ha dato molto; continuer\u00f2 a guardare a questi amici e compagni con il rispetto e la stima che si deve a chi ha fatto un tratto di strada insieme a me, ma ora imbocco un percorso diverso. Resto coerente con i miei valori, con l\u2019entusiasmo di sempre. <strong>Aderisco ad un modello di partito che auspico diverso e migliore<\/strong> dagli schemi sin ora proposti e che hanno generato una sorta di autoreferezialita\u2019 difficile da scrostare: nonostante la mia esperienza personale, osservo che un vero rinnovamento, non solo generazionale, non si \u00e8 mai pienamente attuato e il dibattito ha sofferto spesso di proposte dichiarate ma, troppo poco praticate\u00bb.<\/p>\n<p>\u00ab\u00c8 giunto il momento di un cambio di passo e il tempo pu\u00f2 essere favorevole: \u201cItalia Viva\u201d, non avendo l\u2019ansia della partecipazione diretta ad una immediata competizione elettorale, in vista delle prossime regionali, appogger\u00e0, in Calabria come nelle altre regioni interessate, le liste di centro sinistra, nel mentre potr\u00e0 elaborare e consolidare un progetto con il quale misurarsi in futuro nell\u2019agone politico. Per essere chiaro &#8211; spiega ancora &#8211; non essendo in calendario, dunque, alcuna velleit\u00e0 di candidature, sar\u00e0 questo un ottimo banco di riflessione da parte di tutti\u00bb.<\/p>\n<p>\u00ab\u201cItalia Viva\u201d, insomma, non \u00e8 un contenitore buono per il riciclo di chi non ha trovato spazio nel Partito Democratico, ne\u2019 per chi pensa di portarsi dietro in eredit\u00e0 un curriculum politico, seppure di tutto rispetto; \u00e8, invece, un laboratorio dove tutti avranno cittadinanza, ma che necessita di forze propulsive e non di allori. Questa nuova formazione nasce <strong>all\u2019indomani della formazione del Governo PD-M5S<\/strong>, sebbene se ne avesse sentore da tempo. Le ragioni non stanno solo nella difficile convivenza fra i cosiddetti renziani e il resto delle varie anime del PD; \u00e8 soprattutto la concezione di una diversa politica. Matteo Renzi \u00e8 stato l\u2019artefice dell\u2019attuale Governo, scongiurando non solo l\u2019aumento dell\u2019IVA ma anche il pericolo di una deriva sovranista; gli italiani non devono subire la recessione economica ma devono sentirsi a pieno titolo cittadini europei. Ha dimostrato che, nonostante le aggressioni ricevute, nel tempo, da dirigenti e militanti del M5S, in primis viene il bene dell\u2019Italia: e l\u2019Italia non merita la diffidenza dei mercati, l\u2019uscita dall\u2019euro, la sofferenza dei risparmiatori che Salvini e la destra sovranista avrebbero causato\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si susseguono le adesioni al nuovo soggetto politico di Matteo Renzi. Nei giorni scorsi anche Bianca Rende ha annunciato il suo passaggio Italia Viva. Oggi \u00e8 la volta del sindaco di Aprigliano<\/p>\n","protected":false},"author":42,"featured_media":116358,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-116357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=116357"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/116358"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=116357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=116357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=116357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}