{"id":116403,"date":"2019-09-23T18:14:44","date_gmt":"2019-09-23T16:14:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/visita-di-salvini-assessore-rendese-noi-terroni-conosciamo-disprezzo-ed-esclusione\/"},"modified":"2023-01-16T18:34:50","modified_gmt":"2023-01-16T17:34:50","slug":"314318-visita-di-salvini-assessore-rendese-noi-terroni-conosciamo-disprezzo-ed-esclusione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/314318-visita-di-salvini-assessore-rendese-noi-terroni-conosciamo-disprezzo-ed-esclusione\/","title":{"rendered":"Visita di Salvini, assessore rendese: \u00abNoi terroni conosciamo disprezzo ed esclusione\u00bb"},"content":{"rendered":"<h4>Marta Petrusewicz esprime la propria posizione in merito alle polemiche sulla visita dell&#8217;ex Ministro dell&#8217;Interno<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; \u201cSenza voler interferire nelle dinamiche politiche ad alcun livello e tenendo fermo il diritto inalienabile alla parola, vogliamo sottolineare come il nostro agire politico e culturale si ispiri ai valori di solidariet\u00e0, inclusione e valorizzazione delle differenze\u201d. E&#8217; quanto affermato oggi dall\u2019assessore alla cultura del Comune di Rende Marta Petrusewicz, in riferimento alle polemiche scaturite intorno la prossima visita a Cosenza da parte dell\u2019onorevole Matteo Salvini. \u201cI principi democratici sanciti dalla nostra costituzione\u201d, ha proseguito l&#8217;assessore \u201ccontrastano con le proposte di sovranismo, suprematismo ed esclusione in quanto educativamente nocive e moralmente pericolose per il con-vivere civico\u201d. \u201cNoi \u201cterroni\u201d, ha concluso la Petrusewicz, \u201cconosciamo fin troppo bene cosa voglia dire essere esuli in terra straniera, come disprezzo ed esclusione siano il pane quotidiano di chi \u00e8 costretto ad emigrare. Per questo <strong>dobbiamo pretendere il massimo rispetto verso i valori che ispirano il nostro vivere sociale<\/strong>: perch\u00e9 negare un principio di solidariet\u00e0 universale significa negare le basi della nostra convivenza sociale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marta Petrusewicz esprime la propria posizione in merito alle polemiche sulla visita dell&#8217;ex Ministro dell&#8217;Interno<\/p>\n","protected":false},"author":43,"featured_media":116404,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-116403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=116403"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/116404"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=116403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=116403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=116403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}