{"id":116491,"date":"2019-09-25T09:24:35","date_gmt":"2019-09-25T07:24:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazione-grimilde-due-nuovi-arresti-nel-clan-grande-aracri\/"},"modified":"2023-01-16T18:34:55","modified_gmt":"2023-01-16T17:34:55","slug":"314713-operazione-grimilde-due-nuovi-arresti-nel-clan-grande-aracri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/314713-operazione-grimilde-due-nuovi-arresti-nel-clan-grande-aracri\/","title":{"rendered":"Operazione &#8220;Grimilde&#8221;, due nuovi arresti nel clan Grande Aracri"},"content":{"rendered":"<h4>I reati contestati ai due giovani, di 28 e 29 anni, sono estorsione ed intestazione fittizia di beni. I nomi erano gi\u00e0 spuntati nell&#8217;inchiesta dello scorso mese di giugno<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>BOLOGNA &#8211; La squadra mobile di Bologna ha eseguito ieri le due ordinanze di custodia cautelare in carcere emesse dal Gip presso il Tribunale bolognese nei confronti di due soggetti, ritenuti appartenenti alla cosca di &#8216;ndrangheta Grande Aracri di Cutro. I destinatari del provvedimento restrittivo sono <strong>Paolo Grande Aracri, di 29 anni, e Manuel Conte di 28,<\/strong> gi\u00e0 colpiti da analogo provvedimento nel giugno scorso, nell&#8217;ambito dell&#8217;operazione ribattezzata Grimilde, e ritenuti responsabili del reato di estorsione ed intestazione fittizia di beni. L\u2019operazione infatti, \u00e8 il risultato di un ulteriore sviluppo dell\u2019indagine sviluppata sempre dall\u2019Ufficio investigativo felsineo e che a fine giugno scorso aveva gi\u00e0 portato all\u2019esecuzione di 16 provvedimenti restrittivi nell\u2019ambito dell\u2019operazione denominata \u201cGrimilde\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I reati contestati ai due giovani, di 28 e 29 anni, sono estorsione ed intestazione fittizia di beni. I nomi erano gi\u00e0 spuntati nell&#8217;inchiesta dello scorso mese di giugno<\/p>\n","protected":false},"author":42,"featured_media":116492,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-116491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=116491"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/116492"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=116491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=116491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=116491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}