{"id":116553,"date":"2019-09-26T11:02:19","date_gmt":"2019-09-26T09:02:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/pene-piu-dure-per-chi-aggredisce-i-medici-speranza-le-aggressioni-sono-inaccettabili\/"},"modified":"2023-01-16T18:35:00","modified_gmt":"2023-01-16T17:35:00","slug":"314898-pene-piu-dure-per-chi-aggredisce-i-medici-speranza-le-aggressioni-sono-inaccettabili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/314898-pene-piu-dure-per-chi-aggredisce-i-medici-speranza-le-aggressioni-sono-inaccettabili\/","title":{"rendered":"Pene pi\u00f9 dure per chi aggredisce i medici. Speranza &#8220;le violenze sono inaccettabili&#8221;"},"content":{"rendered":"<h4>Approvato all&#8217;unanimit\u00e0 al Senato, con 237 voti favorevoli il ddl per la sicurezza degli esercenti delle professioni sanitarie nell&#8217;esercizio delle loro funzioni. Il provvedimento adesso passa alla Camera. Soddisfatto il Ministro Speranza &#8220;violenze e aggressioni ai medici sono inaccettabili&#8221;<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Pene pi\u00f9 severe che chi aggredisce medici e personale sanitario durante l&#8217;esercizio della professione e procedibilit\u00e0 d&#8217;ufficio contro l&#8217;<strong>aggressore anche senza la querela della persona offesa<\/strong>. Sono le misure previste dal <strong>Decreto Legge per &#8216;la sicurezza degli esercenti delle professioni sanitarie nell&#8217;esercizio delle loro funzioni&#8217;<\/strong>, approvato dal Senato all&#8217;unanimit\u00e0 con<strong> 237 voti favorevoli<\/strong> per contrasta&#8217;esame della Camera. &#8220;G<em>li episodi di violenza e le aggressioni a chi lavora nel mondo della sanit\u00e0 sono inaccettabili<\/em> &#8211; ha subito commentato su Twitter<strong> il ministro della Salute, Roberto Speranza<\/strong> -. <em>Oggi dal Senato \u00e8 arrivata una prima importante risposta con il voto all&#8217;unanimit\u00e0. \u00c8 la strada giusta su cui continuare a lavorare<\/em>&#8220;.<\/p>\n<h4>7 medici su 10 ha subito un&#8217;aggressione<\/h4>\n<p><strong>Tentativi di strangolamento<\/strong> fino a <strong>stupri o vere e proprie spedizioni punitive<\/strong>, ma anche <strong>parolacce e insulti, il 66% dei medici<\/strong>, ovvero quasi<strong> 7 su 10, dichiara di aver subito un&#8217;aggressione<\/strong> da parte dei pazienti. Di questi, oltre due su tre sono stati aggrediti verbalmente, mentre la restante parte fisicamente. Questo quanto emerge dall&#8217;ultimo sondaggio condotto dal sindacato dei medici dirigenti Anaao Assomed. Le aree pi\u00f9 a rischio sono la <strong>psichiatria e il pronto soccorso<\/strong>, ed i pericoli maggiori si corrono al Sud: arriva infatti a<strong>l 72% nel Sud e nelle Isole il numero di medici che denuncia aggressioni<\/strong>, e <strong>sale all&#8217;80% tra chi, di loro, lavora nei pronto soccorso<\/strong>. Quanto alle cause, i medici le attribuiscono a fattori socio-culturali, al definanziamento del Servizio Sanitario ed a carenze organizzative.<\/p>\n<h4>Cosa prevede il Decreto Legge<\/h4>\n<p>Nel decreto viene anche istituito di un <strong>Osservatorio nazionale sulla sicurezza degli esercenti le professioni sanitarie<\/strong>, grazie al quale sar\u00e0 possibile non solo <strong>monitorare gli episodi di violenza<\/strong> a danno dei sanitari ma anche <strong>promuovere studi ed analisi per poter proporre misure idonee alla rimozione dei fattori di rischio negli ambienti pi\u00f9 esposti<\/strong>. L\u2019Osservatorio dovr\u00e0 essere composto da rappresentanti delle Regioni, un rappresentante dell\u2019Agenzia nazionale per i servizi sanitari regionali (Agenas), rappresentanti dei ministeri di Interno, Difesa, Giustizia e Lavoro e Politiche sociali, degli Ordini professionali interessati, delle organizzazioni di settore e delle associazioni di pazienti.\u00a0\u00a0Il provvedimento approvato dal Senato modifica anche il codice penale per estendere al personale socio-sanitario la <strong>disciplina relativa alle lesioni gravi arrecate a pubblico ufficial<\/strong>e. Previste anche <strong>circostanze aggravanti quando un&#8217;eventuale aggressione avviene con violenza o minaccia<\/strong>. Gli aggressori rischiano quindi la<b> reclusione<\/b>\u00a0<strong>da 4 a 10 anni<\/strong> per lesioni gravi e <strong>da 8 a 16 anni per lesioni gravissime<\/strong>, con un aggravamento di pena rispetto agli stessi reati (articolo 583 del Codice penale) puniti con il carcere da 3 a 7 anni per lesioni gravi e da 6 a 12 per quelle gravissime.<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/quicosenza.it\/news\/provincia-cosenza\/309543-medico-del-118-accoltellato-durante-un-intervento-di-soccorso<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Approvato all&#8217;unanimit\u00e0 al Senato, con 237 voti favorevoli il ddl per la sicurezza degli esercenti delle professioni sanitarie nell&#8217;esercizio delle loro funzioni. Il provvedimento adesso passa alla Camera. Soddisfatto il Ministro Speranza &#8220;violenze e aggressioni ai medici sono inaccettabili&#8221;<\/p>\n","protected":false},"author":46,"featured_media":116554,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-116553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=116553"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/116553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/116554"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=116553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=116553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=116553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}