{"id":117020,"date":"2019-10-04T08:40:01","date_gmt":"2019-10-04T06:40:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/terremoto-in-provincia-di-cosenza-2\/"},"modified":"2023-01-16T18:35:31","modified_gmt":"2023-01-16T17:35:31","slug":"316519-terremoto-in-provincia-di-cosenza-2","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/316519-terremoto-in-provincia-di-cosenza-2\/","title":{"rendered":"Terremoto in provincia di Cosenza"},"content":{"rendered":"<h4>L\u2019epicentro \u00e8 stato localizzato ad una profondit\u00e0 di nove chilometri<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>PARENTI (CS) \u2013 Un terremoto di magnitudo 2.3 si \u00e8 manifestato questa mattina alle 10:05. La scossa \u00e8 stata percepita in diverse zone della provincia di Cosenza, ma non si registrano danni a cose o persone. <strong>L\u2019epicentro \u00e8 stato localizzato a 4 chilometri da Parenti e ad 8 chilometri da Colosimi.<\/strong> L\u2019evento sismico, \u00e8 stato preceduto da un forte boato. Il sisma \u00e8 avvenuto ad una profondit\u00e0 di soli 9 chilometri ed \u00e8 stato verosimilmente avvertito anche dai residenti di Bianchi, Mangone, Rogliano, Cellara e Santo Stefano di Rogliano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019epicentro \u00e8 stato localizzato ad una profondit\u00e0 di nove chilometri<\/p>\n","protected":false},"author":43,"featured_media":117021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[543],"class_list":["post-117020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-terremoto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117020"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117021"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}