{"id":117117,"date":"2019-10-05T15:27:48","date_gmt":"2019-10-05T13:27:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/palazzo-bianchi-come-sede-del-comune-nel-programma-di-corigliano-rossano\/"},"modified":"2023-01-16T18:35:38","modified_gmt":"2023-01-16T17:35:38","slug":"316822-palazzo-bianchi-come-sede-del-comune-nel-programma-di-corigliano-rossano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/316822-palazzo-bianchi-come-sede-del-comune-nel-programma-di-corigliano-rossano\/","title":{"rendered":"Palazzo Bianchi come sede del comune, nel programma di Corigliano-Rossano"},"content":{"rendered":"<h4 dir=\"ltr\">Lo storico immobile, con il suo bell&#8217;affaccio sulla Piazza del Popolo, sar\u00e0 con ogni probabilit\u00e0 il nuovo Palazzo di Governo della Citt\u00e0 di Corigliano Rossano, sede del Sindaco e della giunta<\/h4>\n<p><!--more--><\/p>\n<p dir=\"ltr\">CORIGLIANO ROSSANO &#8211; In queste ore i consiglieri comunali stanno ricevendo le linee programmatiche dell&#8217;amministrazione Stasi. Un fitto allegato di impegni e proposte per la citt\u00e0 unica.<\/p>\n<p dir=\"ltr\"><strong>Tra gli spunti che hanno subito animato dibattiti la circostanza che la sede legale sar\u00e0 ubicata presso Palazzo Bianchi nel centro storico dell&#8217;area urbana coriglianese. Una scelta che premia un immobile di valore del nostro patrimonio culturale.\u00a0<\/strong><\/p>\n<p dir=\"ltr\">Lo storico immobile, con il suo bell&#8217;affaccio sulla Piazza del Popolo, stando al programma, dovrebbe essere\u00a0 il nuovo Palazzo di Governo della Citt\u00e0 di Corigliano Rossano, sede del Sindaco e della giunta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo storico immobile, con il suo bell&#8217;affaccio sulla Piazza del Popolo, sar\u00e0 con ogni probabilit\u00e0 il nuovo Palazzo di Governo della Citt\u00e0 di Corigliano Rossano, sede del Sindaco e della giunta<\/p>\n","protected":false},"author":51,"featured_media":117118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-117117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117117"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117118"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}