{"id":117150,"date":"2019-10-06T15:32:02","date_gmt":"2019-10-06T13:32:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-ad-avellino-un-pareggio-dorgoglio-che-fa-morale-savelloni-para-un-rigore\/"},"modified":"2023-01-16T18:35:41","modified_gmt":"2023-01-16T17:35:41","slug":"317024-rende-ad-avellino-un-pareggio-dorgoglio-che-fa-morale-savelloni-para-un-rigore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/317024-rende-ad-avellino-un-pareggio-dorgoglio-che-fa-morale-savelloni-para-un-rigore\/","title":{"rendered":"Rende, ad Avellino un pareggio d&#8217;orgoglio che fa morale. Savelloni para un rigore"},"content":{"rendered":"<h4>Grande prestazione dei biancorossi che giocano a viso aperto e strappano un prezioso pareggio sul difficile terreno del Partenio sfiorando anche il goal con Scimia nel primo tempo e la traversa di Ndiaye nella ripresa. Savelloni para un calcio di rigore a Di Paolantonio ed \u00e8 miracoloso su Charpentier<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\nAVELLINO &#8211; Se Tricarico aspettava una risposta dalla squadra proprio nel momento pi\u00f9 difficile, il tecnico pu\u00f2 ritenersi pi\u00f9 che soddisfatto <strong>dopo il pareggio strappato questo pomeriggio ad Avellino<\/strong>. Bene il punto ottenuto fuori casa, anche se non cambia di molto la classifica,<strong> benissimo soprattutto quello che la squadra ha messo in campo<\/strong>, lottando fino al 90&#8242; e <strong>giocando senza paura al cospetto in un avversario blasonato<\/strong> e che voleva tornare al successo dopo tre sconfitte consecutive. Ed invece i lupi irpini hanno trovano un osso durissimo nei biancorossi che sin dai primi minuti hanno messo in costante apprensione la retroguardia campana creando gioco e occasioni. Dopo la conclusione alta di Vitofrancesco, <strong>\u00e8 Scimia a sfiorare il vantaggio in due occasioni: <\/strong>al 10&#8242;, quando si fa respingere la conclusione da Tonti e al 20, con il destro dal limite che si perde di poco sul fondo. L&#8217;Avellino fatica a rendersi pericoloso e cos\u00ec il Rende ci riprova con la punizione di Murati respinta dal portiere. Solo intorno alla mezz&#8217;ora i padroni di casa iniziano a farsi pericolosi. <strong>Al 27&#8242; Morero raccoglie un angolo e di testa chiama Savelloni alla respinta mentre al 33&#8242; Alfageme sfiora l&#8217;incrocio dei pali\u00a0<\/strong><\/p>\n<p>Nel secondo tempo la gara \u00e8 ancora pi\u00f9 bella. L&#8217;Avellino, che non ha mai pareggiato in questo inizio di stagione, con l&#8217;inserimento di Charpentier attacca con pi\u00f9 convinzione alla ricerca del vantaggio che potrebbe arrivare al 50&#8242;. <strong>Contatto tra Murati e Rossetti che crolla in area. Per il signor Di Graci di Como \u00e8 calcio di rigore<\/strong> tra le proteste dei biancorossi per un contatto tutt&#8217;altro che evidente. <strong>Dal dischetto si presenta\u00a0Di Paolantonio che calcia alla destra di Savelloni che intuisce<\/strong> e vola a deviare la sfera. Il Rende si compatta ancora di pi\u00f9 e chiude tutti gli spazi agli irpini che allora ci provano da fuori, con la <strong>conclusione di Micovschi al 77&#8242; che esce di un nulla<\/strong>. Ma \u00e8 sul finale che arrivano due clamorose occasioni in fotocopia, una per parte. La prima al minuto 84&#8242; \u00e8 del Rende e la costruisce il neo entrato Ndiaye. Dopo una corsa di 20 metri <strong>il centrocampista senegalese lascia partire un bolide che Tonti smanaccia sulla traversa<\/strong> che poi risputa in campo la sfera. <strong>Capovolgimento di fronte e Savelloni, ancora lui, \u00e8 strepitoso a mettere la punta delle dita sul bolide di Charpentier<\/strong>. Anche in questo caso<strong> la palla deviata colpisce in pieno la traversa<\/strong> e torna in campo. Negli ultimi minuti l&#8217;Avellino si riversa nella met\u00e0 campo del Rende che per\u00f2 stringe i denti e porta a casa un punto importante per il morale.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><strong>US AVELLINO (4-3-3): <\/strong><strong>\u00a0<\/strong>Tonti, Celjak, Morero, Njie (45&#8242; Silvestri), Laezza, De Marco (45&#8242; Charpentier), Di Paolantonio, Rossetti (74&#8242; Karic), Micovschi, Alfageme, Parisi<br \/>\n<strong>Panchina: <\/strong>Abibi, Carbonelli, Palmisano, Karic, Zullo, Charpentier, Silvestri, Pizzella, Evangelista<br \/>\n<strong>Allenatore:<\/strong> Giovanni Ignoffo<\/p>\n<p><strong>RENDE CALCIO (4-3-3): <\/strong>Savelloni, Vitofrancesco, Germinio, Bruno, Scimia, Collocolo (79&#8242; Ndiaye), Giannotti, Murati (60&#8242; Libertazzi), Blaze, Rossini, Morselli (54&#8242; Origlio)<br \/>\n<strong>Panchina: <\/strong>Palermo, Borsellini, Ampollini, Cipolla, Origlio, Libertazzi, Ndiaye, Nossa, Vigolo, Soomets, Drkusic<br \/>\n<strong>Allenatore:<\/strong> Andrea Tricarico<\/p>\n<p><strong>Arbitro: <\/strong>Signor Alessandro\u00a0Di Graci di Como<br \/>\n<strong>Assistenti: <\/strong>Signori Massimiliano\u00a0Bonomo\u00a0di Milano e Fabrizio\u00a0Giorgi di Legnano<\/p>\n<p><strong>Ammoniti: <\/strong>De Marco (A), Laezza (A), Murati (R), Scimia (R), Parisi (A)<br \/>\n<strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli:<\/strong> 4-1<br \/>\n<strong>Recupero: <\/strong>0&#8242; p.t. &#8211; 3&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Pomeriggio nuvoloso e fresco ad Avellino con una temperatura attorno ai 20 gradi. Terreno del Partenio-Lombardi in perfette condizioni. Presenti poco pi\u00f9 3.500 spettatori con una decina di tifosi del Rende<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande prestazione dei biancorossi che giocano a viso aperto e strappano un prezioso pareggio sul difficile terreno del Partenio sfiorando anche il goal con Scimia nel primo tempo e la traversa di Ndiaye nella ripresa. Savelloni para un calcio di rigore a Di Paolantonio ed \u00e8 miracoloso su Charpentier<\/p>\n","protected":false},"author":24,"featured_media":117151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-117150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117150"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117151"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}