{"id":117209,"date":"2019-10-07T14:57:42","date_gmt":"2019-10-07T12:57:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/controlli-del-territorio-denunce-e-sequestri\/"},"modified":"2023-01-16T18:35:44","modified_gmt":"2023-01-16T17:35:44","slug":"317258-controlli-del-territorio-denunce-e-sequestri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/317258-controlli-del-territorio-denunce-e-sequestri\/","title":{"rendered":"Controlli del territorio, denunce e sequestri"},"content":{"rendered":"<h4>I Carabinieri hanno svolto un servizio straordinario di controllo del territorio, con particolare attenzione alle cittadine di Polistena, Cittanova, Cinquefrondi e Varapodio. <strong>Evitati furti e incendi<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>Taurianova (RC) &#8211; Nei giorni scorsi, i Carabinieri della Compagnia di Taurianova hanno svolto un servizio straordinario di controllo del territorio, con particolare attenzione alle cittadine di <strong>Polistena, Cittanova, Cinquefrondi e Varapodio<\/strong>, finalizzato alla prevenzione e repressione dei reati predatori, in materia di armi e al contrasto delle condotte di guida in stato di alterazione, che ha portato al deferimento all\u2019autorit\u00e0 giudiziaria di 9 persone, accusate di detenzione di materiale infiammabile, possesso ingiustificato di attrezzi di scasso, porto abusivo di armi e guida in stato di ebbrezza.<\/p>\n<p>In particolare, i carabinieri delle Stazioni di Cinquefrondi, Giffone, San Giorgio Morgeto e della Sezione Radiomobile della Compagnia, nel corso dei controlli stradali, in diverse circostanze, hanno <strong>denunciato<\/strong> alla Procura di Palmi <strong>tre giovani<\/strong>, un 20enne di Varapodio, un 22 enne di Cittanova e un 36enne di Cittanova, tutti fermati in evidente stato di alterazione e, sottoposti ai previsti accertamenti, sono risultati positivi agli accertamenti alcolemici, con un tasso nettamente superiore al consentito. I carabinieri hanno quindi immediatamente ritirato le patenti e i tre dovranno rispondere penalmente per il reato di guida in stato di ebbrezza, oltre che pagare sanzioni di diverse migliaia di euro.<\/p>\n<p>Simile esito hanno avuto i controlli su altri due giovani, un 24enne di San Giorgio Morgeto e un 27enne di Cittanova,\u00a0i quali sono stati fermati alla guida con un tasso alcolemico superiore al consentito ma inferiore a 0,8 g\/l &#8211; che comporta il reato penale &#8211; e quindi dovranno pagare una <strong>sanzione amministrativa di diverse centinaia di euro<\/strong> e rinunciare alla patente per circa 3 mesi.<\/p>\n<p>Nella rete dei controlli stradali \u00e8 finito anche un 40 enne di Cittanova fermato alla guida e trovato in possesso, senza giustificato motivo, di un <strong>coltello con apertura a scatto<\/strong>, della lunghezza di 18 cm di cui 10 di lama, e quindi deferito all\u2019 autorit\u00e0 giudiziaria per possesso ingiustificato di armi.<\/p>\n<p>Nel corso del servizio straordinario, particolarmente rilevanti sono stati due controlli ad altri 5 soggetti, 3 dei quali minorenni, che hanno verosimilmente evitato pi\u00f9 gravi reati. Infatti, i carabinieri della Stazione di Giffone hanno fermato di notte una autovettura tra Cinquefrondi e Anoia con a bordo tre giovani, M.S. 23enne, D.T. 17enne e R.C. 17 enne, tutti di Cinquefrondi, che, sottoposti a perquisizione, sono stati trovati in possesso, senza giustificato motivo, <strong>di chiavi alterate, grimaldelli nonch\u00e9 tre passamontagna e tre tute da meccanico blu<\/strong>, in parte gi\u00e0 indossate, il tutto posto sotto sequestro. I tre sono stati denunciati alle Procure della Repubblica di Palmi e Reggio Calabria e, seppure sono in corso ulteriori accertamenti, appare probabile che i giovani fossero in procinto di commettere qualche reato predatorio nel territorio.<\/p>\n<p>Stesso esito ha avuto il controllo a carico di altri due giovani, D.S. 24enne e S.N. 17enne entrambi di Amato di Taurianova, fermati dai militari dalla Sezione Radiomobile, e, sottoposti a perquisizione veicolare, trovati in possesso di una tanica contenente circa due litri di benzina, alcuni pezzi di diavolina, due passamontagna e un accendino. Le giustificazioni date dai giovani ai carabinieri sono apparse fin da subito poco credibili, e quindi il materiale \u00e8 stato sequestrato e sono stati denunciati alla Procure di Palmi e Reggio Calabria per <strong>possesso di materiale infiammabile e tentato danneggiamento<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-317282 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/Carabinieri-controllo2.jpg\" alt=\"\" width=\"900\" height=\"1125\" title=\"\"><\/p>\n<p>Nel corso del servizio straordinario sono state controllate quasi 100 persone e oltre 50 autovetture, elevando oltre 20 contravvenzioni al codice della strada.<\/p>\n<p>Tale servizio rientra nella pi\u00f9 ampia e costante azione di contrasto dei Carabinieri della Compagnia di Taurianova contro i reati predatori nel territorio e la <strong>prevenzione e repressione<\/strong> delle condotte di guida in stato di alterazione psicofisica dei giovani, soprattutto nel fine settimana, azione favorita da un costante aumento dei servizi di pattuglia e quindi dall&#8217;aumento della presenza per le strade, in tutto l\u2019arco della giornata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri hanno svolto un servizio straordinario di controllo del territorio, con particolare attenzione alle cittadine di Polistena, Cittanova, Cinquefrondi e Varapodio. Evitati furti e incendi<\/p>\n","protected":false},"author":54,"featured_media":117210,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-117209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117209"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117210"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}