{"id":117338,"date":"2019-10-09T12:15:43","date_gmt":"2019-10-09T10:15:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/emergenza-rifiuti-comuni-non-pagano-calabra-maceri-chiude-i-cancelli\/"},"modified":"2023-01-16T18:35:53","modified_gmt":"2023-01-16T17:35:53","slug":"317796-emergenza-rifiuti-comuni-non-pagano-calabra-maceri-chiude-i-cancelli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/317796-emergenza-rifiuti-comuni-non-pagano-calabra-maceri-chiude-i-cancelli\/","title":{"rendered":"Emergenza rifiuti: Comuni non pagano, Calabra Maceri chiude i cancelli"},"content":{"rendered":"<h4>La Regione Calabria non copre pi\u00f9 le spese dei municipi, spazzatura in &#8216;strada&#8217; a Cosenza<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Torna l&#8217;incubo dei rifiuti in strada. I camion colmi di spazzatura non potranno conferire nell&#8217;impianto di Calabria Maceri a Rende. La famiglia Pellegrino che gestisce il sito in cui viene trattato il residuo della raccolta differenziata prima di finire in discarica, ha chiuso i cancelli ai Comuni morosi. <strong>Tra questi il pi\u00f9 popoloso \u00e8 Cosenza.<\/strong> La Regione Calabria, per ora, non ha intenzione di coprire gli otto milioni di euro di debito che complessivamente hanno maturato i 150 Comuni della provincia di Cosenza, mentre si attende l&#8217;incontro con i gestori degli impianti per sbloccare la situazione. Intanto l&#8217;assessore regionale all&#8217;Ambiente Antonella Rizzo, coadiuvata dalla dirigente generale del Dipartimento Orsola Reillo, ieri ha incontrato i rappresentanti dell&#8217;ufficio di presidenza della Comunit\u00e0 d&#8217;Ambito rifiuti di Cosenza. L&#8217;incontro, che si \u00e8 svolto nella sede dell&#8217;assessorato a Catanzaro, \u00e8 stato chiesto dal sindaco di Rende Marcello Manna, in qualit\u00e0 di presidente della Comunit\u00e0 d&#8217;Ambito di Cosenza, a seguito della nota del 7 ottobre scorso con cui la Regione ha comunicato la decadenza della delega conferita dalla Comunit\u00e0 d&#8217;Ambito all&#8217;ente regionale per la gestione dei contratti relativi al servizio di trattamento dei rifiuti urbani.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;assessore Rizzo, \u00e8 scritto in una nota dell&#8217;ufficio stampa della Giunta regionale, dopo aver ascoltato le istanze dell&#8217;Ato, ha ripercorso la nota vicenda che ha portato alla decadenza della delega. &#8220;Dal primo gennaio 2019 &#8211; ha ricordato &#8211; dopo vari differimenti disposti dalla normativa regionale, i Comuni sono subentrati nella piena titolarit\u00e0 dei contratti di gestione degli impianti e la Regione, in un spirito di collaborazione tra enti e su espressa richiesta del presidente dell&#8217;ANCI, ha previsto, con la legge regionale n. 5\/2019, la possibilit\u00e0 di delegare alla Regione la funzione amministrativa relativa alla gestione di tali contratti, per continuare ad<strong> accompagnare e supportare i Comuni nel processo di subentro della competenza che \u00e8 loro assegnata dalla legge dello Stato.<\/strong> <strong>Tutte le 5 cinque Comunit\u00e0 d&#8217;Ambito hanno chiesto e ottenuto questo soccorso, per cui la Regione ha anticipato il costo del servizio per i primi sei mesi dell&#8217;anno in corso e ha svolto le funzioni delegate<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;assessore all&#8217;Ambiente, prosegue la nota, &#8220;ha poi rimarcato il fatto che i Comuni si erano impegnati a trasferire le risorse alla Regione, per cui la stessa legge, per come concordato con le Amministrazioni comunali, prevede la decadenza della delega qualora entro il primo semestre ciascuna Comunit\u00e0 d&#8217;Ambito non abbia trasferito almeno l&#8217;80% dei costi del servizio&#8221;. &#8220;Sulla scorta del mancato incasso delle somme necessarie per pagare i gestori degli impianti &#8211; ha quindi evidenziato la Rizzo &#8211; il 5 settembre scorso, la Regione ha inviato a tutte le Comunit\u00e0 d&#8217;Ambito e a tutti i Comuni il preavviso di decadenza e la diffida ad adempiere, poich\u00e9 la somma trasferita non consentiva di raggiungere la percentuale stabilita dalla norma. Pertanto, <strong>a seguito della diffida, i Comuni delle Comunit\u00e0 d&#8217;Ambito di Catanzaro, Vibo Valentia e Crotone hanno ottemperato e si sono messi in regola, per cui la delega \u00e8 fatta salva, invece per le Comunit\u00e0 d&#8217;Ambito di Cosenza e di Reggio Calabria la Regione \u00e8 stata costretta a comunicare la decadenza della delega<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Manna, il sindaco di Corigliano-Rossano Flavio Stasi, rappresentante dell&#8217;Aro Sibaritide, ed i sindaci di Rogliano Giovanni Altomare e di Carpanzano Giuseppe Vigliaturo, rappresentanti dell&#8217;Aro Presila, \u00e8 scritto nella nota, &#8220;hanno espresso una<strong> forte preoccupazione per il venir meno della delega e per la comunicazione della societ\u00e0 Calabra Maceri, gestore dell&#8217;impianto di Rende, che, sulla scorta dell&#8217;intervenuta inefficacia della delega, ritiene risolti i contratti<\/strong> con le amministrazioni locali inadempienti e intende sospendere il servizio per tutti in attesa dell&#8217;elenco dei Comuni morosi. L&#8217;assessore Rizzo ha condiviso la preoccupazione dei rappresentati dell&#8217;Ato Cosenza ma ha ribadito che la decadenza della delega \u00e8 prevista dalla norma regionale e la Regione \u00e8 nell&#8217;impossibilit\u00e0 di anticipare ulteriori somme&#8221;. &#8220;Nonostante i solleciti e l&#8217;ultima diffida di settembre &#8211; ha fatto presente l&#8217;assessore &#8211; a fronte di un incasso atteso di 9 milioni di euro, sono stati versati dall&#8217;Ato Cosenza meno di un milione e mezzo di euro. La legge che ha stabilito la delega \u00e8 frutto di una concertazione con le Comunit\u00e0 d&#8217;Ambito e con l&#8217;Anci e che la Regione \u00e8 sempre venuta incontro alle necessit\u00e0 dei Comuni e li ha supportati economicamente in questi anni. Per consentire di trasferire i costi previsti per l&#8217;anno in corso abbiamo anche offerto l&#8217;opportunit\u00e0 di rateizzare i debiti del 2017 e del 2018.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Con rammarico &#8211; ha concluso Rizzo &#8211; devo dire che purtroppo ora la Comunit\u00e0 d&#8217;Ambito deve farsi carico della gestione dei contratti&#8221;. Manna, prosegue la nota, &#8220;dopo aver preso atto che la Regione ha fatto gi\u00e0 molto e non potr\u00e0 fare altro, si \u00e8 detto seriamente preoccupato per la concreta possibilit\u00e0 che i rifiuti rimangano per strada e ha comunque affermato che <strong>inviter\u00e0 tutti i sindaci dei Comuni morosi ad una assunzione di responsabilit\u00e0, facendosi personalmente carico dell&#8217;impegno di contattarli per indurli a pagare entro la fine della settimana<\/strong>&#8220;. &#8220;Al termine &#8211; conclude la nota &#8211; si \u00e8 deciso che la questione della futura gestione a carico dell&#8217;Ato Cosenza sar\u00e0 anche affrontata nella riunione della Comunit\u00e0 d&#8217;Ambito indetta per luned\u00ec prossimo e, nel frattempo, Manna ha chiesto alla Regione di convocare per gioved\u00ec prossimo una riunione con i gestori per consentire almeno ai Comuni virtuosi di conferire. Infine ha sottolineato che le oggettive difficolt\u00e0 economiche di molti Comuni, in dissesto o in predissesto, comporterebbero la necessit\u00e0 di un qualche intervento di sostegno da parte del Governo centrale&#8221;.<\/p>\n<p>https:\/\/quicosenza.it\/news\/le-notizie-dell-area-urbana-di-cosenza\/cosenza\/312089-discariche-da-riaprire-per-evitare-che-la-calabria-affondi-nei-rifiuti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Calabria non copre pi\u00f9 le spese dei municipi, spazzatura in &#8216;strada&#8217; a Cosenza<\/p>\n","protected":false},"author":43,"featured_media":117339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-117338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117338"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117339"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}