{"id":117398,"date":"2019-10-10T11:30:08","date_gmt":"2019-10-10T09:30:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arrestato-per-spaccio-perde-il-reddito-di-cittadinanza\/"},"modified":"2023-01-16T18:35:58","modified_gmt":"2023-01-16T17:35:58","slug":"317969-arrestato-per-spaccio-perde-il-reddito-di-cittadinanza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/317969-arrestato-per-spaccio-perde-il-reddito-di-cittadinanza\/","title":{"rendered":"Arrestato per droga, perde il reddito di cittadinanza"},"content":{"rendered":"<h4>Il suo nome era venuto fuori in alcune inchieste giudiziarie riguardanti la criminalit\u00e0 organizzata ma ora \u00e8 finito in manette per possesso di stupefacenti<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; Beneficiava del reddito di cittadinanza che ora, dopo l&#8217;arresto perch\u00e8 trovato in possesso di droga, gli \u00e8 stato tolto. Si tratta di un <strong>47enne di Lamezia Terme<\/strong>, residente nel quartiere Capizzaglie che \u00e8 stato arrestato dalla Guardia di Finanza dopo essere stato fermato e perquisito.<\/p>\n<p>Addosso l&#8217;uomo, aveva 10 grammi di cocaina e anche da una successiva perquisizione domiciliare, eseguita con l\u2019ausilio delle unit\u00e0 cinofile, \u00e8 stato scoperto un bilancino di precisione elettronico e alcuni grammi di marijuana. La procura della Repubblica di Lamezia Terme ha richiesto il <strong>giudizio direttissimo<\/strong>, durante il quale il locale tribunale, nel convalidare l&#8217;arresto, ha disposto la misura dell\u2019obbligo di dimora nel comune di residenza.<br \/>\n<strong><br \/>\nMa non solo, <\/strong>perch\u00e8 le fiamme gialle hanno accertato che il 47enne risultava percettore del reddito di cittadinanza, per cui il giudice, su richiesta del Pm, ha ordinato <strong>l\u2019immediata sospensione del beneficio<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il suo nome era venuto fuori in alcune inchieste giudiziarie riguardanti la criminalit\u00e0 organizzata ma ora \u00e8 finito in manette per possesso di stupefacenti<\/p>\n","protected":false},"author":42,"featured_media":117399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-117398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117398"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117399"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}