{"id":117761,"date":"2019-10-16T17:06:54","date_gmt":"2019-10-16T15:06:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/audio-addio-agli-sprechi-alimentari-con-unapp-da-cosenza-qualcuno-si-muove\/"},"modified":"2023-01-16T18:36:23","modified_gmt":"2023-01-16T17:36:23","slug":"319107-audio-addio-agli-sprechi-alimentari-con-unapp-da-cosenza-qualcuno-si-muove","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/319107-audio-addio-agli-sprechi-alimentari-con-unapp-da-cosenza-qualcuno-si-muove\/","title":{"rendered":"(AUDIO) Addio agli sprechi alimentari con un&#8217;app, da Cosenza qualcuno si muove"},"content":{"rendered":"<h4>Nella giornata mondiale contro lo spreco alimentare, la Coldiretti Calabria commenta il rapporto pubblicato dalla FAO sugli sprechi. Uno spiraglio di luce arriva anche dal Web e dal mondo delle App per ridurre lo spreco. Anche a Cosenza esiste una realt\u00e0 che ha deciso di mettersi in prima linea per contrastare il decantato malcostume.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; In Italia ci sono 2,7 milioni di affamati costretti nel 2018 a chiedere aiuto per mangiare, di cui oltre il 55% concentrati nelle regioni del Mezzogiorno. E&#8217; quanto emerge dalla prima mappa della fame in Italia elaborata dalla Coldiretti in occasione della <strong>Giornata mondiale dell&#8217;alimentazione promossa dalla Fao<\/strong>, sulla base dei dati sugli aiuti alimentari distribuiti con i fondi Fead attraverso dall&#8217;Agenzia per le Erogazioni in Agricoltura (Agea). <strong>Il problema alimentare non riguarda solo il terzo mondo ma anche i Paesi pi\u00f9 industrializzati<\/strong> dove le differenze sociali generano sacche di povert\u00e0 ed emarginazione. Le maggiori criticit\u00e0 in Italia, precisa la Coldiretti, si registrano in Campania con 554 mila assistiti, in Sicilia con 378 mila e in Calabria con 300 mila, ma anche in Lombardia con quasi 229 mila persone in difficolt\u00e0 alimentare. Tra le categorie pi\u00f9 deboli degli indigenti a livello nazionale si contano 453 mila bambini di et\u00e0 inferiore ai 15 anni, quasi 197 mila anziani sopra i 65 anni e 103 mila senza fissa dimora.<\/p>\n<p>La stragrande maggioranza di chi \u00e8 stato costretto a ricorrere agli aiuti alimentari lo ha fatto attraverso la consegna di pacchi alimentari che rispondono maggiormente alle aspettative dei nuovi poveri (pensionati, disoccupati, famiglie con bambini) che, per vergogna, prediligono questa forma di sostegno piuttosto che il consumo di pasti gratuiti nelle strutture caritatevoli. Infatti sono appena 113 mila quelli che si sono serviti delle mense dei poveri a fronte di 2,36 milioni che invece hanno accettato l&#8217;aiuto delle confezioni di prodotti. Ma ci sono anche 103 mila persone supportate dalle unit\u00e0 di strada, gruppi formati da volontari che vanno ad aiutare le persone pi\u00f9 povere incontrandole direttamente nei luoghi dove trovano ricovero.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-319238 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/applicazione-cibo.jpg\" alt=\"\" width=\"583\" height=\"583\" title=\"\"><\/p>\n<h2>La gestione delle risorse alimentari<\/h2>\n<p>Il mood giusto \u00e8 sempre quello che ci vuole per affrontare ogni situazione. E quello scelto quest&#8217;anno dalla FAO (Food and Agriculture Organization of the United Nations)\u00a0 \u00e8 quello pi\u00f9 diretto, pi\u00f9 esplicito:\u00a0 <strong>\u201cle nostre azioni sono il nostro futuro&#8221;<\/strong>. La FAO, nella giornata mondiale contro lo spreco alimentare, vuol richiamare l&#8217;attenzione sull&#8217;immane impatto negativo che tale spreco ha non solo sul piano etico ma anche sul piano economico, energetico e quello sullo smaltimento dei rifiuti, altra nota dolente che investe la maggior parte delle aree geografiche in via di sviluppo.<\/p>\n<p>Anche la Coldiretti Calabria evidenzia che\u00a0nella nostra regione, nell&#8217;ultimo anno, <strong>sono finiti nei bidoni alimenti e bevande per un valore di circa 125 milioni di euro\u00a0derivanti da sprechi domestici e della ristorazione (la gran parte), distribuzione commerciale, agricoltura e trasformazione.<\/strong>\u00a0Quasi un terzo del cibo prodotto nel mondo viene sprecato per un totale di 1,3 miliardi di tonnellate\u00a0che sarebbero ampiamente sufficienti a sfamare la popolazione che soffre di fame cronica.<\/p>\n<p>Un problema annoso che si sta cercando di contrastare con campagne di sensibilizzazione sulla gestione delle risorse alimentari, da parte degli enti e associazioni preposte, a partire dall&#8217;educazione di una corretta alimentazione. &#8220;<strong>Un\u2019alimentazione sana per un mondo #FameZero<\/strong>\u201c. Negli ultimi anni si \u00e8 registrata una maggiore sensibilit\u00e0 riguardo al tema sugli sprechi alimentari adottando strategie volte anche al riutilizzo degli avanzi: dalla spesa a km zero alla doggy bag (letteralmente \u201cvaschetta degli avanzi per il cane\u201d ma in realt\u00e0 \u00e8 un sacchetto o cartone in cui si conservano gli\u00a0avanzi di cibo del ristorante per mangiarlo a casa).<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-319234 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/72465140_660715934335577_7426089353471852544_n-280x280.jpg\" alt=\"\" width=\"280\" height=\"280\" title=\"\"><\/p>\n<h3>Combattere gli sprechi? A Cosenza qualcuno si muove<\/h3>\n<p>In Italia, prevalentemente nord e centro, sono tante le realt\u00e0 commerciali di somministrazione alimentare iscritte ad una di queste App unendo l&#8217;utile al dilettevole. Ovvero, quello di dar via ad un costo, seppur minore, l&#8217;invenduto della giornata e, quindi, non aver sprecato le materie prime utilizzate per la produzione del prodotto finale. Dall&#8217;altro lato c&#8217;\u00e8 il risparmio del consumatore finale che pu\u00f2 acquistare ad un costo decisamente pi\u00f9 basso del cibo di qualit\u00e0.<\/p>\n<p>Anche a Cosenza esiste una realt\u00e0 che ha deciso di mettersi in prima linea per contrastare il decantato malcostume. In Piazza 11 settembre esiste una pizzeria iscritta ad un&#8217;App che consente di ricevere una Magic Box contenente una parte dell&#8217;invenduto del giorno ad terzo del prezzo di vendita. Tra l&#8217;altro \u00e8 , ahinoi, <strong>l&#8217;unica realt\u00e0 commerciale cosentina ad aver intrapreso questa strada.<\/strong> L&#8217;App in questione \u00e8 <strong>To Good To Go<\/strong> e la pizzeria in questione \u00e8 <strong>1Netto<\/strong>. L&#8217;App \u00e8 veloce ed intuitiva ed \u00e8 veramente facile ordinare la Magic box. Basta avviare l&#8217;applicazione ed in solo tre passi la Magic box \u00e8 ordinata e resta soltanto passare a ritirarla all&#8217;orario indicato. Ovviamente in orario prossimo alla chiusura.<\/p>\n<p>Angelica, dipendente simpatica ed intraprendente della pizzeria, ai microfoni di RLB spiega il doppio vantaggio, sia per gli acquirenti che per i ristoratori, ma soprattutto l&#8217;importanza di non sprecare o buttare il cibo prodotto.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/696796994&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2>Le App giuste per evitare lo spreco<\/h2>\n<p>Uno spiraglio di luce sulla lotta allo spreco alimentare arriva anche via web dove sono state introdotte ben 10 applicazioni da scaricare sui propri cellulari:<\/p>\n<p class=\"storie-title\"><strong>To good to go<\/strong>: se sprecato, il cibo ha un effetto dannoso sull&#8217;ambiente, si legge sul sito di To good to go, l&#8217;app appena arrivata a Milano. Infatti gli alimenti sono responsabili dell&#8217;8% delle emissioni globali di gas serra che tutti sappiamo essere dannose per il pianeta. Per questo l&#8217;applicazione segnala ogni giorno le &#8220;magic box&#8221; disponibili in citt\u00e0. Sono delle scatole che contengono cibo fresco proveniente da locali che non lo potrebbero pi\u00f9 utilizzare il giorno seguente e per non sprecarlo lo vendono a un prezzo modico.<\/p>\n<div class=\"container-body-article clearfix paywall-content\">\n<div class=\"chapter clearfix\">\n<p class=\"storie-title\"><strong>Avanzi popolo 2.0<\/strong>: sulla community online di Avanzi Popolo 2.0 ci si scambia cibo vicino alla scadenza, quando l&#8217;utente si accorge che non sar\u00e0 in grado di consumarlo. Si scatta la foto al cibo da condividere, si posta sul sito e si attende la risposta di qualcuno interessato ad averlo. Gli utenti possono essere sia privati che commercianti attenti a non sprecare cibo.<\/p>\n<\/div>\n<\/div>\n<div class=\"container-body-article clearfix paywall-content\">\n<div class=\"chapter clearfix\">\n<p class=\"storie-title\"><strong>Bring the food<\/strong>: l&#8217;app\u00a0e il sito omonimo, nati e sviluppati a Trento, servono per donare il cibo che non consumiamo ad enti caritativi. Come funziona: si postano gli alimenti che vogliamo dare in beneficenza e se c&#8217;\u00e8 qualche associazione o gruppo nelle vicinanze che \u00e8 interessato, verremo contattati per effettuare la consegna.<\/p>\n<div class=\"container-body-article clearfix paywall-content\">\n<div class=\"chapter clearfix\">\n<p class=\"storie-title\"><strong>My Foody<\/strong>: raccoglie le segnalazioni dei supermercati che propongono a prezzi scontati prodotti vicino alla data di scadenza o con difetti di nella confezione. Sono tutti generi alimentari perfettamente commestibili, che rischierebbero di finire in discarica a fine giornata e invece grazie all&#8217;app possono arrivare in tavola.<\/p>\n<div class=\"container-body-article clearfix paywall-content\">\n<div class=\"chapter clearfix\">\n<p class=\"chapter-paragraph\"><strong>Ubo (Una Buona Occasione)<\/strong>: La buona occasione di cui parla Ubo\u00a0\u00e8 l&#8217;antispreco. Nell&#8217;app, infatti, riceviamo quotidianamente notizie, suggerimenti e memo per non far scadere gli alimenti che abbiamo a casa. Basta inserire la spesa che abbiamo fatto, con le relative date di scadenza, e avremo sempre sotto controllo cosa mangiare.<\/p>\n<p class=\"storie-title\"><strong>Last minute sotto casa<\/strong>: L&#8217;app<span style=\"font-size: 16px;\">, disponibile sia per iOS che per Android, funziona sia per privati che per commercianti. I primi possono sapere ogni giorno ci\u00f2 che i secondi mettono in vendita a prezzo scontato per non sprecare. I negozianti hanno cos\u00ec un modo per far conoscere il loro lato &#8220;green&#8221; e per farsi pubblicit\u00e0 nel quartiere.\u00a0<\/span><\/p>\n<p class=\"storie-title\"><strong>Eco dal frigo<\/strong>: Cosa abbiamo nel frigorifero? Con l&#8217;app<span style=\"font-size: 16px;\">\u00a0realizzata da Missione Bambini contro lo spreco alimentare abbiamo a disposizione delle ricette facili e veloci da eseguire con quello che ci \u00e8 rimasto. In modo da non sprecare nulla.\u00a0<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"storie-title\"><strong>Bring! Lista della spesa<\/strong>: Un altro modo per cercare di non sprecare cibo \u00e8 fare una spesa intelligente. Per questo c&#8217;\u00e8 Bring! Lista della spesa<span style=\"font-size: 16px;\">. In un&#8217;app si pianificare e gestisce la lista con tutta la famiglia, cos\u00ec ognuno sa cosa c&#8217;\u00e8 a casa o cosa comprare, senza creare eccedenze.<\/span><\/p>\n<p class=\"storie-title\"><strong>L&#8217;orto in tasca<\/strong>: L&#8217;app<span style=\"font-size: 16px;\">\u00a0consente di sapere quali sono i produttori locali di frutta e verdura che si trovano vicino a noi. In questo modo si possono comprare cibi freschi, genuini, creando anche gruppi di acquisto solidale per risparmiare.\u00a0<\/span><\/p>\n<p class=\"storie-title\"><strong>Spesa in tempo<\/strong>: Per non sprecare le eccedenze alimentari dei negozi, c&#8217;\u00e8 Spesa in tempo<span style=\"font-size: 16px;\">. Gli esercenti inseriscono nell&#8217;app i cibi vicini alla scadenza, a prezzo scontato, e cos\u00ec chi vuole sa dove trovare le offerte.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata mondiale contro lo spreco alimentare, la Coldiretti Calabria commenta il rapporto pubblicato dalla FAO sugli sprechi. Uno spiraglio di luce arriva anche dal Web e dal mondo delle App per ridurre lo spreco. Anche a Cosenza esiste una realt\u00e0 che ha deciso di mettersi in prima linea per contrastare il decantato malcostume.<\/p>\n","protected":false},"author":52,"featured_media":117762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[19],"class_list":["post-117761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117761"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117762"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}