{"id":117828,"date":"2019-10-18T05:00:20","date_gmt":"2019-10-18T03:00:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-fallimento-e-rivoluzione-oggi-la-presentazione-del-libro-a-cosenza\/"},"modified":"2023-01-16T18:36:28","modified_gmt":"2023-01-16T17:36:28","slug":"319283-il-fallimento-e-rivoluzione-oggi-la-presentazione-del-libro-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/319283-il-fallimento-e-rivoluzione-oggi-la-presentazione-del-libro-a-cosenza\/","title":{"rendered":"&#8220;Il fallimento \u00e8 rivoluzione&#8221;, la presentazione del libro a Cosenza"},"content":{"rendered":"<h4>La vita \u00e8 complessa e l&#8217;errore \u00e8 naturale: &#8220;Sbagliando, s&#8217;impara&#8221;, quante volte ce l&#8217;hanno ripetuto da bambini? \u00c8 cos\u00ec che abbiamo mosso i primi passi, che abbiamo iniziato a parlare e ad andare in bicicletta.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Oggi alle 18, al Gran Caff\u00e8 Renzelli su corso Telesio a Cosenza \u00e8 in programma la presentazione del libro di Francesca Corrado intitolato &#8220;<strong>Il<\/strong> <strong>Fallimento \u00e8 rivoluzione &#8211; perch\u00e8 sbagliare fa bene<\/strong>&#8221; come \u00e8 possibile considerare ogni errore non come un vicolo cieco o un fallimento con ansia e frustrazione. E se il vero errore fosse pensare alla nostra vita come a un percorso piatto, senza ostacoli? Se riuscissimo ad accettare che gli errori non sono deviazioni, ma parti integranti del nostro percorso?<strong> Se cambiassimo punto di vista e vedessimo che quello che ci ha fatto tanto male ieri, oggi ci ha portato su una buona strada?<\/strong><\/p>\n<p><strong>Milly Tucci<\/strong>, innovatrice e azionista di Ingreen Manager Gptw, che moderer\u00e0 la presentazione, ha illustrato ai microfoni di <strong>Rlb<\/strong> l&#8217;importanza del contenuto e del messaggio che il volume della Corrado intende lanciare a tutti, dagli imprenditori ai cittadini<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/697660636&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p>Proprio l&#8217;autrice, che sar\u00e0 presente, <strong>Francesca Corrado<\/strong> ha vissuto in <strong>prima persona<\/strong> una serie di cadute che, a suo tempo, ha considerato dei fallimenti. Ma \u00e8 riuscita a rialzarsi, a rivalutare le sue esperienze e a sfruttare le novit\u00e0 nella sua vita, traendone vantaggi e imparando lezioni importanti. E, con un team d&#8217;eccezione fatto di psicologi e neuroscienziati, ha fondato la prima Scuola di Fallimento, unica nel suo genere in tutta Europa. Con i suoi corsi sta aiutando studenti, lavoratori, manager, ma anche cuori infranti e persone che si sentono schiacciate dal peso di una sconfitta.<\/p>\n<p>In questo libro riporta le sue lezioni per insegnarci che occorre accettare l&#8217;errore come elemento essenziale per la scoperta di s\u00e9, dei propri limiti e dei propri talenti. In un percorso semplice e pratico, scopriamo come accettare gli sbagli, sdrammatizzarli e usarli a nostro favore. Un metodo dall&#8217;impatto immediato, in grado di aiutarci a <strong>cambiare mentalit\u00e0 e ad accogliere l&#8217;errore.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-319286 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/IMG-20191012-WA0035.jpg\" alt=\"\" width=\"540\" height=\"828\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vita \u00e8 complessa e l&#8217;errore \u00e8 naturale: &#8220;Sbagliando, s&#8217;impara&#8221;, quante volte ce l&#8217;hanno ripetuto da bambini? \u00c8 cos\u00ec che abbiamo mosso i primi passi, che abbiamo iniziato a parlare e ad andare in bicicletta.<\/p>\n","protected":false},"author":42,"featured_media":117829,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25],"tags":[],"class_list":["post-117828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=117828"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/117828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/117829"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=117828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=117828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=117828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}