{"id":118306,"date":"2019-10-24T18:19:43","date_gmt":"2019-10-24T16:19:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rlb-in-diretta-per-la-seconda-giornata-della-festa-del-cioccolato\/"},"modified":"2023-01-16T18:37:02","modified_gmt":"2023-01-16T17:37:02","slug":"320824-rlb-in-diretta-per-la-seconda-giornata-della-festa-del-cioccolato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/320824-rlb-in-diretta-per-la-seconda-giornata-della-festa-del-cioccolato\/","title":{"rendered":"RLB in diretta per la seconda giornata della Festa del Cioccolato"},"content":{"rendered":"<h4>Intrattenimento live con la crew di RLB in diretta tra gli stand della XVII edizione della Festa del Cioccolato. La donna e le sue mille sfaccettature \u00e8 il file rouge del contest artistico per la giornata di venerdi 25 ottobre<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Continua la carrellata di artisti nell&#8217;area eventi allestita presso piazza Kennedy che, anche quest&#8217;oggi, RLB Radioattiva proporr\u00e0 a tutti i visitatori della XVII edizione della Festa del Cioccolato. Dopo il successo della serata inaugurale, ancora una volta, gli artisti calabresi daranno forma e valore alla propria arte. Intrattenimento musicale e non solo! <strong>Il mood del giorno sar\u00e0 la donna e il suo fantastico mondo<\/strong>. Una realt\u00e0 composta da diversi tasselli: lavoro, casa e famiglia. Ma anche moda, eleganze e una innata femminilit\u00e0. Sensuale ed avvolgente nel sue semplice essere donna, mamma, figlia. Del resto, cosa sarebbe il mondo senza le donne?<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320888 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/rlb-festa-del-cioccolato-2019-post-programma2_venerdi25-2.jpg\" alt=\"\" width=\"532\" height=\"532\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff0000;\"><strong>Il programma di venerdi 25 ottobre<\/strong><\/span><\/h4>\n<p><strong>The Tribe Music Band &#8211; Romilda Cozzolino<\/strong><\/p>\n<p>Gruppo eterogeneo composto da quattro giovani musicisti locali, che vogliono fare del pop un vero e proprio marchio di fabbrica. La band propone un sound diverso, a loro giudizio differente &#8220;<strong>perch\u00e9 cantano ci\u00f2 che a loro veramente piace e non quello che il mercato impone<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320902 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/the-tribe-1.jpg\" alt=\"\" width=\"533\" height=\"540\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h4>In Punta di Piedi di Giusy Massarini<\/h4>\n<div class=\"_5aj7 _3-8j\">\n<div class=\"_4bl9\">\n<div class=\"_3-8w\">\n<div id=\"id_5db1b25e52aff4813301582\" class=\"text_exposed_root text_exposed\">\n<p>Prima classificata al concorso coreografico nazionale di danza, dopo 21 anni di studio, disciplina e grinta, Giusy Massarini non si \u00e8 mai pentita di aver scelto la danza a discapito della professione di avvocato e non ha mai perso l&#8217;entusiasmo e la voglia di continuare a insegnare. Ogni giorno attende con impazienza l&#8217;inizio della prossima lezione. Un sogno quello della maestra Massarini, che si \u00e8 concretizzato grazie all&#8217;aiuto e al sostegno di tutta la famiglia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320835 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/in-punta-di-piedi.jpg\" alt=\"\" width=\"536\" height=\"357\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h4>For Lady il fascino delle donne over 33<\/h4>\n<p>La bellezza &#8220;matura&#8221; di una donna senza costrizioni di inutili e sterili stereotipi. L&#8217;essenza della femminilit\u00e0 racchiusa in un mondo senza misure e canoni estetici dettati dalle pagine patinate delle riviste di moda. Donne dotate di intelligenza, eleganza e personalit\u00e0 che mettono in mostra le loro esperienze di vita over 30, rendendole speciali. Ognuna a suo modo racconta il proprio vissuto attraverso lo sguardo, le movenze e il modo di indossare un abito, che sia da giorno o da sera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320855 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/for-lady-1.jpg\" alt=\"\" width=\"532\" height=\"416\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h4>Hale Bopp Danza di Erika Spaltro<\/h4>\n<p>Dal 2002 la scuola di danza Halebopp Danza si prende cura degli allievi trasformandoli in veri e propri protagonisti del palcoscenico. Insegnanti con competenze specifiche si prendono cura dell&#8217;allievo in un&#8217;azione congiunta con le famiglie, agendo all&#8217;unisono sullo sviluppo affettivo, sociale ed educativo. Scenografie e costumi curatissimi fanno da cornice alle coreografie elaborate dallo staff della scuola di danza che spaziano in diversi generi: break dance, hip hpo e modern jazz.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320850 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/hale-bopp.jpg\" alt=\"\" width=\"534\" height=\"534\" title=\"\"><\/p>\n<h4><\/h4>\n<h4>Flash Mob &#8220;Donne Vanitose&#8221; a cura di Monica Campanella<\/h4>\n<p>Flash mob\u00a0(dall&#8217;inglese\u00a0<i>flash<\/i>,<strong> lampo<\/strong>, inteso come evento rapido, improvviso, e\u00a0<i>mob<\/i>,<strong> folla<\/strong>) \u00e8 un termine coniato nel 2003 per indicare un assembramento improvviso di un gruppo di persone in uno spazio pubblico, che si dissolve nel giro di poco tempo, con la finalit\u00e0 comune di mettere in pratica un&#8217;azione insolita. Il raduno viene generalmente organizzato attraverso i social. Domani, donne di tutte le et\u00e0, mamme, ragazze, nonne danzeranno insieme per esprimere la loro femminilit\u00e0 e la loro autonomia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320858 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/flash-mob.jpg\" alt=\"\" width=\"520\" height=\"305\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h4>Fil Mama<\/h4>\n<p>Semifinalista The Voice of Italy 2018 e vincitrice del Premio Mia Martini nel 2018, Elisabetta Eneh &#8211; in arte Fil Mama &#8211; \u00e8 un artista che rispecchia il duplice lato della musica, da un lato una certa tenerezza, dall\u2019altro lato potente grinta, \u00e8 eleganza, moda, fragile ma senza paura. Trasporta il suo pubblico con la sua presenza indescrivibile, unica, e la sua voce energica e ruvida, ci lascia stupiti e senza parole. Riflette nei generi soul, Gospel gli elementi dell&#8217;anima. Ancora una volta si pu\u00f2 sperimentare nei numerosi concerti sold-out, dove il pubblico ha applaudito con entusiasmo ogni canzone: Fil Mama \u00e8 grande, elegante, all<span class=\"text_exposed_show\">a moda, fragile ma senza paura. Trasporta il suo pubblico con la sua presenza indescrivibile, unica, con la sua voce energica e ruvida lascia con stupore e senza parole.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320873 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/fil-mama.jpg\" alt=\"\" width=\"532\" height=\"399\" title=\"\"><\/p>\n<h4><\/h4>\n<h4>Contest Moda firmato Manuela Capalbo<\/h4>\n<p>Gli abiti possono servire a nascondere lati della personalit\u00e0 che non si vogliono far conoscere o, viceversa, a esaltarli. Lo testimonia il vecchio adagio &#8220;l&#8217;abito non fa il monaco&#8221;. Nel caso specifico, con gli abiti di Manuela Capalbo si esalta la femminilit\u00e0 in tutto il suo splendore. Abiti eleganti, avvolgenti e intriganti. Realizzati appositamente per mettere in risalto il lato sensuale del corpo femminile e il carattere di chi lo indossa.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-320879 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/contest-moda.jpg\" alt=\"\" width=\"536\" height=\"714\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intrattenimento live con la crew di RLB in diretta tra gli stand della XVII edizione della Festa del Cioccolato. La donna e le sue mille sfaccettature \u00e8 il file rouge del contest artistico per la giornata di venerdi 25 ottobre<\/p>\n","protected":false},"author":52,"featured_media":118307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[663],"class_list":["post-118306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-festa-del-cioccolato"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=118306"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/118307"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=118306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=118306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=118306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}