{"id":118538,"date":"2019-10-28T20:04:54","date_gmt":"2019-10-28T19:04:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/derattizzazione-interventi-nellarea-di-corigliano\/"},"modified":"2023-01-16T18:37:18","modified_gmt":"2023-01-16T17:37:18","slug":"321690-derattizzazione-interventi-nellarea-di-corigliano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/321690-derattizzazione-interventi-nellarea-di-corigliano\/","title":{"rendered":"Derattizzazione, interventi nell&#8217;area di Corigliano"},"content":{"rendered":"<h4>Continuano gli interventi su tutto il territorio comunale<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO-ROSSANO \u2013 Igiene pubblica, continuano gli interventi di derattizzazione su tutto il territorio comunale. Questa mattina si \u00e8 intervenuti nel Centro Storico ed allo Scalo di Corigliano, nel centro urbano di Schiavonea e nelle frazioni di Cantinella, Apollinara, San Nico e contrada Mandria del Forno.<\/p>\n<p>L&#8217;intervento segue a quello gi\u00e0 effettuato nei giorni scorsi sul territorio di Rossano. Le sostanze utilizzate non sono nocive per la salute pubblica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano gli interventi su tutto il territorio comunale<\/p>\n","protected":false},"author":51,"featured_media":118539,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-118538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=118538"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/118539"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=118538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=118538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=118538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}