{"id":118582,"date":"2019-10-29T12:29:44","date_gmt":"2019-10-29T11:29:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestrati-90-chili-di-prodotti-alimentari-al-mercato-di-rota-greca\/"},"modified":"2023-01-16T18:37:21","modified_gmt":"2023-01-16T17:37:21","slug":"321812-sequestrati-90-chili-di-prodotti-alimentari-al-mercato-di-rota-greca","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/321812-sequestrati-90-chili-di-prodotti-alimentari-al-mercato-di-rota-greca\/","title":{"rendered":"Sequestrati 90 chili di prodotti alimentari al mercato di Rota Greca"},"content":{"rendered":"<h4>Il sequestro \u00e8 stato compiuto dai militari della Stazione Carabinieri Forestale di Montalto durante un controllo effettuato nel mercato comunale di Rota Greca.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROTA GRECA (CS) &#8211; Novanta chilogrammi di prodotti alimentari sono stati sequestrati al mercato di Rota Greca durante un&#8217;attivit\u00e0 di controllo che ha portato ad accertare come i prodotti alimentari presenti sul banco espositore non refrigerato di un<strong> ambulante abusivo<\/strong>, erano privi di qualsiasi documentazione e etichetta atta a garantirne la tracciabilit\u00e0 degli stessi e la regolare provenienza.<\/p>\n<p>Sono stati pertanto posti sotto sequestro amministrativo cautelativo <strong>35 chili di miele<\/strong> in prevalenza di essenze di acacia, sulla e castagno, 15 confezioni di peperoncino, <strong>9 confezioni di funghi porcini stagionati ed oltre 50 kg suddivisi<\/strong> in 92 confezioni di fichi preimballati e non. Al <strong>venditore abusivo<\/strong> \u00e8 stata inoltre contestata una sanzione amministrativi di circa <strong>7000 euro.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sequestro \u00e8 stato compiuto dai militari della Stazione Carabinieri Forestale di Montalto durante un controllo effettuato nel mercato comunale di Rota Greca.<\/p>\n","protected":false},"author":42,"featured_media":118583,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-118582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=118582"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/118583"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=118582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=118582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=118582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}