{"id":118718,"date":"2019-11-03T14:00:32","date_gmt":"2019-11-03T13:00:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/al-museo-del-codex-larte-che-genera-speranza-nelle-periferie-del-mondo\/"},"modified":"2023-01-16T18:37:29","modified_gmt":"2023-01-16T17:37:29","slug":"322251-al-museo-del-codex-larte-che-genera-speranza-nelle-periferie-del-mondo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/322251-al-museo-del-codex-larte-che-genera-speranza-nelle-periferie-del-mondo\/","title":{"rendered":"Al Museo del Codex, l&#8217;arte che genera speranza nelle periferie del Mondo"},"content":{"rendered":"<h4>Il prossimo mercoled\u00ec 6 novembre alle 17.30 il Museo Diocesano e del Codex incontrer\u00e0 gli artisti del Wajukuu Art Project impegnata nello sviluppo della baraccopoli di Mukuru a Nairobi (Kenya)<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Il museo Diocesano e del Codex incontra gli artisti del Wajukuu Art Project, associazione impegnata nello sviluppo di un\u2019area degradata, la <strong>baraccopoli di Mukuru a Nairobi (Kenya<\/strong>), dove si vive nel pi\u00f9 totale abbandono. Scopo dell\u2019associazione \u00e8 quella di creare luoghi di condivisione in una comunit\u00e0 a rischio, attraverso la creazione di spazi e attivit\u00e0 in cui i <strong>giovani possano esprimere la loro creativit\u00e0 artistica e valorizzare i loro talenti.<\/strong><\/p>\n<p>I <strong>quattro artisti fondatori del progetto <\/strong>sono presenti con le loro opere in Calabria nella mostra collettiva Our Stories, Human Stories, ospitata fino a <strong>domenica 17 novembre<\/strong> al Museo dei Brettii e degli Enotri di <strong>Cosenza<\/strong>.<\/p>\n<p>In occasione della loro visita a Corigliano-Rossano, gli artisti saranno accolti nel Museo Diocesano e del Codex, significativo luogo d\u2019arte del territorio, per lasciare testimonianza sulla capacit\u00e0 delle persone di trasformare il dolore nella bellezza e di come l\u2019arte possa essere considerata segno di rinascita.<\/p>\n<p>L\u2019incontro, organizzato dall\u2019associazione \u201cInsieme per Camminare\u201d, ente gestore del Museo, in collaborazione con il MoCI ONG, partner e sostenitore delle attivit\u00e0 di Wajukuu Art Project dal 2007, vedr\u00e0 la presenza <strong>dell\u2019Arcivescovo di Rossano-Cariati Mons. Giuseppe Satriano<\/strong>, dell\u2019Assessore alla Citt\u00e0 della Cultura a delle Solidariet\u00e0 di Corigliano-Rossano <strong>Donatella Novellis<\/strong>, del volontario di MoCi ONG <strong>Andrea Bevacqua<\/strong> e del vicedirettore del Museo Diocesano e del Codex <strong>Cecilia Perri.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-322254 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/10\/Locandina-6-novembre-2019.jpg\" alt=\"\" width=\"497\" height=\"807\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prossimo mercoled\u00ec 6 novembre alle 17.30 il Museo Diocesano e del Codex incontrer\u00e0 gli artisti del Wajukuu Art Project impegnata nello sviluppo della baraccopoli di Mukuru a Nairobi (Kenya)<\/p>\n","protected":false},"author":42,"featured_media":118719,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-118718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=118718"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/118719"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=118718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=118718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=118718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}