{"id":118770,"date":"2019-11-01T19:00:58","date_gmt":"2019-11-01T18:00:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/clementine-calo-schock-nella-raccolta\/"},"modified":"2023-01-16T18:37:32","modified_gmt":"2023-01-16T17:37:32","slug":"322379-clementine-calo-schock-nella-raccolta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/322379-clementine-calo-schock-nella-raccolta\/","title":{"rendered":"Clementine e caldo anomalo: calo shock nella raccolta"},"content":{"rendered":"<h4>Il caldo anomalo che si \u00e8 registrato in particolare nel mese di giugno \u2013 fa notare Confagricoltura &#8211; ha determinato una diminuzione dei raccolti con punte del 30% rispetto alla precedente annata<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO &#8211; Si prospetta un&#8217;annata dura, per il frutto simbolo di Corigliano-Rossano. L\u2019andamento climatico ha ridotto quest\u2019anno la produzione italiana di clementine. Il caldo anomalo che si \u00e8 registrato in particolare nel mese di giugno \u2013 fa notare Confagricoltura attraverso una nota &#8211; ha determinato una diminuzione dei raccolti con punte del 30% rispetto alla precedente annata.<\/p>\n<p>\u201cIl livello dei prezzi per\u00f2 non \u00e8 soddisfacente, nonostante la minore disponibilit\u00e0 di prodotto\u201d &#8211; evidenzia il presidente di Confagricoltura, Massimiliano Giansanti &#8211; \u201cIn alcuni casi, le clementine sono poste in vendita a prezzi inferiori a quelli che sarebbero giustificati dal normale gioco della domanda e dell\u2019offerta. Invitiamo i protagonisti della filiera a valutare con urgenza la situazione, per migliorare nell\u2019interesse di tutti le prospettive della campagna\u201d.<\/p>\n<p>\u201cNegli ultimi tempi &#8211; aggiunge il vicepresidente di Confagricoltura, Nicola Cilento &#8211; sono stati realizzati investimenti e poste in essere importanti iniziative per valorizzare in termini commerciali la qualit\u00e0 della produzione italiana nei confronti della concorrenza, soprattutto spagnola. E\u2019 il caso, ad esempio, della <strong>IGP Clementine di Calabria<\/strong>\u201d.<\/p>\n<p>\u201cCome produttori abbiamo avviato un programma pluriennale per migliorare la presenza delle clementine italiane sul mercato nazionale e all\u2019estero. Il nostro auspicio &#8211; conclude Cilento &#8211; \u00e8 che, con il contributo di tutti i soggetti interessati, il programma non sia rallentato o vanificato da iniziative di breve respiro in termine di prezzi. E soprattutto controproducenti per la parte agricola\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il caldo anomalo che si \u00e8 registrato in particolare nel mese di giugno \u2013 fa notare Confagricoltura &#8211; ha determinato una diminuzione dei raccolti con punte del 30% rispetto alla precedente annata<\/p>\n","protected":false},"author":51,"featured_media":118771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-118770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=118770"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/118771"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=118770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=118770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=118770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}