{"id":118794,"date":"2019-11-02T09:00:48","date_gmt":"2019-11-02T08:00:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-scuola-con-il-cuore-lunedi-liniziativa-per-il-benessere-degli-studenti\/"},"modified":"2023-01-16T18:37:35","modified_gmt":"2023-01-16T17:37:35","slug":"322460-a-scuola-con-il-cuore-lunedi-liniziativa-per-il-benessere-degli-studenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/322460-a-scuola-con-il-cuore-lunedi-liniziativa-per-il-benessere-degli-studenti\/","title":{"rendered":"&#8220;A Scuola&#8230; con il Cuore&#8221;, luned\u00ec l&#8217;iniziativa per il benessere degli studenti"},"content":{"rendered":"<h4>L&#8217;iniziativa voluta dal Dirigente Scolastico del I.P.S.S.S. Da Vinci &#8211; I.T.A.S Nitti di Cosenza, Damiano De Paola \u00e8 rivolta agli alunni dell&#8217;Istituto.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Si intitola &#8220;<strong>A Scuola&#8230; con il Cuore<\/strong>&#8221; ed \u00e8 un&#8217;iniziativa promossa dall&#8217;istituto di Istruzione Superiore I.P.S.S.S. Da Vinci &#8211; I.T.A.S Nitti di Cosenza. L&#8217;obiettivo dell&#8217;iniziativa in programma l<strong>uned\u00ec 4<\/strong> novembre <strong>alle ore 10.00<\/strong> nell&#8217;auditorium dell&#8217;Istituto in <strong>viale Mancini a Cosenza<\/strong>, \u00e8 il benessere degli studenti, intesi come centralit\u00e0 dell&#8217;azione formativa quotidiana.<\/p>\n<p>L&#8217;iniziativa infatti, si inserisce in uno spettro ampio di eventi che coinvolgono l&#8217;istituto, in stretto rapporto con il suo territorio, in particolare, con le istituzioni e gli enti con cui da tempo collabora. Considerata l&#8217;offerta formativa del &#8220;Da Vinci-Nitti&#8221;, l&#8217;intervento del <strong>Dott. Antonello Talarico<\/strong> , Responsabile dell&#8217;UOS di Elettrofisiologia ed Elettro Stimolazione, UOC Cardioloogia-UTIC dell&#8217;azienda ospedaliera di Cosenza, rappresenta un importante <strong>accrescimento delle competenze curriculari degli studenti.<\/strong><\/p>\n<p>A fare gli onori di casa sar\u00e0 il <strong>dirigente scolastico Damiano De Paola<\/strong> mentre parteciperanno alla giornata l&#8217;assessore all&#8217;Istruzione e alla Cultura della Regione Calabria, <strong>Maria Francesca Corigliano<\/strong>; <strong>Gianfranco Ramundo<\/strong>, delegato all&#8217;edilizia scolastica dell&#8217;ente Provincia di Cosenza e il presidente del Consiglio comunale della citt\u00e0 dei bruzi, <strong>Pierluigi Caputo.\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-322464 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/11\/locandina_2019.11.04_-_A_scuola_con_il_cuore.jpeg\" alt=\"\" width=\"543\" height=\"1379\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;iniziativa voluta dal Dirigente Scolastico del I.P.S.S.S. Da Vinci &#8211; I.T.A.S Nitti di Cosenza, Damiano De Paola \u00e8 rivolta agli alunni dell&#8217;Istituto.<\/p>\n","protected":false},"author":42,"featured_media":118795,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[53],"tags":[],"class_list":["post-118794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ck20-scuola"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=118794"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/118794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/118795"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=118794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=118794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=118794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}