{"id":119274,"date":"2019-11-11T05:32:35","date_gmt":"2019-11-11T04:32:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-cosenza-i-mercatini-di-natale-diffusi-linaugurazione-sabato-prossimo\/"},"modified":"2023-01-16T18:38:07","modified_gmt":"2023-01-16T17:38:07","slug":"323912-a-cosenza-i-mercatini-di-natale-diffusi-linaugurazione-sabato-prossimo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/323912-a-cosenza-i-mercatini-di-natale-diffusi-linaugurazione-sabato-prossimo\/","title":{"rendered":"A Cosenza i mercatini di Natale diffusi. L&#8217;inaugurazione sabato prossimo"},"content":{"rendered":"<h4><strong>Su richiesta delle Associazioni<\/strong> e sentito il parere favorevole della Commissione competente ha deciso quest&#8217;anno di organizzare i Mercatini su piazza Bilotti e alla Villa nuova<\/h4>\n<p class=\"gmail-MsoBodyText\"><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p class=\"gmail-MsoBodyText\">COSENZA &#8211; Torna il tradizionale <strong>appuntamento con i Mercatini di Natale<\/strong>. L&#8217;edizione 2019 si presenta con tante novit\u00e0 visto che l&#8217;esposizione delle decorazioni natalizie raddoppia, abbracciando la filosofia dei mercatini diffusi. L&#8217;assessorato Attivit\u00e0 Produttive, guidato da Loredana Pastore, infatti, di comune accordo col sindaco Mario Occhiuto,<strong> su richiesta delle Associazioni<\/strong> e sentito il parere favorevole della Commissione competente ha deciso quest&#8217;anno di organizzare <strong>i Mercatini su piazza Bilotti e alla Villa nuova<\/strong> (ritornando in parte dove erano stati organizzati la prima volta dall&#8217;Assessorato). Tante quindi le sorprese all&#8217;interno delle due aree espositive\u00a0 per la gioia dei pi\u00f9 piccoli ma anche dei loro genitori. Saranno circa <strong>100 gli stand distribuiti fra le due location<\/strong> dove i cosentini potranno trovare tutte le novit\u00e0 e le decorazioni natalizie per addobbare le loro case. L&#8217;inaugurazione \u00e8 fissata per il prossimo <strong>16 novembre a piazza Bilotti ed il 22 novembre alla Villa nuova<\/strong>. Anche quest&#8217;anno i mercatini, in una atmosfera suggestiva, saranno allietati dalla presenza della banda musicale di sant&#8217;Ippolito e dal coro della scuola &#8220;Don Milani-De Matera&#8221; che li accompagna sin dalla prima edizione. Uno sforzo organizzativo notevole, dunque, ma che incontrer\u00e0 certamente il favore dei cosentini e dei tanti visitatori che ogni anno arrivano da tutta la regione. L&#8217;Assessore Pastore ha indirizzato un grazie particolare alle due associazioni dei commercianti che stanno collaborando e collaboreranno in modo concreto alla realizzazione dell&#8217;edizione di quest&#8217;anno. Nei prossimi giorni <strong>saranno resi noti gli ulteriori dettagli organizzativi<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su richiesta delle Associazioni e sentito il parere favorevole della Commissione competente ha deciso quest&#8217;anno di organizzare i Mercatini su piazza Bilotti e alla Villa nuova<\/p>\n","protected":false},"author":54,"featured_media":119275,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-119274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119274"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119275"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}