{"id":119280,"date":"2019-11-10T17:51:47","date_gmt":"2019-11-10T16:51:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/allerta-meteo-diramata-dalla-protezione-civile-scuole-chiuse\/"},"modified":"2023-01-16T18:38:08","modified_gmt":"2023-01-16T17:38:08","slug":"323953-allerta-meteo-diramata-dalla-protezione-civile-scuole-chiuse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/323953-allerta-meteo-diramata-dalla-protezione-civile-scuole-chiuse\/","title":{"rendered":"Allerta meteo diramata dalla Protezione Civile, scuole chiuse"},"content":{"rendered":"<div>\n<h4>A seguito dell\u2019allerta arancione prevista per domani e diramata dalla Protezione civile, scuole chiuse nel comune di Crotone, Catanzaro, Borgia, Soverato, Simeri Crichi, Sersale, Cerva e Caraffa<\/h4>\n<\/div>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<div>\n<p>CALABRIA &#8211; \u00a0Il Dipartimento di Protezione Civile della Regione Calabria ha trasmesso il <b>messaggio di Allertamento Unificato<\/b>\u00a0fase previsionale che indica che a partire\u00a0<b>dalle ore 12 e fino alle ore 24 di luned\u00ec 11 novembre 2019<\/b>, vi sar\u00e0 un l<strong>ivello di allertamento arancione<\/strong>. Dal pomeriggio e per le successive 24\/36 ore sono previsti: venti di burrasca sud orientali con<strong> raffiche di burrasca forte o tempesta<\/strong>; precipitazioni diffuse e persistenti a prevalente carattere di rovescio o temporale. Tutti i fenomeni saranno accompagnati da rovesci di forte intensit\u00e0, <strong>frequente attivit\u00e0 elettrica e forti raffiche di vento.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-323664 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/11\/Allerta-Arancione.jpg\" alt=\"\" width=\"465\" height=\"661\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>Pertanto i sindaci dei comuni di Crotone, Catanzaro, Borgia, Soverato, Simeri Crichi, Sersale, Cerva e Caraffa hanno ordinato la chiusura delle<b> scuole di ogni ordine e grado<\/b>. Inoltre, si raccomanda ai cittadini la <strong>massima prudenza limitando gli spostamenti<\/strong> a quelli strettamente necessari evitando le zone vicine ai corsi d\u2019acqua per il rischio di possibili esondazioni, le pinete per il <strong>rischio di caduta alberi<\/strong> e le coste esposte.<\/p>\n<\/div>\n<p>https:\/\/quicosenza.it\/news\/provincia-cosenza\/323851-maltempo-sulla-costa-tirrenica-cosentina-i-primi-danni<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguito dell\u2019allerta arancione prevista per domani e diramata dalla Protezione civile, scuole chiuse nel comune di Crotone, Catanzaro, Borgia, Soverato, Simeri Crichi, Sersale, Cerva e Caraffa<\/p>\n","protected":false},"author":54,"featured_media":119281,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-119280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119280"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119281"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}