{"id":119373,"date":"2019-11-14T09:13:48","date_gmt":"2019-11-14T08:13:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/e-di-spezzano-sila-il-miglior-panettone-artigianale-ditalia-audio-video\/"},"modified":"2023-01-16T18:38:15","modified_gmt":"2023-01-16T17:38:15","slug":"324267-e-di-spezzano-sila-il-miglior-panettone-artigianale-ditalia-audio-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/324267-e-di-spezzano-sila-il-miglior-panettone-artigianale-ditalia-audio-video\/","title":{"rendered":"\u00c8 di Spezzano Sila il miglior &#8220;Panettone artigianale d&#8217;Italia&#8221; (AUDIO &#8211; VIDEO)"},"content":{"rendered":"<h4>Primo posto per Damiano e Valentino Rizzo della Pasticceria San Francesco di Spezzano della Sila al concorso a Bari per il &#8220;Miglior Panettone d&#8217;Italia&#8221;. Il premio assegnato dalla giuria popolare <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SPEZZANO DELLA SILA (CS) &#8211; La professionalit\u00e0, la passione e l&#8217;amore per il lavoro portano a grandi risultati. In pi\u00f9 ci sono le materie prime rigorosamente di qualit\u00e0. I fratelli <strong>Damiano e Valentino Rizzo<\/strong> sono i vincitori della <strong>terza edizione di \u201cMastro Panettone\u201d,<\/strong> il concorso organizzato da Goloasi.it che premia i panettoni artigianale pi\u00f9 buoni dell\u2019anno, e sono stati premiati in occasione di \u201cMastro Panettone in Festa\u201d, appuntamento dedicato al dolce di Natale per eccellenza svoltosi il 10 e l&#8217;11 novembre scorsi <strong>all&#8217;Hotel Excelsior di Bari<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-324579 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/11\/miglior-panettone-artigianale-fratelli-rizzo-02.jpg\" alt=\"\" width=\"555\" height=\"331\" title=\"\"><\/p>\n<p>La provincia di Cosenza dunque protagonista con il \u201c<strong>Miglior panettone artigianale tradizionale<\/strong>\u201d premiato dalla giuria popolare; riconoscimento assegnato alla pasticceria <strong>&#8216;San Francesco&#8217; di Spezzano della Sila<\/strong> su 20 panettoni finalisti per la categoria e altri 20, per quella \u201cMiglior panettone artigianale creativo al cioccolato\u201d.<\/p>\n<p>https:\/\/www.facebook.com\/rlbradioattiva\/videos\/968136093538637\/<\/p>\n<p>Difficile la valutazione per la giuria che ha dovuto osservare alcuni canoni fondamentali nella preparazione: il rispetto del disciplinare, creativit\u00e0 (per quello al cioccolato), peso, qualit\u00e0 degli ingredienti, gusto, forma, sofficit\u00e0, profumo, alveolatura, taglio e cottura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-324586 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/11\/panettone-valentino-rizzo-simona-gambaro.jpg\" alt=\"\" width=\"408\" height=\"266\" title=\"\"><\/p>\n<p>Ma a <strong>spopolare \u00e8 stato proprio il loro panettone,<\/strong> morbido, soffice, gustoso, preparato con ingredienti rigorosamente di prima qualit\u00e0. A raccontare ai <strong>microfoni di RLB questa esperienza<\/strong>, ma anche l&#8217;impegno e i sacrifici che hanno portato al riconoscimento, <strong>\u00e8 Valentino Rizzo<\/strong><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/712614127&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primo posto per Damiano e Valentino Rizzo della Pasticceria San Francesco di Spezzano della Sila al concorso a Bari per il &#8220;Miglior Panettone d&#8217;Italia&#8221;. Il premio assegnato dalla giuria popolare<\/p>\n","protected":false},"author":42,"featured_media":119374,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[63,28],"tags":[],"class_list":["post-119373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gusto","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119373"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119374"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}