{"id":119474,"date":"2019-11-14T07:30:47","date_gmt":"2019-11-14T06:30:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rose-conclusa-la-bonifica-dellamianto-dellex-stabilimento-russo-pavimenti\/"},"modified":"2023-01-16T18:38:21","modified_gmt":"2023-01-16T17:38:21","slug":"324574-rose-conclusa-la-bonifica-dellamianto-dellex-stabilimento-russo-pavimenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/324574-rose-conclusa-la-bonifica-dellamianto-dellex-stabilimento-russo-pavimenti\/","title":{"rendered":"Rose, conclusa la bonifica dell\u2019amianto dell\u2019ex stabilimento Russo Pavimenti"},"content":{"rendered":"<h4>Si sono finalmente conclusi gli interventi di bonifica dell\u2019ex stabilimento Russo Pavimenti in localit\u00e0 Petraro del Comune di Rose, dove erano presenti 8.100 mq di coperture in amianto<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROSE &#8211; Un sito sottoposto a curatela fallimentare interposto tra l\u2019argine del fiume Crati ed un\u2019area ad alta densit\u00e0 abitativa bonificato. L\u2019importante intervento fa seguito alla bonifica effettuata in localit\u00e0 Triscioli di Santa Caterina Albanese, dove sono stati rimossi circa 15.000 mq dello stesso materiale. <strong>In entrambi i casi \u00e8 intervenuta la Regione Calabria con un contributo<\/strong> (120.000,00 euro per Rose, 190.000,00 per Santa Caterina Albanese) a favore dei Comuni che agiscono in danno alla curatela fallimentare, per cui le somme erogate dovranno essere restituite dalla stessa curatela quando disporr\u00e0 di liquidit\u00e0 derivante dalla vendita degli immobili.<\/p>\n<p>A comunicarlo \u00e8 l\u2019ing. Giuseppe Infusini, Coordinatore Provinciale dell\u2019ONA, l&#8217;Osservatorio Nazionale Amianto, quale direttore e supervisore dei lavori appaltati dalla Calabra Maceri e Servizi S.p.A., attivit\u00e0 resa in forma gratuita in virt\u00f9 dell\u2019adesione del Comune di Rose all\u2019Associazione ONA Cosenza.<\/p>\n<p>&#8220;Un&#8217;altra passo avanti nella lotta all&#8217;amianto in Calabria \u2013 afferma Infusini \u2013 in una Regione ove stentano a partire i censimenti e sono del tutto assenti contributi per le bonifiche a favore dei privati bench\u00e9 previsti dall\u2019art. 17.1 del PRAC (incentivi economici &#8211; Piano Regionale Amianto Calabria). L&#8217;intervento della Regione \u00e8 stato possibile grazie all&#8217;impegno dei sindaci dei due Comuni e dell&#8217;ONA Cosenza che per anni ha affiancato le amministrazioni sostenendo il coinvolgimento diretto della Regione in casi di conclamato rischio ambientale a cui i Comuni non possono far fronte&#8221;.<\/p>\n<p>&#8220;Nel <strong>caso di Rose<\/strong> &#8211; continua Infusini \u2013 la passata amministrazione \u00e8 riuscita ad ottenere il finanziamento ed avviare le procedure per la consegna dei lavori. <strong>Le attivit\u00e0 di bonifica sono poi iniziate con la nuova giunta e si sono effettivamente concluse il 7 novembre scorso<\/strong>, con la rimozione dell\u2019ultima pericolosa lastra d\u2019amianto. Un\u2019altra battaglia vinta, dunque, ma molto c\u2019\u00e8 ancora da fare sia sul fronte della sensibilizzazione che su quello del coinvolgimento attivo delle istituzioni\u201d. Comprensibile la soddisfazione di Infusini che in queste battaglie \u00e8 stato a lungo impegnato in prima persona, segno dell&#8217;azione sempre pi\u00f9 incisiva e significativa che l&#8217;ONA Cosenza esercita sul territorio, coinvolgendo cittadini &#8211; attraverso le attivit\u00e0 di informazione messe in campo nelle piazze, nelle scuole, con l&#8217;organizzazione di convegni scientifici &#8211; ed istituzioni: i Comuni, grazie agli Sportelli Amianto ONA che continuano ad istituirsi in diversi centri della provincia, e la Regione, grazie all&#8217;azione di stimolo a effettuare gli adempimenti connessi con l&#8217;attuazione del PRAC. Una rete in cui ognuno \u00e8 chiamato a fare la propria parte secondo i propri obblighi, in modo da poter ottenere risultati significativi per l&#8217;eliminazione graduale dell&#8217;amianto dal territorio calabrese&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono finalmente conclusi gli interventi di bonifica dell\u2019ex stabilimento Russo Pavimenti in localit\u00e0 Petraro del Comune di Rose, dove erano presenti 8.100 mq di coperture in amianto<\/p>\n","protected":false},"author":42,"featured_media":119475,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-119474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119474"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119475"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}