{"id":119484,"date":"2019-11-14T10:25:59","date_gmt":"2019-11-14T09:25:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rossano-ex-operaio-enel-protesta-sulla-terrazza-della-centrale-nessuna-riassunzione\/"},"modified":"2023-01-16T18:38:22","modified_gmt":"2023-01-16T17:38:22","slug":"324616-rossano-ex-operaio-enel-protesta-sulla-terrazza-della-centrale-nessuna-riassunzione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/324616-rossano-ex-operaio-enel-protesta-sulla-terrazza-della-centrale-nessuna-riassunzione\/","title":{"rendered":"Rossano: ex operaio Enel sulla terrazza della centrale: &#8220;nessuna riassunzione&#8221;"},"content":{"rendered":"<h4>A settembre scorso l&#8217;uomo era salito sulla ciminiera per chiedere di essere riassunto ma nonostante le promesse di lavoro, anche del sindaco Stasi, l&#8217;ex operaio \u00e8 a tutt&#8217;oggi senza occupazione<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Continua la protesta di un ex operaio della centrale termoelettrica Enel dell&#8217;area urbana di Rossano, che gi\u00e0 a settembre era salito sulla ciminiera della struttura. <strong>Giuseppe Bosco, di 58 anni<\/strong>, \u00e8 salito la scorsa notte al <strong>nono piano della centrale Enel<\/strong>, nel reparto caldaie, per protestare contro quelle che ha definito le promesse di lavoro non rispettate.<\/p>\n<p><span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/8692\" target=\"_blank\" rel=\"noopener noreferrer\">L&#8217;ultima protesta il 16 settembre<\/a><\/strong><\/span>: Bosco era salito sulla ciminiera della centrale ad un&#8217;altezza di cento metri per chiedere di essere riassunto. Addetto alla pulizia industriale della centrale, aveva lasciato il lavoro per una migliore proposta per poi rimanere disoccupato. A settembre scorso, in seguito alla protesta, i responsabili della centrale ed il sindaco di Corigliano Rossano, <strong>Flavio Stavi, avevano garantito la riassunzione dell&#8217;operaio<\/strong>. &#8220;Per l&#8217;ennesima volta &#8211; ha detto il responsabile sindacale Sgb Bruno Graziano &#8211; l&#8217;Enel non ha mantenuto le promesse fatte e che avrebbero permesso al lavoratore di essere assunto nel settore produttivo Enel&#8221;. <strong>Sul posto ci sono le forze dell&#8217;ordine.<\/strong><\/p>\n<p>https:\/\/quicosenza.it\/news\/8692<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A settembre scorso l&#8217;uomo era salito sulla ciminiera per chiedere di essere riassunto ma nonostante le promesse di lavoro, anche del sindaco Stasi, l&#8217;ex operaio \u00e8 a tutt&#8217;oggi senza occupazione<\/p>\n","protected":false},"author":42,"featured_media":119485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-119484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119484"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119485"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}