{"id":119498,"date":"2019-11-14T13:22:40","date_gmt":"2019-11-14T12:22:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-estirpano-un-bosco-a-nogiano-per-fare-una-vigna-due-denunce\/"},"modified":"2023-01-16T18:38:23","modified_gmt":"2023-01-16T17:38:23","slug":"324670-rende-estirpano-un-bosco-a-nogiano-per-fare-una-vigna-due-denunce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/324670-rende-estirpano-un-bosco-a-nogiano-per-fare-una-vigna-due-denunce\/","title":{"rendered":"Rende, estirpano un bosco a Nogiano per fare una vigna. Due denunce"},"content":{"rendered":"<h4>Hanno letteralmente estirpato un bosco con l&#8217;intento di realizzare un vigneto. Due persone sono state denunciate dai carabinieri forestali di Cosenza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; I militari della Stazione Carabinieri Forestale di Cosenza hanno denunciato alla Procura della Repubblica di Cosenza il titolare di una ditta boschiva ed un imprenditore agricolo per l\u2019estirpazione di una area boscata senza alcuna autorizzazione. I militari avevano notato un taglio effettuato di recente e cos\u00ec, hanno effettuato un controllo <strong>in Contrada Nogiano nel Comune di Rende<\/strong> accertando che, <strong>oltre al taglio del bosco vi era in corso l\u2019estirpazione delle ceppaie, effettuato con macchine operatrici.<\/strong><\/p>\n<p>Controllata la documentazione in possesso dal proprietario del fondo e del titolare della ditta boschiva incaricata di effettuare i lavori, \u00e8 stato accertato che i lavori sono stati eseguiti in assenza dell\u2019autorizzazione di vincolo idrogeologico forestale ed in assenza di nulla osta paesaggistico ambientale.\u00a0Si \u00e8 pertanto proceduto ai rilievi che hanno accertato l\u2019interessamento al taglio di una <strong>superficie boscata composta da bosco misto con prevalenza di Roverella frammista a Carpino e Orniello<\/strong> nella parte alta ed un bosco di neoformazione di Pioppo nella parte bassa <strong>per un\u2019estensione di circa 6000 mq.<\/strong><\/p>\n<p>Successivamente a tali lavori di taglio erano state inoltre estirpate parte delle ceppaie su di una <strong>superficie di circa 1000 mq<\/strong>. L\u2019area \u00e8 stata posta sotto sequestro in quanto i lavori sono stati effettuati senza autorizzazione paesaggistico ambientale ed \u00e8 stata inoltre contestata una <strong>sanzione amministrativa di 7.600 euro<\/strong>. Con l\u2019intervento dei militari della Stazione Forestale di Cosenza si \u00e8 evitato che l\u2019intera area boscata venisse cos\u00ec eliminata con lo scopo di realizzare un\u2019area da adibire alla <strong>coltivazione di un vigneto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hanno letteralmente estirpato un bosco con l&#8217;intento di realizzare un vigneto. Due persone sono state denunciate dai carabinieri forestali di Cosenza<\/p>\n","protected":false},"author":42,"featured_media":119499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-119498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119498"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119499"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}