{"id":119822,"date":"2019-11-20T09:47:33","date_gmt":"2019-11-20T08:47:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spaccio-di-droga-tra-il-potentino-e-il-cosentino-arrestato-un-47enne\/"},"modified":"2023-01-16T18:38:46","modified_gmt":"2023-01-16T17:38:46","slug":"325513-spaccio-di-droga-tra-il-potentino-e-il-cosentino-arrestato-un-47enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/325513-spaccio-di-droga-tra-il-potentino-e-il-cosentino-arrestato-un-47enne\/","title":{"rendered":"Spaccio di droga tra il potentino e il cosentino. Arrestato un 47enne"},"content":{"rendered":"<h4>Durante le indagini i militari hanno scoperto che l\u2019uomo nel Lagonegrese si riforniva di droga, che poi spacciava in alcuni comuni del Senisese e dell\u2019alta provincia cosentina<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>POTENZA &#8211; In esecuzione di un&#8217;ordinanza di custodia cautelare in carcere emessa dal gip di Castrovillari, a Castelluccio Superiore i Carabinieri hanno <strong>arrestato un uomo di 47 anni<\/strong> accusato di detenzione ai fini di spaccio di sostanze stupefacenti. Durante le indagini, i militari hanno scoperto che l&#8217;uomo si riforniva nel Lagonegrese di droga, che poi spacciava in alcuni comuni del Senisese e<strong> dell&#8217;alta provincia cosentina<\/strong>. Durante la perquisizione effettuata nell&#8217;abitazione, con l&#8217;ausilio del cane antidroga &#8220;Gnom&#8221;, i carabinieri di Senise, nel potentino, hanno scoperto circa<strong> 3,5 grammi di cocaina<\/strong>, due pugnali del genere vietato, e 400 euro in banconote contraffatte, delle quali 15 da 20 e due da 50 euro: per questo l&#8217;uomo \u00e8 stato d<strong>enunciato anche per i reati di spendita di monete falsificate<\/strong> e <strong>porto di armi od oggetti atti ad offendere<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante le indagini i militari hanno scoperto che l\u2019uomo nel Lagonegrese si riforniva di droga, che poi spacciava in alcuni comuni del Senisese e dell\u2019alta provincia cosentina<\/p>\n","protected":false},"author":46,"featured_media":119823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-119822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=119822"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/119822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/119823"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=119822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=119822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=119822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}