{"id":120140,"date":"2019-11-26T09:24:48","date_gmt":"2019-11-26T08:24:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ai-domiciliari-interagiva-e-pubblicava-post-sui-social-finisce-in-carcere\/"},"modified":"2023-01-16T18:39:07","modified_gmt":"2023-01-16T17:39:07","slug":"326567-ai-domiciliari-interagiva-e-pubblicava-post-sui-social-finisce-in-carcere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/326567-ai-domiciliari-interagiva-e-pubblicava-post-sui-social-finisce-in-carcere\/","title":{"rendered":"Ai domiciliari interagiva e pubblicava post sui social, finisce in carcere"},"content":{"rendered":"<h4>Protagonista un trentunenne al quale erano stati concessi gli arresti domiciliari con l\u2019espresso divieto di conferire con persone diverse dai conviventi.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME &#8211; Per chi \u00e8 ristretto ai domiciliari \u00e8 vietato ogni contatto con l&#8217;esterno, anche per via telematica ma nonostante il &#8220;beneficio&#8221; rispetto alla detenzione in carcere, <strong>M.P., di 31 anni<\/strong>, ha violato le prescrizioni imposte dalla magistratura ed ha riattivato i suoi profili social. E cos\u00ec si era dato a lunghe chiacchierate, alla condivisione di post comunicando come se nulla fosse, con chiunque volesse.<\/p>\n<p>La sua attivit\u00e0 online non \u00e8 passata inosservata ai carabinieri di Lamezia Terme Scalo che hanno minuziosamente documentato, riepilogato e catalogato le <strong>assidue frequentazioni virtuali<\/strong> del giovane da cui \u00e8 scaturita una richiesta di <strong>aggravamento della misura cautelare<\/strong> in atto, accolta dal Tribunale di Lamezia Terme. Grazie all\u2019attenta attivit\u00e0 di <strong>monitoraggio dei Carabinieri anche sul web<\/strong>, il <strong>trentunenne<\/strong> \u00e8 stato ricondotto nella casa circondariale di Catanzaro. \u200b<\/p>\n<p>L&#8217;uomo era finito in carcere nel febbraio scorso perch\u00e9 pretendeva una consumazione senza pagare in un esercizio commerciale del centro di Lamezia ed aveva minacciato il titolare. La stessa sera era finito in carcere dove ha trascorso la prima parte della sua misura cautelare. Dopo alcuni mesi aveva ottenuto il beneficio della detenzione a casa che gli \u00e8 stato ora revocato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Protagonista un trentunenne al quale erano stati concessi gli arresti domiciliari con l\u2019espresso divieto di conferire con persone diverse dai conviventi.<\/p>\n","protected":false},"author":42,"featured_media":120141,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-120140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=120140"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120141"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=120140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=120140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=120140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}