{"id":120200,"date":"2019-11-27T09:44:42","date_gmt":"2019-11-27T08:44:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-partecipazione-civica-nasce-il-comitato-di-quartiere-commenda-2-0\/"},"modified":"2023-01-16T18:39:10","modified_gmt":"2023-01-16T17:39:10","slug":"326733-rende-partecipazione-civica-nasce-il-comitato-di-quartiere-commenda-2-0","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/326733-rende-partecipazione-civica-nasce-il-comitato-di-quartiere-commenda-2-0\/","title":{"rendered":"Rende: partecipazione civica, nasce il comitato di quartiere &#8220;Commenda 2.0&#8221;"},"content":{"rendered":"<h4>Si sono ritrovati lo scorso 21 novembre i cittadini di Commenda per la presentazione ufficiale del neonato Comitato di Quartiere \u201cCommenda 2.0\u201d<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; Eterogeneo il pubblico presente composto da professionisti, insegnanti, commercianti, gente comune, tutti testimoni di una <strong>rinnovata voglia di partecipazione popolare alla cosa pubblica<\/strong>. L&#8217;iniziativa \u00e8 stata ospitata nella sala \u201cSanta Chiara\u201d della chiesa di Sant\u2019Antonio a Commenda, resa gentilmente disponibile dal nuovo Parroco Padre Luigi Loricchio. A coordinare e fare gli onori di casa, la vicepresidente Lisa Ficara.<\/p>\n<p>\u00ab\u201cCommenda 2.0&#8243;\u00a0<strong> si pone come obiettivo quello di diventare una presenza reale sul territorio di Commenda<\/strong>, <strong>slegata da influenze di qualsiasi genere<\/strong> ma con la profonda volont\u00e0 di esercitare il diritto alla partecipazione attiva di tutti al governo cittadino. Per fortuna &#8211; riporta la nota del comitato &#8211;\u00a0 siamo capaci di autonomia di pensiero e di quello spirito critico oggi pi\u00f9 che mai necessario in una democrazia che s\u2019intende chiamare tale. Ci\u00f2 non toglie che la collaborazione tra noi cittadini semplici, a prescindere dal personalissimo pensiero politico e\/o partitico, e la riscoperta di un dialogo e di una fiducia perduta nelle istituzioni, sia la vera grande grande sfida per tutti e il <strong>Comitato Commenda 2.0<\/strong> \u00e8 pronto a diventare protagonista e garante di questa rinnovata partecipazione civica\u00bb.<\/p>\n<p>\u00abVogliamo costruire <strong>ponti e non muri<\/strong>, diventare quel <strong>tramite tra istituzioni e cittadini<\/strong> che <strong>manca nella nostra societ\u00e0 locale da troppo tempo<\/strong> e che invece rappresenta un pezzo fondamentale per la costruzione di una comunit\u00e0 pi\u00f9 matura e consapevole. In maniera <strong>sana ed etica<\/strong>, dimostreremo questo sul campo con azioni e fatti concreti\u201d.<\/p>\n<p>Illustri i relatori invitati per l\u2019occasione all&#8217;iniziativa: Carlo Ponte, ex viceprefetto del comune di Cosenza e Silvio Gambino, docente di diritto presso l\u2019universit\u00e0 della Calabria, che hanno dato notevoli spunti di riflessione al dibattito sottolineando i vari riferimenti giuridici della partecipazione popolare.<\/p>\n<p>\u00abAbbiamo fortemente voluto la presenza di questi competenti \u00a0&#8211; ha dichiarato il Presidente del comitato Gasparo Tozzi &#8211; conoscitori di legge proprio per delineare in maniera chiara e netta le finalit\u00e0 del Comitato, nato come aggregazione di cittadini ai sensi dell\u2019art. 39 del Codice Civile. Nell\u2019art. 1 dello statuto del Comitato infatti si legge \u201cha lo scopo di promuovere iniziative ed attivit\u00e0 di interesse generale volte alla realizzazione di interventi, in ambito di quartiere, sussidiari all&#8217;attivit\u00e0 dell\u2019amministrazione\u00bb.<\/p>\n<p>Fa chiarezza ancora il presidente Tozzi: \u00ab<strong>il comitato di quartiere non \u00e8 un organo istituito dall\u2019amministrazione comunale rendese ma semplicemente un gruppo di cittadini di \u201cbuona volont\u00e0\u201d<\/strong> che intendono dare nuovo slancio e linfa vitale <strong>all\u2019impegno civico<\/strong>, con proposte e progetti concreti\u00bb.<\/p>\n<p>Visibilmente orgogliosi ed emozionati nel vedere concretizzarsi un momento tanto atteso, frutto di studio delle normative vigenti in materia e di impegno civico, siedono al tavolo con i relatori anche alcuni membri del direttivo, il tesoriere Stefano Cananzi, il segretario Luca Clausi e Carmine delle Donne, altro socio fondatore. Presenti poi, il presidente del Consiglio comunale, Gaetano Morrone, gli assessori Annamaria Artese, con delega alle Politiche Sociali e all\u2019Associazionismo e Marinella Castiglione, con delega alla Pubblica Istruzione, i consiglieri Luciano Bonanno, Romina Provenzano, Concetta Brogno e Michele Morrone, nonch\u00e9 altri personaggi noti del panorama politico locale, Francesco Adamo e Carlo Scola, la cui presenza d\u00e0 fiducia che pluralit\u00e0 d\u2019intenti di Commenda 2.0 siano oggettivamente degli obiettivi concreti.<\/p>\n<p>Inoltre partecipe il primo cittadino di Rovito, Felice D\u2019Alessandro, a prova che l\u2019interesse per questa nuova forma aggregativa sia decisamente trasversale, oltrepassando il Campagnano. Presenti anche i presidenti di varie associazioni operanti sul territorio, Angela Cirigliano per Ars Enotria, Elena Hoo per l\u2019Auser e Maria Moraca, presidente del Comitato di Quartiere \u201cI Quartieri\u201d di Saporito, Surdo, Difesa e Linze. La presentazione si conclude con l\u2019intervento dell\u2019Assessore Domenico Ziccarelli, con delega all\u2019Ambiente ed al Decentramento, che presenzia sin dall\u2019inizio in rappresentanza dell\u2019amministrazione comunale: \u00abQueste libere manifestazioni, sorte spontaneamente, sono solo da applaudire e da incoraggiare e la loro libera costituzione conferma che i tempi siano maturi per un cambio di passo\u00bb. Ribadisce cos\u00ec l\u2019impegno dell\u2019amministrazione Manna di riportare al centro del dibattito politico e delle scelte amministrative i cittadini ed i loro bisogni e rilancia: \u00abil problema \u00e8 culturale e la necessit\u00e0 concreta del coinvolgimento popolare non \u00e8 uno slogan propagandistico. La campagna elettorale \u00e8 finita e noi siamo i rappresentanti di tutti i cittadini, nessuno escluso. La mia porta \u00e8 sempre aperta, cos\u00ec come quella del sindaco e di tutti i colleghi assessori, perci\u00f2 ben vengano queste libere iniziative, cos\u00ec come per gli altri comitati gi\u00e0 sorti in altri quartieri grazie anche all\u2019operato di alcuni membri di Commenda 2.0, con la concreta volont\u00e0 di collaborare e cooperare, tutti insieme -istituzioni e cittadini- per il bene comune. Gli amministratori passano ma, i comitati di quartiere rimangono\u00bb.<\/p>\n<p>L\u2019applauso spontaneo dei partecipanti a queste parole conclusive riscalda di entusiasmo la sala gremita, conferma di ritrovata voglia di ricominciare ad occuparsi in concreto delle problematiche di \u201ccasa propria\u201d, al di fuori di ogni riflessione poco costruttiva e lascia ben sperare in un nuovo capitolo di cittadinanza realmente attiva, propositiva e collaborativa tra cittadini, pi\u00f9 consapevoli ed informati, ed amministrazioni locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono ritrovati lo scorso 21 novembre i cittadini di Commenda per la presentazione ufficiale del neonato Comitato di Quartiere \u201cCommenda 2.0\u201d<\/p>\n","protected":false},"author":42,"featured_media":120201,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-120200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=120200"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120201"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=120200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=120200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=120200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}