{"id":120328,"date":"2019-11-29T10:22:30","date_gmt":"2019-11-29T09:22:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/terribile-schianto-sulla-statale-106-muoiono-moglie-e-marito-ferite-4-persone\/"},"modified":"2023-01-16T18:39:20","modified_gmt":"2023-01-16T17:39:20","slug":"327112-terribile-schianto-sulla-statale-106-muoiono-moglie-e-marito-ferite-4-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/327112-terribile-schianto-sulla-statale-106-muoiono-moglie-e-marito-ferite-4-persone\/","title":{"rendered":"Terribile schianto sulla Statale 106, muoiono moglie e marito. Ferite 4 persone"},"content":{"rendered":"<h4>L&#8217;ennesimo tragico incidente stradale questa mattina sulla strada statale 106 nel reggino. Le vittime sono due anziani, marito e moglie. Coinvolte 3 auto, 4 i feriti. Statale chiusa al traffico in entrambe le direzioni<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>MELITO PORTO SALVO (RC) &#8211; L&#8217;ennesimo tragico incidente stradale sulla strada statale 106 Jonica si \u00e8 verificato questa mattina intorno alle 9.30 <strong>nel comune di Melito di Porto Salvo nel reggino <\/strong>al chilometro 29,500 a pochi chilometri dal capoluogo. Nel violentissimo impatto sono deceduti <strong>marito e moglie, originari di Bova, che viaggiavano a bordo di una Peugeot<\/strong>. I sanitari del 118 giunti immediatamente sul luogo con 4 ambulanze, hanno tentato di rianimare l&#8217;uomo di circa 80 anni ma purtroppo senza esito. La moglie invece \u00e8 deceduta nella disperata corsa in ospedale. Sono <strong>tre in totale le autovetture coinvolte nell&#8217;incidente<\/strong> che ha provocato anche <strong>quattro feriti<\/strong>. Sul posto \u00e8 arrivata una squadra dei vigili del fuoco e la polizia stradale che ha scortato negli ospedali le ambulanze che hanno prestato i soccorsi alle persone coinvolte nell&#8217;impatto. La strada statale 106 \u00e8 stata <strong>temporaneamente chiusa in entrambe le direzioni <\/strong>e il traffico deviato sulla circolazione ordinaria.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/8855\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-327115\" src=\"https:\/\/quicosenza.it\/news\/8855\" alt=\"Foto Basta Vittime\" width=\"593\" height=\"365\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ennesimo tragico incidente stradale questa mattina sulla strada statale 106 nel reggino. Le vittime sono due anziani, marito e moglie. Coinvolte 3 auto, 4 i feriti. Statale chiusa al traffico in entrambe le direzioni<\/p>\n","protected":false},"author":46,"featured_media":120329,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-120328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=120328"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120329"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=120328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=120328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=120328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}