{"id":120456,"date":"2019-12-02T11:03:48","date_gmt":"2019-12-02T10:03:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/calci-e-pugni-allex-le-rompe-due-costole-arrestato-28enne-a-san-demetrio-corone\/"},"modified":"2023-01-16T18:39:28","modified_gmt":"2023-01-16T17:39:28","slug":"327514-calci-e-pugni-allex-le-rompe-due-costole-arrestato-28enne-a-san-demetrio-corone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/327514-calci-e-pugni-allex-le-rompe-due-costole-arrestato-28enne-a-san-demetrio-corone\/","title":{"rendered":"Calci e pugni all&#8217;ex, le rompe due costole: arrestato 28enne a San Demetrio Corone"},"content":{"rendered":"<h4>Stalking nei confronti dell&#8217;ex: dapprima messaggi sul WhatsApp, poi intimidazioni e minacce fino all&#8217;aggressione fisica<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN DEMETRIO CORONE (CS) \u2013 Arresti domiciliari per un ragazzo di 28 anni per i reati di atti persecutori e lesioni personali. Questo il provvedimento eseguito dai Carabinieri della Compagnia di Corigliano Calabro, emesso dal G.I.P. presso il Tribunale di Castrovillari, su richiesta della locale Procura. I fatti, di una gravit\u00e0 inaudita, risalgono a settembre di quest\u2019anno quando il ragazzo, non rassegnato alla fine della relazione sentimentale con la sua ex, aveva iniziato a perseguitarla: dapprima con messaggi sul WhatsApp, poi <strong>intimidazioni e minacce che si erano spinte fino all\u2019aggressione fisica<\/strong>. Precisamente in due distinti episodi il 28enne era riuscito ad avvicinare la ragazza e nel primo caso, a seguito di una scenata di gelosia, l\u2019aveva presa a <strong>calci e pugni, anche dopo che questa era caduta a terra, arrivando a romperle due costole<\/strong> ed essendo costretta a recarsi in ospedale dove le refertavano 30 giorni di prognosi. Nel secondo caso, invece, era riuscito ad entrare in un locale dove si trovava la ragazza e qui aveva iniziato ad afferrarla per i polsi ed aggredirla fisicamente, solo le urla della vittima avevano attirato l\u2019attenzione di alcuni avventori che erano intervenuti per allontanare il giovane. In altri casi aveva danneggiato parti dell\u2019abitazione dove vive la ex compagna, arrivando a <strong>distruggere il campanello della casa<\/strong> o apponendo la colla nella serratura della porta d\u2019ingresso.<\/p>\n<p>Nel giro di pochi mesi i Carabinieri della Stazione di San Demetrio Corone hanno constatato un graduale aggravamento della condotta del giovane, che ha raggiunto il culmine nei due episodi di violenza fisica perpetrati verso la ragazza. Il 28enne ha agito con violenza spinto da una forte ostinazionenel proseguimento dei propri scopi ed insensibile ai doveri imposti dalla civile convivenza, nonch\u00e9 mosso dalla spregiudicatezza ed indifferenza rispetto alle conseguenze del proprio agire. La condotta tenuta dall\u2019arrestato ha spinto l\u2019A.G. ad optare per la misura cautelare degli <strong>arresti domiciliari<\/strong>, poich\u00e9 allo stato dei fatti \u00e8 apparsa la pi\u00f9 idonea ed oggettivamente adeguata per frenare la pericolosit\u00e0 dell\u2019uomo e prevenire il pericolo di reiterazione dei reati. Sulla base dei fatti descritti e del grave impianto accusatorio costruito dai Carabinieri di San Demetrio, fondato non solo sui racconti della vittima, ma anche sugli oggettivi riscontri documentali e sulle dichiarazioni concordi di diversi testimoni che avevano assistito alle aggressioni dell\u2019indagato, nonch\u00e9 sulla base della pericolosit\u00e0 del soggetto, l\u2019A.G. \u00e8 stata applicata all\u2019uomo la misura cautelare degli arresti domiciliari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stalking nei confronti dell&#8217;ex: dapprima messaggi sul WhatsApp, poi intimidazioni e minacce fino all&#8217;aggressione fisica<\/p>\n","protected":false},"author":22,"featured_media":120457,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-120456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=120456"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120457"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=120456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=120456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=120456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}