{"id":120644,"date":"2019-12-04T18:50:40","date_gmt":"2019-12-04T17:50:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/anzianotti-nuoto-master-cosenza-secondo-posto-nella-prima-trasferta-stagionale\/"},"modified":"2023-01-16T18:39:41","modified_gmt":"2023-01-16T17:39:41","slug":"328047-anzianotti-nuoto-master-cosenza-secondo-posto-nella-prima-trasferta-stagionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/328047-anzianotti-nuoto-master-cosenza-secondo-posto-nella-prima-trasferta-stagionale\/","title":{"rendered":"Anzianotti Nuoto Master: secondo posto al 6 Trofeo Flegreo e 3 record regionali"},"content":{"rendered":"<h4>Prima gara stagionale in trasferta per la compagine cosentina dell\u2019Asd Anzianotti Nuoto Master ed un ottimo secondo posto conquistato al \u201c6\u00b0 Trofeo Flegreo\u201d nella piscina del complesso sportivo PalaTrincone a Monterusciello &#8211; Pozzuoli <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>POZZUOLI (NA) &#8211; Le gare si sono svolte\u00a0 nei giorni 30 Novembre e 1\u00b0 Dicembre, e hanno visto la\u00a0 partecipazione di\u00a0 57 squadre provenienti da tutte le regioni del centro Italia con oltre 500 atleti.\u00a0La manifestazione \u00e8 stata sapientemente \u00a0organizzata dalla<strong> Societ\u00e0 Sporting Club Flegreo<\/strong> con la direzione tecnica dell\u2019ex azzurro delfinista Francesco Vespe ed in collaborazione con la societ\u00e0 Eventualmente \u2013 Eventi &amp; Comunicazione nella piscina coperta di <strong>25 m e suddivisa in 8 corsie<\/strong>. I master cosentini, allenati dal team di tecnici formato da <strong>Giovanni Mazzuca,\u00a0 Daniele Maletta<\/strong> e supportati dal <strong>preparatore atletico Daniele Tenuta<\/strong>, hanno superato nel migliore dei modi il primo vero test agonistico della stagione.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/8903\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-328051\" src=\"https:\/\/quicosenza.it\/news\/8903\" alt=\"\" width=\"558\" height=\"363\" title=\"\"><\/a><\/p>\n<p>Due giorni di gare nella trasferta partenopea,\u00a0 durante i quali gli \u201cAnzianotti\u201d del team del <strong>presidente Caccuri Baffa<\/strong>, hanno dato dimostrazione delle loro elevate capacit\u00e0 tecniche anche contro squadre ben pi\u00f9 blasonate.\u00a0Grande soddisfazione \u00e8 stata espressa dal <strong>Vice Presidente degli Anzianiotti Pierluigi De Benedittis<\/strong>, il quale ha confermato che\u00a0 la qualit\u00e0 dei risultati raggiunti \u00e8 il frutto di un lavoro costante di tutti gli atleti a conferma dei sacrifici fatti quotidianamente.\u00a0Un weekend, quello della compagine cosentina, interamente dedicato alla memoria del giovane atleta di Sellia Marina (CZ) <strong>Sergio Mirante<\/strong> prematuramente scomparso soltanto un mese a soli 30 anni fa e tesserato da poco con gli Anzianotti.\u00a0Ricchissimo il bottino di medaglie conquistate dagli Anzianotti<strong>, 34 in totale e ben\u00a0 3 record regionali battuti<\/strong>.<\/p>\n<h4><strong>Il medagliere di sabato 30 novembre:<\/strong><\/h4>\n<p>Giovanni Mazzuca (M30) <strong>medaglia d\u2019oro<\/strong> nei 50 dorso. <strong>Medaglia d\u2019argento<\/strong> e <strong>record regionale<\/strong> per Angela De luca (M30) nei 400 stile. Ancora <strong>argento<\/strong> per Natalino Imbrogno (M40) e Gaspare Cerzoso (M30) 50 rana, Martina Borruto (M30) nei 50 dorso. <strong>Medaglia di bronzo<\/strong> conquistata da Francesco Verre (M 30) nei 50 dorso, da Aldo Gimigliano (M45) nei 50 rana, Domenico Sapia (M55) nei 200 stile.<\/p>\n<p>Staffette<strong>:<\/strong> <strong>medaglia d\u2019argento<\/strong> nella 4&#215;50 mista\/mista (Mazzuca \u2013 Cerzoso &#8211; De Luca &#8211; Borruto) e <strong>medaglia di bronzo<\/strong> nella staffetta 4&#215;50 stile\/mista (Cerzoso &#8211; Borruto &#8211; De Luca &#8211; Mazzuca).<\/p>\n<h4>Il medagliere di domenica 1 dicembre:<\/h4>\n<p><strong>Medaglia d\u2019oro<\/strong> per Vincenza Rossi (M60) nei 50 delfino e nei 50 stile, Simone Sacco (M40) e Marco Allori (M35) 100 dorso, Massimo Montimurro nei 50 delfino. <strong>Medaglia d\u2019argento<\/strong> per Angela De luca (M30) nei 50 stile e <strong>record regionale<\/strong>, Giovanni De Maria (M25) nei 100 misti, Giulia Guido nei 50 stile e nei 100 misti, Alfonso Armini (M50) nei 50 delfino. <strong>Medaglia di bronzo<\/strong> per Giovanni De Maria (M30) nei 50 stile, Aldo Trecroci (M60) nei 100 misti, Francesca Bilotta (M45) nei 50 stile e nei 100 misti, Raffaele Zinno (M3) nei 200 rana e Massimo Montimurro (M40) nei 50 stile.<\/p>\n<p>Staffette<strong>: medaglia d\u2019oro<\/strong> nella 4&#215;50 maschi 160-199 (Allori &#8211; Imbrogno &#8211; Montimurro \u2013 Armini). <strong>Medaglia d\u2019argento<\/strong> nella 4&#215;50 stile femmine 160-199 (Guido \u2013 Bilotta \u2013 Borruto \u2013 Rossi), nella 4&#215;50 mista femmine 160-199 con <strong>record regionale<\/strong> (Bilotta \u2013 Guido \u2013 De Luca \u2013 Rossi), nella 4&#215;50 stile maschi 100-119 (De Maria &#8211; Verre &#8211; Mazzuca \u2013 Cerzoso) e nella 4&#215;50 maschi (Verre &#8211; De Maria &#8211; Mazzuca -Cerzoso). <strong>Medaglia di bronzo<\/strong> nella 4&#215;50 stile 160-199 (Allori &#8211; Imbrogno &#8211; Montimurro \u2013 Armini).<\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Prima gara stagionale in trasferta per la compagine cosentina dell\u2019Asd Anzianotti Nuoto Master ed un ottimo secondo posto conquistato al \u201c6\u00b0 Trofeo Flegreo\u201d nella piscina del complesso sportivo PalaTrincone a Monterusciello &#8211; Pozzuoli<\/p>\n","protected":false},"author":24,"featured_media":120645,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-120644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=120644"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120645"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=120644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=120644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=120644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}