{"id":120796,"date":"2019-12-07T15:45:56","date_gmt":"2019-12-07T14:45:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/come-scegliere-giocattoli-sicuri-e-senza-sostanze-tossiche-da-regalare-a-natale\/"},"modified":"2023-01-16T18:39:50","modified_gmt":"2023-01-16T17:39:50","slug":"328464-come-scegliere-giocattoli-sicuri-e-senza-sostanze-tossiche-da-regalare-a-natale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/328464-come-scegliere-giocattoli-sicuri-e-senza-sostanze-tossiche-da-regalare-a-natale\/","title":{"rendered":"Come scegliere giocattoli sicuri e senza sostanze tossiche da regalare a Natale"},"content":{"rendered":"<h4>Natale si avvicina ed \u00e8 tempo di regali, soprattutto per i bambini. Ma proprio i pi\u00f9 piccoli sono particolarmente a rischio a causa della presenza sul mercato di giocattoli che presentano tracce di sostanze chimiche potenzialmente pericolose<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Acquistare giocattoli sicuri \u00e8 importante meglio dunque fare scelte ponderate semmai riducendo il quantitativo di regali e scegliendo piuttosto che il numero la qualit\u00e0. Per questo motivo\u00a0i<strong>l Comitato Difesa Consumatori, <\/strong>tramite il proprio responsabile prof. Pietro Vitelli, vuole offrire a tutela dei consumatori\u00a0 che solitamente proprio in questo mese si accingono all&#8217;acquisto dei\u00a0 giocattoli portando alla loro conoscenza come scegliere giocattoli \u201csicuri\u201d \u00a0senza tracce di sostanze potenzialmente pericolose e a quali \u201ccaratteristiche e certificazioni\u201d bisogna fare attenzione, insomma una guida per orientarsi anche in base alla \u201ctipologia\u201d e ai \u201cmateriali scelti\u201d<em>. <\/em><strong>Purtroppo il problema non riguarda solo i giocattoli che provengono dalla Cina<\/strong> e che ogni anno si ripropone lungi dall\u2019essere definitivamente risolto. Recentemente ad esempio, in seguito all&#8217;<strong>analisi di 430 prodotti commercializzati nei paesi dell\u2019Unione europea<\/strong>, \u00e8 stato pubblicato un rapporto allarmante sulla presenza di <strong>giocattoli tossici<\/strong>.<\/p>\n<p>Ma quali sono davvero i rischi che presentano i giocattoli? Innanzitutto c\u2019\u00e8 da specificare che, rispetto agli adulti, i bambini sono pi\u00f9 esposti al problema in quanto la loro pelle \u00e8 pi\u00f9 permeabile, i loro polmoni immaturi e il loro sistema immunitario e nervoso pi\u00f9 delicato.\u00a0Dato che gi\u00e0 siamo piuttosto esposti ogni giorno a una moltitudine di prodotti chimici nocivi sarebbe bene, almeno in casa, evitare tale esposizione facendo entrare solo\u00a0<strong>giocattoli sicuri<\/strong>\u00a0e \u201cpuliti\u201d.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/8924\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-328470\" src=\"https:\/\/quicosenza.it\/news\/8924\" alt=\"\" width=\"530\" height=\"349\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h4>Ma cosa possono contenere i comuni giocattoli?<\/h4>\n<p><strong>Consigli per scegliere al meglio i giocattoli<\/strong><\/p>\n<p>Difendersi da acquisti sbagliati \u00e8 possibile cos\u00ec come assicurare ai nostri bambini dei giocattoli \u201cpuliti\u201d. Ecco alcuni consigli che potranno esservi utili:<\/p>\n<ul>\n<li><strong>Considerare l\u2019et\u00e0:<\/strong>al momento dell\u2019acquisto \u00e8 importante valutare l\u2019et\u00e0 indicata per l\u2019utilizzo di quel giocattolo. Pu\u00f2 infatti contenere parti piccole che i bambini potrebbero ingerire, oppure non essere assolutamente indicato per essere morso o messo in bocca.<\/li>\n<li><strong>Scelta dei materiali:<\/strong>questo \u00e8 un punto essenziale. Sia a livello ambientale che di salute dei pi\u00f9 piccoli sarebbe bene scegliere materiali naturali, come ad esempio il legno, piuttosto che la plastica.<\/li>\n<li><strong>Certificazioni<\/strong>: importante scegliere giocattoli certificati per bambini che vantano dunque nell\u2019etichetta indicazione di essere Ecocert, OEKO-TEX\u00ae (sistema di controllo e certificazione indipendente), GS e Spiel Gut (questi ultimi certificano l\u2019assenza di sostanze tossiche). Il marchio CE, apposto dal produttore stesso, dichiara che quel giocattolo \u00e8 conforme ai regolamenti europei.<\/li>\n<li><strong>Giocattoli profumati<\/strong>: questa tipologia sarebbe da evitare in quanto a maggior rischio di contenere sostanze tossiche.<\/li>\n<\/ul>\n<p>Sottolineiamo l\u2019importanza di prestare particolare attenzione ai giocattoli che si acquistano soprattutto per i bambini pi\u00f9 piccoli, sotto i tre anni, che tendono a mettere tutto in bocca. Ma vediamo adesso per tipologia di gioco come scegliere al meglio.<\/p>\n<p><strong>Bambole<\/strong> &#8211; \u00a0sono realizzate in plastica o altri componenti sintetici e possono quindi contenere diverse sostanze tossiche. Attenzione in particolare alle bambole in miniatura che il pi\u00f9 delle volte non sono considerate come giocattoli per bambini, ma articoli di decorazione e dunque i limiti fissati dai regolamenti sui giocattoli non sono applicabili. Si consiglia di scegliere bambole di stoffa e cotone biologico da lavare prima dell\u2019uso.<\/p>\n<p><strong>\u00a0<\/strong><strong>Peluche<\/strong>\u00a0&#8211; \u00a0e altri giocattoli con parti in peluche, soprattutto quelli sintetici a pelo lungo o imbottiti, sono pi\u00f9 a rischio di contenere allergeni e ritardanti di fiamma bromurati che impediscono al fuoco di diffondersi ma sono pericolosi per la salute. Meglio preferire quelli in fibre naturali o ecologiche, ad esempio quelli etichettati Oeko- Tex. Lavarli sempre prima di metterli in mano ai bambini.<\/p>\n<p><strong>Giocattoli di legno<\/strong><strong> \u2013 <\/strong>esistono \u00a0ormai di ogni genere: costruzioni, case delle bambole, macchinine, puzzle, ecc. Purtroppo anche il legno non garantisce di per s\u00e9 sicurezza. I giocattoli di compensato possono contenere ad esempio formaldeide mentre nelle pitture usate sul legno possono essere presenti tracce di piombo. Il consiglio \u00e8 quello di scegliere giocattoli in legno grezzo non verniciato (ad esempio di faggio o acero), o decorato ma non con vernici tossiche. Si possono prediligere quelli con certificazione FSC o PEFC che assicura una gestione sostenibile di boschi e foreste.<\/p>\n<p><strong>Giocattoli di plastica<\/strong><strong> &#8211; <\/strong>alcuni giocattoli gonfiabili o di plastica possono contenere ftalati o Bisfenolo A ma anche idrocarburi aromatici policiclici. La plastica poi, come sappiamo, inquina. Se proprio non si riesce ad evitare giocattoli realizzati con questo materiale si pu\u00f2 almeno scegliere quelli di marchi che hanno volontariamente rimosso queste sostanze dai loro prodotti indicando in etichetta\u201dSenza PVC\u201d o \u201csenza ftalati\u201d. Prima di utilizzare questi giochi \u00e8 bene sciacquarli e metterli a prendere aria per un paio di giorni.<\/p>\n<p><strong>Giocattoli elettronici<\/strong><strong> &#8211; <\/strong>questa categoria include giocattoli elettronici e alimentati a batteria come le auto elettriche, i trenini, i computer, ecc. Oltre alla presenza in questi giocattoli di ignifughi bromurati, c\u2019\u00e8 il rischio di entrare in contatto con cadmio, mercurio e altre sostanze tossiche. Sicuramente dovrebbero evitare questi giochi i bambini pi\u00f9 piccoli..<\/p>\n<p><strong>Giochi per disegnare, pitturare e cosmetici<\/strong><strong> &#8211; <\/strong>pennarelli, tempere, kit di pasta da modellare ma anche trucchi per bambini possono contenere tracce di bario, piombo, formaldeide o ftalati. Per scongiurare il rischio, meglio evitare l\u2019acquisto di giocattoli profumati (i profumi tra l\u2019altro possono scatenare allergie) e scegliere sempre prodotti su cui sono stati usati coloranti alimentari o da piante e senza conservanti.<\/p>\n<p><strong>Altri consigli utili<\/strong><strong> : <\/strong><strong>\u201c<\/strong>Lavare il gioco e farlo asciugare all&#8217;aria<strong>:<\/strong> sarebbe importante, ogni volta che si ha un nuovo gioco, aprirlo, lavarlo e lasciarlo asciugare e riposare per alcune ore o giorni all&#8217;aperto in modo che i composti organici volatili possano andare via\u201d. \u201cControllare che il giocattolo non abbia parti che si staccano, potenzialmente pericolose soprattutto per i bambini pi\u00f9 piccoli\u201d. \u201cRicordare la regola che \u201cMeno \u00e8 meglio\u201d. Acquistiamo quindi meno giocattoli dando priorit\u00e0 alla qualit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natale si avvicina ed \u00e8 tempo di regali, soprattutto per i bambini. Ma proprio i pi\u00f9 piccoli sono particolarmente a rischio a causa della presenza sul mercato di giocattoli che presentano tracce di sostanze chimiche potenzialmente pericolose<\/p>\n","protected":false},"author":55,"featured_media":120797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-120796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=120796"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/120796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120797"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=120796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=120796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=120796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}