{"id":121068,"date":"2019-12-11T15:01:15","date_gmt":"2019-12-11T14:01:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nascondeva-la-droga-in-cassaforte-arrestato-32enne-di-paola\/"},"modified":"2023-01-16T18:40:09","modified_gmt":"2023-01-16T17:40:09","slug":"329252-nascondeva-la-droga-in-cassaforte-arrestato-32enne-di-paola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/329252-nascondeva-la-droga-in-cassaforte-arrestato-32enne-di-paola\/","title":{"rendered":"Nascondeva la droga in cassaforte, arrestato 32enne di Paola"},"content":{"rendered":"<h4>La droga conservata all&#8217;interno di una cassaforte, a sua volta era sapientemente occultata all&#8217;interno del bagno dell\u2019abitazione e per la cui apertura si \u00e8 reso necessario l\u2019intervento di un fabbro<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>PAOLA (COSENZA) &#8211; Nascondeva in cassaforte una tavoletta di hashish del peso complessivo di 50 grammi circa. I carabinieri di Paola hanno arrestato <strong>un 32enne, P.P<\/strong>., noto alle forze dell\u2019ordine. I militari, nel corso di attivit\u00e0 di perquisizione di un\u2019abitazione nella disponibilit\u00e0 dell\u2019uomo, hanno rinvenuto la droga conservata all&#8217;interno di una cassaforte, a sua volta sapientemente occultata all&#8217;interno del bagno dell\u2019abitazione e per la cui apertura si \u00e8 reso necessario l\u2019intervento di un fabbro. Il 32enne, terminate le formalit\u00e0 di rito, su disposizione del Sostituto procuratore di turno presso la Procura della Repubblica di Paola, \u00e8 stato tradotto nella sua abitazione in regime di arresti domiciliari. L\u2019arresto \u00e8 stato convalidato dal giudice monocratico \u2013 dott.ssa Altamura \u2013 che ne ha disposto la sottoposizione all&#8217;<strong>obbligo di presentazione alla Polizia Giudiziaria.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La droga conservata all&#8217;interno di una cassaforte, a sua volta era sapientemente occultata all&#8217;interno del bagno dell\u2019abitazione e per la cui apertura si \u00e8 reso necessario l\u2019intervento di un fabbro<\/p>\n","protected":false},"author":56,"featured_media":121069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-121068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121068"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121069"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}