{"id":121480,"date":"2019-12-18T11:28:08","date_gmt":"2019-12-18T10:28:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/inchiesta-cenide-bombardieri-gestione-privatistica-dellufficio-tecnico\/"},"modified":"2023-01-16T18:40:39","modified_gmt":"2023-01-16T17:40:39","slug":"330498-inchiesta-cenide-bombardieri-gestione-privatistica-dellufficio-tecnico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/330498-inchiesta-cenide-bombardieri-gestione-privatistica-dellufficio-tecnico\/","title":{"rendered":"Inchiesta &#8216;Cenide&#8217;, Bombardieri: &#8220;gestione &#8216;privatistica&#8217; dell&#8217;ufficio tecnico&#8221;"},"content":{"rendered":"<h4>E&#8217; stato ribattezzato &#8220;sistema Morabito&#8221; perch\u00e8 l&#8217;indagine che ieri sera ha portato all&#8217;arresto anche del sindaco di Villa San Giovanni ruotava attorno alla figura dell&#8217;ingegnere e dirigente dell&#8217;ufficio tecnico Francesco Morabito<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>VILLA SAN GIOVANNI (RC) &#8211; &#8220;L&#8217;inchiesta &#8216;<strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9032\" target=\"_blank\" rel=\"noopener noreferrer\">Cenide<\/a><\/span><\/strong>&#8216; fa emergere un quadro desolante di gestione dell&#8217;ufficio tecnico del comune di Villa San Giovanni e tutto ruota sulla figura centrale del dirigente, Francesco Morabito&#8221;. Il procuratore della Repubblica di Reggio Calabria Giovanni Bombardieri in conferenza stampa parla di un &#8220;sistema Morabito&#8221; e di piaceri e favori in cambio di agevolazioni di iter per pratiche edilizie.<\/p>\n<p>&#8220;Intendo chiarire &#8211; ha detto Bombardieri &#8211; che in questa indagine <strong>non \u00e8 coinvolto il senatore Marco Siclari<\/strong>, di Forza Italia, fratello del sindaco, e la vicenda riguarda la <strong>gestione quasi privatistica di un ufficio pubblico<\/strong>, <strong>diretto da Morabito<\/strong>, sempre pronto a soddisfare le richieste della societ\u00e0 di navigazione in cambio di favori, di assunzioni, anche con promesse fatte ad un consigliere di minoranza (Villa San Giovanni \u00e8 guidata da una maggioranza di centrodestra, ndr) di <strong>assumergli un figlio in cambio<\/strong> di un <strong>ammorbidimento<\/strong> delle posizioni politiche&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-330500 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/12\/Operazione-Cenide-01-.jpg\" alt=\"\" width=\"585\" height=\"324\" title=\"\"><\/p>\n<p>L&#8217;inchiesta, avviata anche a seguito di numerose <strong>segnalazioni di cittadini e di associazioni<\/strong>, ha riguardato i lavori di <strong>adeguamento di un grande piazzale di cui era proprietaria l&#8217;Anas<\/strong>, ceduto poi al Comune, su cui la Caronte &amp; Tourist aveva realizzato <strong>un&#8217;area di sosta e una biglietteria automatica<\/strong>, secondo l&#8217;accusa,<strong> non rispettando la legge urbanistica e senza i pareri tecnici comunali<\/strong>.<\/p>\n<h3>&#8220;Intercettazioni allarmanti&#8221;<\/h3>\n<p>&#8220;Le intercettazioni sono davvero allarmanti &#8211; ha sottolineato ancora il procuratore Bombardieri &#8211; e consentono di delineare un quadro di convenienze, <strong>di &#8216;do ut des&#8217;, tra Morabito e il suo vice, Giancarlo Trunfio,<\/strong> da una parte, <strong>e la societ\u00e0 di navigazione dall&#8217;altra<\/strong>. Per agevolare i lavori di ammodernamento del piazzale e la realizzazione della biglietteria, infatti, i vertici della societ\u00e0 si erano impegnati ad assumere uno dei figli di Trunfio, Gianluca, ottenendo dall&#8217;ufficio tecnico del comune di Villa San Giovanni un provvedimento autorizzativo illegittimo per la rapida esecuzione dell&#8217;opera. Rimanendo in questo ambito sono state registrate ulteriori condotte corruttive, attraverso cui i manager indagati sono riusciti ad asservire la pubblica funzione agli interessi privati della societ\u00e0 di navigazione&#8221;.<\/p>\n<p>Alla conferenza stampa era presenti anche il comandante provinciale dei carabinieri, col. Giuseppe Battaglia, il comandante del reparto operativo t.col. Massimiliano Galasso, e il maggiore Cristian Tedeschi.<\/p>\n<h4>Il ruolo del sindaco<\/h4>\n<p>Giovanni Siclari, sindaco di Villa San Giovanni, ha ricevuto &#8220;<strong>un ritorno in termini di consenso politico-elettorale&#8221;<\/strong> da &#8220;illeciti rapporti di cointeressenza&#8221; con il presidente del Cda di Caronte &amp; Tourist. Lo scrive il gip di Reggio Calabria nell&#8217;ordinanza di custodia cautelare in carcere con cui ha disposto i domiciliari per entrambi con l&#8217;accusa di corruzione.<\/p>\n<p>L&#8217;azione di <strong>pressione dei vertici della societ\u00e0 Caronte<\/strong>\u00a0segnatamente di Repaci, scrive il gip, &#8220;si rivelano anche con le risultanze investigative raccolte e versate in atti con riferimento all&#8217;ipotesi corruttiva&#8221;. Emerge infatti come Repaci, &#8220;si sia mosso anche sul fronte politico, individuando quale suo interlocutore il sindaco Giovanni Siclari al fine di assicurarsi l&#8217;affidamento dell&#8217;area sulla quale la sua societ\u00e0 aveva progettato la realizzazione dei lavori in argomento, area che risultava di propriet\u00e0 Anas&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-330502 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/12\/Operazione-Cenide-03.jpg\" alt=\"\" width=\"549\" height=\"307\" title=\"\"><\/p>\n<p>Il gip, a tale proposito, afferma come &#8220;le investigazioni hanno dimostrato la sussistenza di illeciti rapporti di cointeressenze tra Repaci e Siclari, il quale, bench\u00e9 consapevole dell&#8217;illegittima occupazione del suolo Anas su cui insistevano i lavori posti in essere dalla Caronte e Tourist, ha fatto pesare la sua influenza politica per ottenere dalla societ\u00e0 di navigazione indebiti vantaggi che si sono concretizzati in assunzioni di persone e contributi economici e quindi, in un ritorno in termini di consenso politico-elettorale&#8221;. In particolare, secondo l&#8217;accusa, Siclari, sapendo che la Caronte e Tourist aveva in corso lavori per la riorganizzazione della biglietteria su un&#8217;area di propriet\u00e0 di Anas, in assenza di un provvedimento concessorio da parte del Comune, &#8220;si opponeva, in Consiglio comunale, alla mozione di un consigliere di minoranza volta a chiedere ai competenti uffici comunali di disporre la sospensione dei lavori nelle more delle opportune verifiche circa l&#8217;effettiva propriet\u00e0 delle aree interessate&#8221;. Inoltre avrebbe sollecitato Anas per la stipula di una convenzione di concessione con il Comune per cederla poi in subconcessione alla Caronte &amp; Tourist. In cambio, Repaci avrebbe promesso del figlio del consigliere comunale Angela Vilardi chiesta dallo stesso Siclari, \u00e8 scritto nel capo di imputazione, &#8220;che, cos\u00ec facendo, intendeva assicurarsi il voto favorevole in consiglio della stessa Vilardi&#8221;, <strong>un&#8217;altra assunzione e l&#8217;erogazione in favore del comune di almeno 8.000 euro<\/strong> per l&#8217;organizzazione di manifestazioni culturali, sportive, ricreative e turistiche.<\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/9032\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\">\u2018Ceniade\u2019, arrestato sindaco di Villa San Giovanni e i manager della \u201cCaronte\u201d (VIDEO \u2013 NOMI)<\/span><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; stato ribattezzato &#8220;sistema Morabito&#8221; perch\u00e8 l&#8217;indagine che ieri sera ha portato all&#8217;arresto anche del sindaco di Villa San Giovanni ruotava attorno alla figura dell&#8217;ingegnere e dirigente dell&#8217;ufficio tecnico Francesco Morabito<\/p>\n","protected":false},"author":42,"featured_media":121481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-121480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121480"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121481"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}