{"id":121492,"date":"2019-12-18T14:21:24","date_gmt":"2019-12-18T13:21:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/blitz-dei-nas-nelle-mense-scolastiche-sospese-21-ditte-sequestrata-1-tonnellata-di-cibo\/"},"modified":"2023-01-16T18:40:39","modified_gmt":"2023-01-16T17:40:39","slug":"330541-blitz-dei-nas-nelle-mense-scolastiche-sospese-21-ditte-sequestrata-1-tonnellata-di-cibo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/330541-blitz-dei-nas-nelle-mense-scolastiche-sospese-21-ditte-sequestrata-1-tonnellata-di-cibo\/","title":{"rendered":"Blitz dei Nas nelle mense scolastiche. Sospese 21 ditte, sequestrata 1 tonnellata di cibo"},"content":{"rendered":"<h4>La gigantesca operazione dei carabinieri con ispezioni in tutta Italia di ben 968 aziende di ristorazione operanti nelle scuole sia pubbliche che private.\u00a0Sequestrati 900 kg di cibo, elevate 25 violazioni penali e 247 amministrative.\u00a0D<strong>isposta la sospensione di 21 imprese di catering per un valore di quasi 3 milioni di euro.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>Il carabinieri per la Tutela della salute, unitamente al ministero della Salute, ha realizzato un gigantesco piano di controllo nazionale sui servizi di ristorazione e delle imprese di catering assegnatari della gestione <strong>mense presso gli istituti scolastici dalla Valle D&#8217;Aosta alla Calabria<\/strong>. A seguito degli accertamenti i <strong>carabinieri dei Nas hanno disposto la sospensione dell&#8217;attivit\u00e0 o il sequestro di 21 imprese di catering,\u00a0 per un valore stimato in circa 3 milioni, <\/strong>assegnatari della gestione delle mense negli istituti scolastici per rilevanti carenze igienico-sanitarie e strutturali<strong>. <\/strong>Il controlla e il monitoraggio \u00e8 stato effettuato <strong>nelle scuole di ogni ordine e grado, pubbliche e private<\/strong>.<\/p>\n<p>Sono stati, inoltre, <strong>sequestrati oltre 900 kg di derrate alimentar<\/strong>i (carni, formaggi, frutta ed ortaggi, olio) riscontrati in assenza di tracciabilit\u00e0, custoditi in cattive condizioni sanitarie e in ambienti inadeguati e destinati all&#8217;impiego nelle pietanze sebbene di qualit\u00e0 inferiore a quanto previsto nei contratti di fornitura. I<strong>l monitoraggio \u00e8 stato pianificato per accertare la regolarit\u00e0 dei servizi erogati delle scuole<\/strong>,<strong> partendo dagli asili nido fino agli istituti superiori<\/strong>, verificando le condizioni d&#8217;igiene nei locali di lavoro e nella detenzione degli alimenti, la rispondenza dei men\u00f9 alle clausole contrattuali previste dai capitolati d&#8217;appalto, la qualit\u00e0 e la salubrit\u00e0 degli alimenti somministrati, non trascurando la regolarit\u00e0 delle maestranze impiegate ed il possesso di adeguata qualifica e preparazione professionale.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/9035\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-330543\" src=\"https:\/\/quicosenza.it\/news\/9035\" alt=\"\" width=\"559\" height=\"313\" title=\"\"><\/a><\/p>\n<p>Complessivamente sono state i<strong>spezionate 968 aziende di ristorazione collettiva operanti all&#8217;interno di mense scolastiche, di cui 198 hanno evidenziato irregolarit\u00e0<\/strong>, determinando la contestazione di 25 violazioni penali e 247 amministrative alle normative nazionali e comunitarie, con conseguente irrogazione di sanzioni pecuniarie per 204 mila euro. Le violazioni penali pi\u00f9 ricorrenti contestate ai 27 gestori e titolari delle imprese sono relative alla<strong> frode e alle inadempienze in pubbliche forniture<\/strong>, alla detenzione di\u00a0<strong>alimenti in cattivo stato di conservazione<\/strong>\u00a0ed a inottemperanze alla normativa sulla sicurezza sui luoghi di lavoro. Gli accertamenti dei Nas\u00a0hanno rilevato, nei casi di irregolarit\u00e0, il r<strong>ipetuto utilizzo\u00a0di prodotti di minore qualit\u00e0 rispetto a quella pattuita e dichiarata<\/strong> <strong>nei contratti di fornitura stipulati con i Comuni<\/strong>, per trarre un illecito profitto lucrando sulla differenza di costo della materia prima utilizzata nella preparazione dei pasti.<\/p>\n<p>Frequentemente, dunque, sono gli <strong>alimenti DOP o biologici\u00a0<\/strong>(f<strong>ormaggi, olio extravergine, prosciutto) ad essere sostituiti con altri di minore valore economico<\/strong> che, pur non presentando criticit\u00e0 igieniche, non posseggono alcuna denominazione di origine. Ulteriori controlli hanno evidenziato l&#8217;utilizzo di carne o vegetali surgelati\/congelati invece di quelli freschi dichiarati in contratto.\u00a0<strong>Il ministro della Salute Roberto Speranza ha espresso apprezzamento per le operazioni svolte dai carabinieri dei Nas<\/strong> &#8220;la regolarit\u00e0 dei servizi erogati nelle scuole \u00e8 di fondamentale importanza perch\u00e9 interessa la salute dei nostri figli&#8221;, ha detto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gigantesca operazione dei carabinieri con ispezioni in tutta Italia di ben 968 aziende di ristorazione operanti nelle scuole sia pubbliche che private.\u00a0Sequestrati 900 kg di cibo, elevate 25 violazioni penali e 247 amministrative.\u00a0Disposta la sospensione di 21 imprese di catering per un valore di quasi 3 milioni di euro.<\/p>\n","protected":false},"author":55,"featured_media":121493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-121492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121492"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121493"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}