{"id":121522,"date":"2019-12-19T08:41:03","date_gmt":"2019-12-19T07:41:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-a-pisa-per-non-affondare-serve-una-vittoria-che-manca-da-5-partite\/"},"modified":"2023-01-16T18:40:42","modified_gmt":"2023-01-16T17:40:42","slug":"330660-cosenza-a-pisa-per-non-affondare-serve-una-vittoria-che-manca-da-5-partite","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/330660-cosenza-a-pisa-per-non-affondare-serve-una-vittoria-che-manca-da-5-partite\/","title":{"rendered":"Cosenza, a Pisa per non affondare. Serve una vittoria che manca da 5 partite"},"content":{"rendered":"<h4>Il periodo pi\u00f9 complicato della stagione per i rossoblu impegnati in un match cruciale per la stagione dei lupi. Nelle ultime cinque partite la di Braglia non ha mai vinto, nelle precedenti sette aveva perso solamente una volta: questo doppio dato la dice lunga sul periodo complicato <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; La<a href=\"https:\/\/quicosenza.it\/news\/9048\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #0000ff;\"> sconfitta contro il Pordenone<\/span><\/strong><\/a>, arrivata a cospetto di una squadra capace di issarsi in seconda posizione alle spalle solamente del Benevento, ha <strong>invece certificato la crisi nerissima del Cosenza<\/strong> inchiodato al terz\u2019ultimo posto in classifica e -6 dalla zona salvezza. Per carit\u00e0, nulla \u00e8 compromesso in questo problematico campionato, partito per dare ben altre soddisfazioni alla tifoseria rossoblu, ma se non dovessero da subito invertire la rotta e iniziare a ritrovare i 3 punti, Bruccini e compagni<strong> si ritroverebbero alla sosta natalizia con i piedi fuori persino dalla zona playout<\/strong>. Una squadra, quella di Braglia, alla disperata ricerca di punti dunque a cominciare dalla prossima gara che si disputer\u00e0 in casa di una Pisa che invece viaggia a mille e che sembra aver ritrovato la quadra dopo le difficolt\u00e0 iniziali: <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9049\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>stando alle quote bwin sulla prossima giornata di Serie B<\/strong><\/a><\/span> non sar\u00e0 impresa facile espugnare il Garibaldi dei nerazzurri. La vittoria dei rossobl\u00f9 \u00e8 data a 3.30, il pareggio fra le due compagini viene pagato 3 volte la posta mentre a 2.30 \u00e8 data la vittoria degli uomini di casa. Un Pisa che vive un buonissimo momento, con ben 10 punti raccolti nelle ultime cinque uscite e tre vittorie: un filotto positivo che \u00e8 valso ai toscani la nona piazza, ad un passo dalla zona playoff.<\/p>\n<p>Il Cosenza, da parte sua, deve<strong> ritrovare quanto prima quegli equilibri fra reparti e quella compattezza che, seppur in parte, aveva caratterizzato<\/strong> almeno la prima parte di stagione. Anche guardando i numeri del Cosenza, si evince come la differenza reti sia la pi\u00f9 equilibrata della parte destra della classifica:<strong> 18 gol realizzati e 20 subiti,<\/strong> a dimostrazione di quanto la squadra non abbia smarrito del tutto la costanza nelle prestazioni nemmeno all\u2019interno di un momento cos\u00ec difficile. \u00c8 possibile pensare che il mese di gennaio possa venire in soccorso dei rossoblu, grazie ad un mercato invernale che possa mettere mano alla rosa di un Braglia mai in discussione sino a questo momento dalla societ\u00e0, tifoseria e giocatori. Prima di pensare al mercato, per\u00f2, testa e gambe per chiudere nel migliore dei modi il girone di andata a cominciare dal&#8217;appuntamento all\u2019Arena Garibaldi di Pisa, contro la nona in classifica. L\u2019obiettivo \u00e8 quello di fare punti e strappare almeno un pareggio, ma quei tre punti che mancano da cinque partite porterebbero nuova linfa vitalein vista di una seconda parte di stagione di fuoco per il Cosenza, alla disperata ricerca di una salvezza che vale oro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il periodo pi\u00f9 complicato della stagione per i rossoblu impegnati in un match cruciale per la stagione dei lupi. Nelle ultime cinque partite la di Braglia non ha mai vinto, nelle precedenti sette aveva perso solamente una volta: questo doppio dato la dice lunga sul periodo complicato<\/p>\n","protected":false},"author":24,"featured_media":121523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-121522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121522"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121523"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}