{"id":121564,"date":"2019-12-19T16:48:14","date_gmt":"2019-12-19T15:48:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/chi-e-jole-santelli-la-deputata-che-ha-strappato-la-candidatura-a-mario-occhiuto\/"},"modified":"2023-01-16T18:40:45","modified_gmt":"2023-01-16T17:40:45","slug":"330804-chi-e-jole-santelli-la-deputata-che-ha-strappato-la-candidatura-a-mario-occhiuto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/330804-chi-e-jole-santelli-la-deputata-che-ha-strappato-la-candidatura-a-mario-occhiuto\/","title":{"rendered":"Chi \u00e8 Jole Santelli, la deputata che ha strappato la candidatura a Mario Occhiuto"},"content":{"rendered":"<h4>Ex vicesindaco e assessore alla cultura di Cosenza, avvocato e deputata dal 2001 \u00e8 legata da sempre a Forza Italia. Quasi vent&#8217;anni tra i banchi di Montecitorio e ben 4 legislature con importanti incarichi istituzionali<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/9056\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Jole Santelli,<\/strong><\/a><\/span> 51 anni cosentina doc, una laurea in giurisprudenza, \u00e8 deputata alla Camera dal lontano 2001 e da sempre legata a Forza Italia partito nel quale \u00e8 coordinatore Regionale della Calabria. Al partito ader\u00ec nel 1994, collaborando due anni pi\u00f9 tardi, con l&#8217;ufficio legislativo di FI al Senato per poi passare a quello della Camera. <strong>Quasi vent&#8217;anni tra i banchi di Montecitorio, sempre con il partito di Berlusconi, e ben 4 legislature<\/strong> (nel 2006 riusc\u00ec ad esser eletta nella circoscrizione Emilia Romagna) che le sono valse, tra l&#8217;altro, un incarico da <strong>sottosegretario di Stato al ministero della Giustizia <\/strong>dal 2001 al 2006 nel secondo e terzo Governo Berlusconi, e un&#8217;<strong>incarico da sottosegretario al ministero del Lavoro e delle Politiche Social<\/strong>i da maggio a dicembre 2013 nel Governo Letta.<\/p>\n<p>Il 14 novembre del 2018 \u00e8 stata eletta <strong>vicepresidente della Commissione parlamentare antimafia, <\/strong>ruolo che ricopre tutt&#8217;ora. Alle ultime elezioni politiche del 2018 la Santelli \u00e8 stata eletta nel collegio plurinominale Calabria 02, ovviamente tra le lista di Forza Italia. La candidata governatrice della Calabria <strong>ha avuto anche due importanti incarichi parlamentari:<\/strong>\u00a0\u00e8 stata per due volte <strong>vicepresidente della prima Commissione Affari costituzionali<\/strong>, della Presidenza del Consiglio e interni. Tra l&#8217;altro, \u00e8 stata promotrice di <strong>151 progetti di Legge<\/strong> ed ha presentato qualcosa come <strong><span class=\"tit16Ara\">578 <\/span>atti di indirizzo e controllo, ovvero<\/strong> mozioni, interrogazioni, interpellanze e ordini del giorno.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/9057\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-328689\" src=\"https:\/\/quicosenza.it\/news\/9057\" alt=\"Regionali Calabria\" width=\"548\" height=\"316\" title=\"\"><\/a><\/p>\n<h4>Da vicesindaco di Cosenza alla candidatura a governatrice<\/h4>\n<p>A livello locale, solo 10 giorni fa, la Santelli era legata saldamente alla legislatura di Mario Occhiuto, ricoprendo\u00a0 non solo il ruolo di <strong>vicesindaco di Cosenza, ma anche assessore alla Cultura<\/strong>. Un binomio imprescindibile, quello con Occhiuto, che si \u00e8 per\u00f2 <strong>spezzato a inizio dicembre<\/strong> proprio per la <strong>contesa alla poltrona da presidente della Calabria. <\/strong>Forza Italia aveva messo sul tavolo il nome del sindaco di Cosenza ma alla fine ha scelto quello della Santelli dopo <strong>il veto imposto dal leader della Lega Matteo Salvini<\/strong> e un&#8217;infinita serie di summit e riunioni con i vertici dei principali partiti del centrodestra che alla fine hanno puntato tutto sulla Santelli. Decisione che ha mandato su tutte le furie Mario Occhiuto che con molta probabilit\u00e0, <strong>correr\u00e0 da solo alle prossime regionali con il sostegno di liste civiche<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex vicesindaco e assessore alla cultura di Cosenza, avvocato e deputata dal 2001 \u00e8 legata da sempre a Forza Italia. Quasi vent&#8217;anni tra i banchi di Montecitorio e ben 4 legislature con importanti incarichi istituzionali<\/p>\n","protected":false},"author":55,"featured_media":121565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42],"tags":[667],"class_list":["post-121564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza","tag-regionali-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121564"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121565"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}