{"id":121623,"date":"2019-12-20T16:40:16","date_gmt":"2019-12-20T15:40:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/jole-santelli-emozionata-e-pronta-il-mio-desiderio-restituire-speranza-ai-calabresi\/"},"modified":"2023-01-16T18:40:48","modified_gmt":"2023-01-16T17:40:48","slug":"330961-jole-santelli-emozionata-e-pronta-il-mio-desiderio-restituire-speranza-ai-calabresi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/330961-jole-santelli-emozionata-e-pronta-il-mio-desiderio-restituire-speranza-ai-calabresi\/","title":{"rendered":"Jole Santelli: &#8220;emozionata e pronta. Il mio desiderio? Restituire speranza ai calabresi&#8221;"},"content":{"rendered":"<h4 dir=\"auto\">La candidata del centrodestra: &#8220;ringrazio i tre leader e sono pronta alla sfida con tutta la passione che mi \u00e8 propria. La sinistra? Ha sgovernato in Calabria&#8221;<\/h4>\n<p><!--more--><\/p>\n<div dir=\"auto\"><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div dir=\"auto\">COSENZA &#8211; <strong>&#8220;Sono emozionata per questa designazione e sono pronta ad affrontare la sfida regionale con tutta la passione che mi \u00e8 propria<\/strong>. Ringrazio i tre leader del centrodestra e tutti i responsabili dei partiti e delle liste a sostegno di questa candidatura che nasce dalla consapevolezza di dover lavorare per rendere giustizia a una regione che vive una fase di oscurantismo senza precedenti&#8221;.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Sono le prime parole della candidata del centrodestra Jole Santelli all&#8217;indomani della sua investitura ufficiale e l&#8217;ok di Forza Italia, Fratelli D&#8217;Italia e la Lega. &#8220;Il compito pi\u00f9 importante &#8211; scrive la Santelli &#8211; \u00e8 quello di dare <strong>un brand identitario alla Calabria, che non \u00e8 solo cronaca e negativit\u00e0 ma un luogo pieno di tradizioni e di cultura<\/strong>.\u00a0 Il mio desiderio \u00e8 <strong>restituire speranza ai calabresi, lavorare con abnegazione<\/strong>, riaccendere la luce in un tunnel che non \u00e8 il destino immane di una regione.\u00a0<strong>Sono particolarmente grata per essere stata scelta dai leader nazionali<\/strong> e sono cosciente della necessit\u00e0 di agire usando il cuore, per uscire dalle acque stagnanti cui la sinistra ha costretto la Calabria. Questa campagna elettorale &#8211;\u00a0 conclude la Santelli &#8211; far\u00e0 conoscere ai calabresi il nostro programma, strumento di governo efficace del territorio, intriso di argomenti che nascono nella sensibilit\u00e0 dei nostri concittadini.\u00a0<strong>Saranno i fatti a parlare ed a restituirci l&#8217;immagine veritiera di una regione dinamica e pronta a risollevarsi&#8221;<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La candidata del centrodestra: &#8220;ringrazio i tre leader e sono pronta alla sfida con tutta la passione che mi \u00e8 propria. La sinistra? Ha sgovernato in Calabria&#8221;<\/p>\n","protected":false},"author":55,"featured_media":121624,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-121623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121623"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121624"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}