{"id":121751,"date":"2019-12-23T10:22:58","date_gmt":"2019-12-23T09:22:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-lite-al-mercato-di-via-asmara-camion-perde-il-controllo-un-ferito\/"},"modified":"2023-01-16T18:40:57","modified_gmt":"2023-01-16T17:40:57","slug":"331332-cosenza-lite-al-mercato-di-via-asmara-camion-perde-il-controllo-un-ferito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/331332-cosenza-lite-al-mercato-di-via-asmara-camion-perde-il-controllo-un-ferito\/","title":{"rendered":"Cosenza: lite al mercato di via Asmara. Camion perde il controllo, un ferito"},"content":{"rendered":"<h4>Sarebbe stata una lite tra due venditori avvenuta al mercato di via Asmara a determinare l&#8217;incidente. Il conducente del camion, sceso dal mezzo per risolvere l&#8217;alterco, non avrebbe inserito il freno a mano<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; E&#8217; accaduto questa mattina a Cosenza, al mercato <span class=\"st\">agroalimentare <\/span>di via Asmara in queste ore molto frequentato visti gli acquisti per il Natale. Secondo le prime ricostruzioni ci sarebbe stata <strong>una lite per motivi legati pare, alle operazioni di carico e scarico merci<\/strong> e ad una postazione &#8216;fuori misura&#8217; all&#8217;interno del mercato segnalata da diverso tempo alla polizia municipale di Cosenza che avrebbe reso difficile la manovra del mezzo. La lite ha visto protagonisti i proprietari del banco e l&#8217;autista del camion che sarebbe stato costretto a scendere dal mezzo e, nella concitazione non sarebbe riuscito ad<strong> inserire il freno a mano<\/strong>.<\/p>\n<p>Il camion senza controllo \u00e8 andato cos\u00ec ad impattare contro parte della cancellata che delimita l&#8217;area mercatale danneggiandola. Sul posto sono arrivati i Carabinieri e i Vigili del Fuoco. Il proprietario del mezzo \u00e8 rimasto ferito seppure lievemente ed \u00e8 stato portato in ospedale, ma <strong>la dinamica e l&#8217;accertamento dei fatti \u00e8 al vaglio dei carabinieri.<\/strong><\/p>\n<div id=\"attachment_331347\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-331347\" class=\"wp-image-331347 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/12\/Incidenre-camion-Cosenza3.jpg\" alt=\"\" width=\"599\" height=\"417\" title=\"\"><p id=\"caption-attachment-331347\" class=\"wp-caption-text\"><strong>Foto: Francesco Greco<\/strong><\/p><\/div>\n<div id=\"attachment_331346\" style=\"width: 609px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-331346\" class=\"wp-image-331346\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/12\/Incidenre-camion-Cosenza2.jpg\" alt=\"\" width=\"599\" height=\"447\" title=\"\"><p id=\"caption-attachment-331346\" class=\"wp-caption-text\"><strong>Foto: Francesco Greco<\/strong><\/p><\/div>\n<p>&nbsp;<\/p>\n<div class=\"g\">\n<div data-hveid=\"CAYQAA\" data-ved=\"2ahUKEwjK6tLHwcvmAhUHbFAKHbi6AzcQFSgAMAJ6BAgGEAA\">\n<div class=\"rc\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sarebbe stata una lite tra due venditori avvenuta al mercato di via Asmara a determinare l&#8217;incidente. Il conducente del camion, sceso dal mezzo per risolvere l&#8217;alterco, non avrebbe inserito il freno a mano<\/p>\n","protected":false},"author":42,"featured_media":121752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-121751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=121751"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/121751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/121752"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=121751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=121751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=121751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}